{"id":108522,"date":"2021-06-09T07:35:38","date_gmt":"2021-06-09T11:35:38","guid":{"rendered":"https:\/\/www.eltrabajo.cl\/portal\/?p=108522"},"modified":"2021-06-08T23:14:39","modified_gmt":"2021-06-09T03:14:39","slug":"aprueban-diseno-de-ingenieria-para-nuevo-estadio-municipal-de-putaendo","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/aprueban-diseno-de-ingenieria-para-nuevo-estadio-municipal-de-putaendo\/","title":{"rendered":"Aprueban dise\u00f1o de ingenier\u00eda para nuevo estadio municipal de Putaendo"},"content":{"rendered":"<p style=\"text-align: left;\"><span style=\"color: #ff0000;\"><strong>Tendr\u00e1 una inversi\u00f3n superior a los 90 millones de pesos:<\/strong><\/span><\/p>\n<ul style=\"text-align: left;\">\n<li><strong>El anhelado proyecto fue aprobado recientemente por el Consejo Regional. El alcalde Sergio Zamora considera que es una tremenda y excelente noticia para el deporte comunal, pues Putaendo merece un nuevo recinto deportivo.<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>PUTAENDO.- <\/strong>A comienzos de esta semana lleg\u00f3 a la municipalidad de Putaendo el llamado \u2018convenio mandato\u2019, donde se oficializa la aprobaci\u00f3n del proyecto de dise\u00f1o llamado \u2018Reposici\u00f3n Estadio Fiscal comuna de Putaendo\u2019.<\/p>\n<p style=\"text-align: justify;\">La inversi\u00f3n alcanza los $92.261.000, a trav\u00e9s del Fondo Nacional de Desarrollo Regional (FNDR). El alcalde <strong>Sergio Zamora<\/strong> valor\u00f3 la respectiva aprobaci\u00f3n porque se trata de un proyecto muy esperado por la comunidad.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Estamos contentos porque es una obra anhelada por muchos deportistas en Putaendo. Nosotros como comuna nos hab\u00edamos quedado atr\u00e1s en el proyecto de un nuevo estadio, pero ahora podemos decir que estamos avanzando en esa materia. Estamos viendo la luz\u00bb,<\/em> expres\u00f3 la m\u00e1xima autoridad comunal.<\/p>\n<p style=\"text-align: justify;\">De acuerdo a los lineamientos del proyecto aprobado, el desarrollar la ingenier\u00eda previa a la construcci\u00f3n de obras permitir\u00e1 conocer los montos concretos para el inicio de los trabajos.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Una vez que tengamos el dise\u00f1o listo, podremos saber el monto definitivo para la ejecuci\u00f3n del proyecto. Algunos profesionales calculan que la construcci\u00f3n del nuevo estadio estar\u00e1 por arriba de los dos mil millones de pesos\u00bb,<\/em> pronostic\u00f3 el alcalde Zamora.<\/p>\n<p style=\"text-align: justify;\">Cabe mencionar que en los \u00faltimos meses la municipalidad ha materializado proyectos de infraestructura en estadios de distintos clubes deportivos a lo largo de todo el territorio comunal de Putaendo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ff0000;\">AVANZA PROYECTO DE RECAMBIO DE CESPED<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">En este mismo \u00e1mbito, se encuentra en plena ejecuci\u00f3n el proyecto llamado \u2018Mejoramiento de Cancha e Instalaci\u00f3n de Riego Tecnificado Estadio Fiscal, Putaendo\u2019. Con una inversi\u00f3n cercana a los 35 millones de pesos, con recursos municipales, las obras est\u00e1n en la fase de siembra de pasto.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Hemos visto el tranque lleno para este proyecto de mejoramiento de la cancha actual del estadio. Por muchos a\u00f1os necesit\u00e1bamos un nuevo campo deportivo y esperamos concretar pronto estos trabajos en su totalidad\u00bb,<\/em> sostuvo el alcalde Zamora.<\/p>\n<figure id=\"attachment_108523\" aria-describedby=\"caption-attachment-108523\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-108523\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2021\/06\/ALCALDE-EN-ESTADIO-MUNICIPAL-JUNIO-2020.jpg?resize=640%2C427&#038;ssl=1\" alt=\"El alcalde Sergio Zamora valor\u00f3 la aprobaci\u00f3n de un proyecto muy esperado por la comunidad como es el nuevo estadio.\" width=\"640\" height=\"427\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2021\/06\/ALCALDE-EN-ESTADIO-MUNICIPAL-JUNIO-2020.jpg?w=699&amp;ssl=1 699w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2021\/06\/ALCALDE-EN-ESTADIO-MUNICIPAL-JUNIO-2020.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2021\/06\/ALCALDE-EN-ESTADIO-MUNICIPAL-JUNIO-2020.jpg?resize=200%2C133&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2021\/06\/ALCALDE-EN-ESTADIO-MUNICIPAL-JUNIO-2020.jpg?resize=696%2C464&amp;ssl=1 696w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-108523\" class=\"wp-caption-text\">El alcalde Sergio Zamora valor\u00f3 la aprobaci\u00f3n de un proyecto muy esperado por la comunidad como es el nuevo estadio.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Tendr\u00e1 una inversi\u00f3n superior a los 90 millones de pesos: El anhelado proyecto fue aprobado recientemente por el Consejo Regional. El alcalde Sergio Zamora considera que es una tremenda y excelente noticia&#8230;<\/p>\n","protected":false},"author":482,"featured_media":108523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[103],"tags":[],"class_list":["post-108522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica-2"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2021\/06\/ALCALDE-EN-ESTADIO-MUNICIPAL-JUNIO-2020.jpg?fit=699%2C466&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/108522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=108522"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/108522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/108523"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=108522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=108522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=108522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}