{"id":114202,"date":"2022-05-02T07:40:54","date_gmt":"2022-05-02T11:40:54","guid":{"rendered":"https:\/\/eltrabajo.cl\/portal\/?p=114202"},"modified":"2022-05-04T16:47:56","modified_gmt":"2022-05-04T20:47:56","slug":"escuela-almendral-presenta-llamativa-y-novedosa-propuesta-de-ludoteca","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/escuela-almendral-presenta-llamativa-y-novedosa-propuesta-de-ludoteca\/","title":{"rendered":"Escuela Almendral presenta llamativa y novedosa propuesta de \u2018Ludoteca\u2019"},"content":{"rendered":"<p style=\"text-align: left;\"><span style=\"color: #ff0000;\"><strong>Idea busca generar mejoras en la convivencia escolar:<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Un novedoso plan que busca mejorar la convivencia escolar en la escuela Almendral se est\u00e1 implementando hace algunos d\u00edas en dicho establecimiento. Se trata de una \u2018Ludoteca\u2019, la que, por medio del trabajo en quipos, entre otros, pretende hacer frente a un retorno a clases presenciales que en algunos establecimientos se ha vuelto un tanto problem\u00e1tico.<\/p>\n<p style=\"text-align: justify;\">En este sentido, la directora de la Escuela Almendral, <strong>Ximena Baquedano P\u00e9rez<\/strong>, se\u00f1al\u00f3 que <em>\u00aben el contexto de la convivencia escolar, el colegio presenta una propuesta de \u2018Ludoteca\u2019 de patio que permite a los estudiantes desarrollar habilidades sociales y cognitivas, tales como compartir espacios de recreaci\u00f3n en forma respetuosa y arm\u00f3nica, trabajo en equipo, desarrollo psicomotor, coordinaci\u00f3n y equilibrio, pensamiento matem\u00e1tico, etc\u00bb. <\/em><\/p>\n<p style=\"text-align: justify;\">La docente adem\u00e1s explic\u00f3 que <em>\u00abest\u00e1 probado que cuando hay una sana convivencia escolar, los ni\u00f1os quieren ir a clases y aprenden m\u00e1s. La comunidad Almendralina invita a un momento de reflexi\u00f3n conjunta entre quienes forman parte de la comunidad educativa, establecer conversaciones y generar propuestas sobre el tipo de v\u00ednculos que estamos favoreciendo en nuestro quehacer cotidiano, con el fin de fomentar modos m\u00e1s respetuosos de relacionarnos y mejorar nuestra convivencia\u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\">Baquedano tambi\u00e9n sostuvo que <em>\u00abdesde el lunes 25 de abril en reuni\u00f3n de padres y apoderados implementamos una acci\u00f3n del buen uso y no abuso del celular y objetos tecnol\u00f3gicos. Presentamos tanto a padres y\/o apoderados y a los estudiantes, un protocolo de uso del celular, cuyo objetivo es lograr la participaci\u00f3n y convivencia entre estudiantes que no se limite a estar de forma aislada frente a este objeto\u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\">Es por esto que, en el marco de todos estos planes, es que la \u2018Ludoteca\u2019 busca generar un espacio de esparcimiento para los y las estudiantes, y de esta manera, mejorar la convivencia escolar.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Para lograr este objetivo ofrecemos una ludoteca, instancia de patio entretenido con m\u00fasica y juegos. Partimos con mesas de pimp\u00f3n, balones de esponja, cuerdas, domin\u00f3 gigante, jenga , aros, etc\u00bb,<\/em> agreg\u00f3 la directora.<\/p>\n<p style=\"text-align: justify;\">Finalmente, Ximena Baquedano indic\u00f3 que <em>\u00abla reacci\u00f3n de los estudiantes a esta semana de implementaci\u00f3n ha sido positiva y muy enriquecedora desde la mirada del compartir y convivir con nuestros pares y de los adultos, a participar con los estudiantes, principalmente los asistentes y profesores que acompa\u00f1an a los alumnos durante el recreo\u00bb.<\/em><\/p>\n<figure id=\"attachment_114203\" aria-describedby=\"caption-attachment-114203\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-114203\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2022\/05\/ludoteca-1.jpg?resize=640%2C480&#038;ssl=1\" alt=\"Estudiantes de la Escuela Almendral participando de la \u2018Ludoteca\u2019.\" width=\"640\" height=\"480\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2022\/05\/ludoteca-1.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2022\/05\/ludoteca-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2022\/05\/ludoteca-1.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2022\/05\/ludoteca-1.jpg?resize=696%2C522&amp;ssl=1 696w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-114203\" class=\"wp-caption-text\">Estudiantes de la Escuela Almendral participando de la \u2018Ludoteca\u2019.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Idea busca generar mejoras en la convivencia escolar: Un novedoso plan que busca mejorar la convivencia escolar en la escuela Almendral se est\u00e1 implementando hace algunos d\u00edas en dicho establecimiento. Se trata&#8230;<\/p>\n","protected":false},"author":482,"featured_media":114203,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-114202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2022\/05\/ludoteca-1.jpg?fit=700%2C525&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/114202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=114202"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/114202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/114203"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=114202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=114202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=114202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}