{"id":12216,"date":"2011-12-23T08:50:39","date_gmt":"2011-12-23T12:50:39","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=12216"},"modified":"2011-12-23T08:50:39","modified_gmt":"2011-12-23T12:50:39","slug":"fieles-al-ex-%e2%80%9ccura-pancho%e2%80%9d-cuestionan-versiones-dadas-por-las-victimas","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/fieles-al-ex-%e2%80%9ccura-pancho%e2%80%9d-cuestionan-versiones-dadas-por-las-victimas\/","title":{"rendered":"Fieles al ex \u201cCura Pancho\u201d cuestionan versiones dadas por las v\u00edctimas"},"content":{"rendered":"<figure id=\"attachment_12217\" aria-describedby=\"caption-attachment-12217\" style=\"width: 210px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/12216\/catequista-maria-vergara\" rel=\"attachment wp-att-12217\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12217 \" title=\"CATEQUISTA MARIA VERGARA\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2011\/12\/CATEQUISTA-MARIA-VERGARA-300x168.jpg?resize=210%2C118\" alt=\"\" width=\"210\" height=\"118\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2011\/12\/CATEQUISTA-MARIA-VERGARA.jpg?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2011\/12\/CATEQUISTA-MARIA-VERGARA.jpg?resize=200%2C112&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2011\/12\/CATEQUISTA-MARIA-VERGARA.jpg?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2011\/12\/CATEQUISTA-MARIA-VERGARA.jpg?resize=400%2C224&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2011\/12\/CATEQUISTA-MARIA-VERGARA.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><figcaption id=\"caption-attachment-12217\" class=\"wp-caption-text\">Mar\u00eda Vergara, Catequista de la Parroquia, declar\u00f3 ante el Tribunal: \u201cLa PDI me llam\u00f3 a declarar porque yo hab\u00eda insultado y molestado a la ni\u00f1a C.M.O.V.\u201d<\/figcaption><\/figure>\n<p>Pablo Salinas Sald\u00edas &#8211; psalinas@eltrabajo.cl<\/p>\n<p>Continuando con el controvertido juicio contra el ex sacerdote Francisco Valenzuela, en horas de la ma\u00f1ana de ayer se conocieron nuevos relatos presentados por la defensa, donde dos catequistas manifestaron nunca haber visto algo extra\u00f1o en la Parroquia, los que se sumaron a los testimonios entregados la v\u00edspera de ex amigas de J.V.G.O., quienes cuestionaron la conducta de la joven y las circunstancias de la p\u00e9rdida de su virginidad.<\/p>\n<p>En esta ocasi\u00f3n subieron al estrado dos catequistas de la Parroquia San Antonio de Padua, Ana Mar\u00eda y Mar\u00eda Vergara, de 52 a\u00f1os, donde la primera declar\u00f3 abiertamente ser una amiga fiel del imputado, recalcando que lo visitaba en el Centro de Cumplimiento Penitenciario de San Felipe, lugar donde se encuentra en prisi\u00f3n preventiva.<\/p>\n<p>Ambas mujeres de igual forma manifestaron que el imputado, cuando era sacerdote, prestaba amablemente su celular a todos los j\u00f3venes cuando se lo ped\u00edan, en alusi\u00f3n a la fotograf\u00eda pornogr\u00e1fica recibida por una de las v\u00edctimas, puntualizando que Francisco Valenzuela era una persona muy afectiva y que a todos saludaba de la misma forma.<\/p>\n<p>A ellas se les unieron los testimonios aportados por Karen Gallardo y Paulina Ferreira, quienes expresaron ser ex amigas de la v\u00edctima J.V.G.O., quienes de igual forma como lo dimos a conocer en nuestra edici\u00f3n del d\u00eda de ayer, las muchachas dudan del relato en contra de Valenzuela, cuestionando la conducta de la v\u00edctima y reiterando que la p\u00e9rdida de su virginidad habr\u00eda sido con su ex pareja, Javier Olgu\u00edn.<\/p>\n<p>Al t\u00e9rmino de esta jornada, el abogado querellante Jos\u00e9 Villagr\u00e1n manifest\u00f3 a DIARIO EL TRABAJO que \u00abhasta ahora estos testimonios no representan ning\u00fan sobresalto ni relevancia que complique o que ponga en duda los hechos imputados, la defensa est\u00e1 haciendo uso de su derecho de presentar los testimonios que estime pertinentes\u00bb.<\/p>\n<p>Villagr\u00e1n estim\u00f3 que para el pr\u00f3ximo lunes se espera la prueba pericial presentada por la defensa, la que es relativa al an\u00e1lisis que entreg\u00f3 el CAVAS, donde una de las v\u00edctimas, J.V.G.O., fue sometida a tres pruebas periciales por esta entidad. Pero a su vez la defensa contrat\u00f3 un perito particular, quien ha se\u00f1alado que esas tres pericias no son t\u00e9cnicas, la que se presentar\u00e1 ante el Tribunal para demostrar que esas pericias no ser\u00edan concluyentes y que sembrar\u00edan alg\u00fan tipo de dudas ante el Tribunal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pablo Salinas Sald\u00edas &#8211; psalinas@eltrabajo.cl Continuando con el controvertido juicio contra el ex sacerdote Francisco Valenzuela, en horas de la ma\u00f1ana de ayer se conocieron nuevos relatos presentados por la defensa, donde&#8230;<\/p>\n","protected":false},"author":482,"featured_media":12217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-12216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2011\/12\/CATEQUISTA-MARIA-VERGARA.jpg?fit=600%2C337&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=12216"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/12217"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=12216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=12216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=12216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}