{"id":122973,"date":"2023-07-11T07:35:41","date_gmt":"2023-07-11T11:35:41","guid":{"rendered":"https:\/\/eltrabajo.cl\/portal\/?p=122973"},"modified":"2023-07-10T23:11:09","modified_gmt":"2023-07-11T03:11:09","slug":"facundo-gomez-da-vuelta-la-pagina-y-ya-piensa-en-proximo-desafio-del-uni","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/facundo-gomez-da-vuelta-la-pagina-y-ya-piensa-en-proximo-desafio-del-uni\/","title":{"rendered":"Facundo G\u00f3mez da vuelta la p\u00e1gina y ya piensa en pr\u00f3ximo desaf\u00edo del Un\u00ed"},"content":{"rendered":"<p>El volante ofensivo del Un\u00ed Un\u00ed, <strong>Facundo G\u00f3mez<\/strong>, no escondi\u00f3 su desilusi\u00f3n por haber desperdiciado la opci\u00f3n del triunfo frente al <strong>AC Barnechea<\/strong>. Pese al empate, el trasandino prefiri\u00f3 encontrar cosas positivas de ese resultado. <em>\u00abLo ideal era ganar, pero cuando no se puede es importante sumar, aunque sea un empate. Igual quedamos tristes porque sab\u00edamos que lo ideal era el triunfo\u00bb,<\/em> afirm\u00f3.<\/p>\n<p>Respecto al juego que mostr\u00f3 el Un\u00ed Un\u00ed, el jugador se\u00f1al\u00f3: <em>\u00abTuvimos nuestras posibilidades. No fueron muchas, y por eso el error fue no haber convertido. A medida que fue avanzando el tiempo, nos fuimos fastidiando. Despu\u00e9s el segundo tiempo fue una ida y vuelta constante, en el cual cualquiera de los dos pudo haberlo ganado\u00bb.<\/em><\/p>\n<p>Pese a estar desde principio de la temporada, Facundo G\u00f3mez debi\u00f3 esperar mucho para que le llegara su oportunidad. Esto fue en el recordado triunfo sobre San Luis, donde el jugador se gan\u00f3 la atenci\u00f3n de todo el medio, por lo mismo era interesante saber si hab\u00eda quedado del todo conforme con su actuaci\u00f3n.\u00a0 <em>\u00abSiempre uno trata de dar lo mejor, ahora solo hay que seguir porque esto es largo. Todos los partidos son importantes, as\u00ed que hay que preparar bien el partido contra Antofagasta\u00bb,<\/em> respondi\u00f3.<\/p>\n<figure id=\"attachment_122974\" aria-describedby=\"caption-attachment-122974\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-122974\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Gomez.jpg?resize=640%2C403&#038;ssl=1\" alt=\"G\u00f3mez tratando de dejar atr\u00e1s a un marcador de Barnechea. (Foto: Jorge Ampuero)\" width=\"640\" height=\"403\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Gomez.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Gomez.jpg?resize=300%2C189&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Gomez.jpg?resize=200%2C126&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Gomez.jpg?resize=696%2C438&amp;ssl=1 696w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-122974\" class=\"wp-caption-text\">G\u00f3mez tratando de dejar atr\u00e1s a un marcador de Barnechea. (Foto: Jorge Ampuero)<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El volante ofensivo del Un\u00ed Un\u00ed, Facundo G\u00f3mez, no escondi\u00f3 su desilusi\u00f3n por haber desperdiciado la opci\u00f3n del triunfo frente al AC Barnechea. Pese al empate, el trasandino prefiri\u00f3 encontrar cosas positivas&#8230;<\/p>\n","protected":false},"author":482,"featured_media":122974,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[38,894,874,27,92],"class_list":["post-122973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-aconcagua","tag-deportes","tag-futbol-profesional","tag-san-felipe","tag-union-san-felipe"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Gomez.jpg?fit=700%2C441&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/122973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=122973"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/122973\/revisions"}],"predecessor-version":[{"id":122975,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/122973\/revisions\/122975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/122974"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=122973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=122973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=122973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}