{"id":123203,"date":"2023-07-21T07:54:17","date_gmt":"2023-07-21T11:54:17","guid":{"rendered":"https:\/\/eltrabajo.cl\/portal\/?p=123203"},"modified":"2023-07-20T23:34:07","modified_gmt":"2023-07-21T03:34:07","slug":"en-estado-grave-hombre-que-recibio-tres-impactos-de-bala-en-la-villa-el-totoral","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/en-estado-grave-hombre-que-recibio-tres-impactos-de-bala-en-la-villa-el-totoral\/","title":{"rendered":"En estado grave hombre que recibi\u00f3 tres impactos de bala en la Villa El Totoral"},"content":{"rendered":"<ul>\n<li><strong>V\u00edctima se trasladaba en su motocicleta cuando recibi\u00f3 los impactos.-<\/strong><\/li>\n<\/ul>\n<p>Un hombre se encuentra en estado grave, aunque fuera de riesgo vital, internado en el Hospital San Camilo de San Felipe, tras recibir tres impactos de bala en el sector de la <strong>Villa El Totoral<\/strong> de nuestra ciudad.<\/p>\n<p>Por causas que est\u00e1n siendo investigadas por Carabineros, la v\u00edctima recibi\u00f3 dos balazos en la zona lumbar y otro en una de sus extremidades.<\/p>\n<p>El Comisario de Carabineros, mayor <strong>Jorge Guzm\u00e1n<\/strong>, se\u00f1al\u00f3 que <em>\u00abefectivamente ayer <\/em>(mi\u00e9rcoles)<em> en la Villa El Totoral mantuvimos una persona lesionada por impactos bal\u00edsticos, se encuentra fuera de riesgo vital, tuvo complicaciones durante la noche y fue necesario desplegar un amplio operativo m\u00e9dico para poder estabilizarlo, el cual gracias a Dios sali\u00f3 de manera fruct\u00edfera y est\u00e1 estable dentro de su gravedad\u00bb.<\/em><\/p>\n<p>Asimismo, el mayor Guzm\u00e1n detall\u00f3 que <em>\u00abson tres impactos bal\u00edsticos los que tiene, dos en la zona lumbar y uno en la parte posterior de la pierna derecha. Las circunstancias est\u00e1n en materia de investigaci\u00f3n, se est\u00e1n desplegando los operativos policiales para dar con los autores del hecho, al momento no se mantienen personas identificadas y la totalidad de lo sucedido fue informado al Ministerio P\u00fablico de San Felipe\u00bb.<\/em><\/p>\n<p>Finalmente, el Comisario precis\u00f3 que la v\u00edctima recibi\u00f3 estos balazos cuando se movilizaba en su motocicleta por el sector; <em>\u00abes mayor de edad, lo hac\u00eda en su motocicleta, chileno y por circunstancias que se est\u00e1n investigando \u00e9l recibi\u00f3 estos impactos bal\u00edsticos\u00bb,<\/em> cerr\u00f3.<\/p>\n<figure id=\"attachment_123204\" aria-describedby=\"caption-attachment-123204\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-123204\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/baleado-totoral.jpg?resize=640%2C464&#038;ssl=1\" alt=\"Personal de Carabineros se constituy\u00f3 en el sitio del suceso poco despu\u00e9s del atentado.\" width=\"640\" height=\"464\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/baleado-totoral.jpg?w=699&amp;ssl=1 699w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/baleado-totoral.jpg?resize=300%2C218&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/baleado-totoral.jpg?resize=200%2C145&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/baleado-totoral.jpg?resize=696%2C505&amp;ssl=1 696w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/baleado-totoral.jpg?resize=324%2C235&amp;ssl=1 324w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-123204\" class=\"wp-caption-text\">Personal de Carabineros se constituy\u00f3 en el sitio del suceso poco despu\u00e9s del atentado.<\/figcaption><\/figure>\n<figure id=\"attachment_123205\" aria-describedby=\"caption-attachment-123205\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-123205\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Mayor-Jorge-Guzman.jpg?resize=640%2C450&#038;ssl=1\" alt=\"Mayor Jorge Guzm\u00e1n, comisario de Carabineros de San Felipe.\" width=\"640\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Mayor-Jorge-Guzman.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Mayor-Jorge-Guzman.jpg?resize=300%2C211&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Mayor-Jorge-Guzman.jpg?resize=200%2C141&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/Mayor-Jorge-Guzman.jpg?resize=696%2C489&amp;ssl=1 696w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-123205\" class=\"wp-caption-text\">Mayor Jorge Guzm\u00e1n, comisario de Carabineros de San Felipe.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edctima se trasladaba en su motocicleta cuando recibi\u00f3 los impactos.- Un hombre se encuentra en estado grave, aunque fuera de riesgo vital, internado en el Hospital San Camilo de San Felipe, tras&#8230;<\/p>\n","protected":false},"author":482,"featured_media":123204,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[38,981,57,983,27,984],"class_list":["post-123203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-aconcagua","tag-balacera","tag-carabineros","tag-herido","tag-san-felipe","tag-villa-el-totoral"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/baleado-totoral.jpg?fit=699%2C507&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/123203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=123203"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/123203\/revisions"}],"predecessor-version":[{"id":123206,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/123203\/revisions\/123206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/123204"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=123203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=123203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=123203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}