{"id":123356,"date":"2023-07-31T07:45:20","date_gmt":"2023-07-31T11:45:20","guid":{"rendered":"https:\/\/eltrabajo.cl\/portal\/?p=123356"},"modified":"2023-07-30T22:35:32","modified_gmt":"2023-07-31T02:35:32","slug":"lanzan-plan-piloto-auto-testeo-del-virus-de-inmunodeficiencia-humana-cih","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/lanzan-plan-piloto-auto-testeo-del-virus-de-inmunodeficiencia-humana-cih\/","title":{"rendered":"Lanzan plan piloto auto testeo del Virus de Inmunodeficiencia Humana CIH"},"content":{"rendered":"<ul>\n<li><strong>Examen permite tener un resultado en 20 minutos.-<\/strong><\/li>\n<\/ul>\n<p>En la Universidad de Aconcagua, sede San Felipe, el Servicio de Salud Aconcagua (SSA) lanz\u00f3 el plan piloto de la campa\u00f1a que lleva a cabo el Ministerio de Salud para el auto testeo del virus del VIH Sida. el trabajo est\u00e1 dirigido principalmente a los j\u00f3venes universitarios para la prevenci\u00f3n y educaci\u00f3n de esta enfermedad.<\/p>\n<p><strong>Maricruz Naylor<\/strong>, enfermera encargada del programa de VIH del Servicio de Salud Aconcagua, se\u00f1al\u00f3 que <em>\u00abla Universidad de Aconcagua, sede San Felipe, se encuentra participando activamente de este piloto de la implementaci\u00f3n del auto test del VIH.<\/em><\/p>\n<p>\u00ab<em>Importante mencionar que la implementaci\u00f3n de esta estrategia es a nivel ministerial, en el contexto del programa de prevenci\u00f3n y control del VIH, y a cada Servicio de Salud, en conjunto con la Seremi de Salud, nos han mandado la tarea de poder comenzar la implantaci\u00f3n\u00bb,<\/em> agreg\u00f3.<\/p>\n<p>Es as\u00ed, que la campa\u00f1a comenz\u00f3 ya con el lanzamiento y una charla en cuanto a la prevenci\u00f3n del VIH, oportunidad en la que adem\u00e1s se explic\u00f3 c\u00f3mo se aplica este auto test.<\/p>\n<p>\u00ab<em>Nosotros en el valle del Aconcagua decidimos comenzarla con los establecimientos de nivel superior debido a que el objetivo que tiene esta estrategia es reducir brechas en el acceso y poder llegar a la poblaci\u00f3n que no est\u00e1 accediendo o acudiendo a tomarse el test del VIH en los establecimientos de salud\u00bb,<\/em> destac\u00f3 Naylor.<\/p>\n<p>Asimismo, la enfermera a cargo de este trabajo del SSA sostuvo que <em>\u00abinicialmente se va a estar entregando en las universidades, pr\u00f3ximamente vamos a comenzar a entregarlo en todos los niveles de educaci\u00f3n superior que tenemos para luego seguir con las municipalidades, oficinas de la diversidad y, finalmente, tenerlo disponible en el servicio de atenci\u00f3n primaria\u00bb. <\/em><\/p>\n<p>Respecto de c\u00f3mo funciona y se hace el auto testeo, la profesional precis\u00f3 que <em>\u00abse entrega un kit donde est\u00e1 el auto test, hay folleter\u00eda informativa de acuerdo al auto test y promoci\u00f3n y prevenci\u00f3n del VIH y las ETS\u00bb<\/em> (Enfermedades de Transmisi\u00f3n Sexual).<\/p>\n<p>\u00ab<em>Es un test sencillo, no necesita que participe una persona que sepa de salud, se lo puede realizar la misma persona en forma aut\u00f3noma y privada, no necesita a un sistema de salud para poder realiz\u00e1rselo, el resultado es un reactivo para que la persona luego pueda acceder a la atenci\u00f3n primaria de salud para la confirmaci\u00f3n diagn\u00f3stica, se demora aproximadamente 20 minutos\u00bb,<\/em> agreg\u00f3.<\/p>\n<p>En la pr\u00e1ctica, usted debe pincharse con un elemento que viene dentro del kit uno de sus dedos para que salga una gota de sangre, esta misma la vierte en un dispositivo al que posteriormente le coloca un l\u00edquido especial y debe esperar el tiempo antes se\u00f1alado. Una vez que haya realizado todo esto, usted tendr\u00e1 su resultado.<\/p>\n<p>Finalmente, Maricruz Naylor dijo que <em>\u00abesto es un piloto, vamos de forma paulatina, esperamos que m\u00e1ximo al mes de enero del 2024 ya lo tengamos disponible en toda la red, no s\u00f3lo en la atenci\u00f3n primaria, sino que en Hospitales y otros dispositivos, es importante ac\u00e1 que l\u00edderes de la comunidad se van a involucrar para que esto se pueda hacer m\u00e1s masivo\u00bb.<\/em><\/p>\n<figure id=\"attachment_123357\" aria-describedby=\"caption-attachment-123357\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-123357\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-Maricruz-Naylor.jpg?resize=640%2C457&#038;ssl=1\" alt=\"Maricruz Naylor, enfermera encargada del programa de VIH del Servicio de Salud Aconcagua. \" width=\"640\" height=\"457\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-Maricruz-Naylor.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-Maricruz-Naylor.jpg?resize=300%2C214&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-Maricruz-Naylor.jpg?resize=200%2C143&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-Maricruz-Naylor.jpg?resize=696%2C497&amp;ssl=1 696w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-123357\" class=\"wp-caption-text\">Maricruz Naylor, enfermera encargada del programa de VIH del Servicio de Salud Aconcagua.<\/figcaption><\/figure>\n<figure id=\"attachment_123358\" aria-describedby=\"caption-attachment-123358\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-123358\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-autotest-copia.jpg?resize=640%2C790&#038;ssl=1\" alt=\"Profesionales explicando a uno de los presentes c\u00f3mo realizarse el auto test.\" width=\"640\" height=\"790\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-autotest-copia.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-autotest-copia.jpg?resize=243%2C300&amp;ssl=1 243w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-autotest-copia.jpg?resize=122%2C150&amp;ssl=1 122w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-autotest-copia.jpg?resize=324%2C400&amp;ssl=1 324w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-autotest-copia.jpg?resize=696%2C859&amp;ssl=1 696w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-123358\" class=\"wp-caption-text\">Profesionales explicando a uno de los presentes c\u00f3mo realizarse el auto test.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Examen permite tener un resultado en 20 minutos.- En la Universidad de Aconcagua, sede San Felipe, el Servicio de Salud Aconcagua (SSA) lanz\u00f3 el plan piloto de la campa\u00f1a que lleva a&#8230;<\/p>\n","protected":false},"author":482,"featured_media":123359,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[103],"tags":[38,1046,857,27,1045],"class_list":["post-123356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica-2","tag-aconcagua","tag-examen","tag-salud","tag-san-felipe","tag-vih-sida"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/07\/VIH-autotest.jpg?fit=700%2C530&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/123356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=123356"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/123356\/revisions"}],"predecessor-version":[{"id":123360,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/123356\/revisions\/123360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/123359"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=123356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=123356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=123356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}