{"id":126091,"date":"2023-12-12T07:45:50","date_gmt":"2023-12-12T10:45:50","guid":{"rendered":"https:\/\/eltrabajo.cl\/portal\/?p=126091"},"modified":"2023-12-11T21:45:59","modified_gmt":"2023-12-12T00:45:59","slug":"pan-de-pascua-de-panaderia-moderna-fue-elegido-el-segundo-mejor-de-chile","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/pan-de-pascua-de-panaderia-moderna-fue-elegido-el-segundo-mejor-de-chile\/","title":{"rendered":"Pan de pascua de Panader\u00eda Moderna fue elegido el segundo mejor de Chile"},"content":{"rendered":"<p>El Pan de Pascua de la \u2018Panader\u00eda Moderna\u2019 de San Felipe fue elegido como el segundo mejor de Chile, luego de un an\u00e1lisis realizado por la Asociaci\u00f3n Gremial de Industriales del Pan (Indupan).<\/p>\n<p>Con una historia que data desde el a\u00f1o 1905 y con una administraci\u00f3n familiar que ya va en su cuarta generaci\u00f3n, la Panader\u00eda Moderna obtuvo la distinci\u00f3n en el concurso \u2018Mejor Pan de Pascua de Chile en el 2023\u2019, el que cont\u00f3 con 93 participantes.<\/p>\n<p>Seg\u00fan comentaron a <strong>Diario El Trabajo<\/strong>, la receta del distinguido pan de pascua fue tra\u00edda directamente desde Alemania y con influencias de Francia, lo cual logr\u00f3 una qu\u00edmica perfecta para su preparaci\u00f3n, sin olvidar el trabajo de los panaderos, quienes han sabido mantener la calidad del producto. Adem\u00e1s, un punto destacado del estudio, es que fue el \u00fanico pan que a\u00fan se prepara con levadura y no con polvos de hornear.<\/p>\n<p>En relaci\u00f3n a este gran reconocimiento para su pan de pascua, <strong>Jos\u00e9 Tom\u00e1s Jorquera<\/strong>, administrador de la \u2018Panader\u00eda Moderna\u2019, abord\u00f3 la tradici\u00f3n que tiene el local familiar y su destacada participaci\u00f3n en este concurso. <em>\u00abUna panader\u00eda que est\u00e1 desde 1905, somos ya la cuarta generaci\u00f3n que contin\u00faa el negocio familiar, parti\u00f3 con mi abuelo y ahora bueno, se sigue la tradici\u00f3n familiar, hasta el pan de pascua, que lo trajo mi abuelo de Alemania la receta\u00bb<\/em>.<\/p>\n<p>En este sentido, se refiri\u00f3 a la f\u00f3rmula que los ha llevado al \u00e9xito y que los diferencia por sobre el resto en la materia. <em>\u00abBueno, la primera parte es que la receta la trajimos de afuera, mi abuelo la trajo de Alemania y hay influencia francesa tambi\u00e9n por otro lado de la familia, y por ah\u00ed hemos logrado hacer harta y buena qu\u00edmica en lo que es la receta. Yo tengo gente de Santiago que viene a comprar pan, vamos a dejar pan a las Termas de Jahuel, ahora tengo un pedido de un cliente de Santiago, mucha gente, la gente de San Felipe nos quiere harto tambi\u00e9n y hemos tenido harto reconocimiento por eso. Por lo menos ahora en temporada estamos haciendo unos 200, 250 kilos diarios y ah\u00ed salen millones de panes de pascua, imag\u00ednate, vueltos locos embolsando\u00bb<\/em>, a\u00f1adi\u00f3.<\/p>\n<figure id=\"attachment_126092\" aria-describedby=\"caption-attachment-126092\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-126092\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua.jpg?resize=640%2C361&#038;ssl=1\" alt=\"Jos\u00e9 Tom\u00e1s Jorquera, administrador de Panader\u00eda Moderna, junto a sus tradicionales panes de pascua.\" width=\"640\" height=\"361\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua.jpg?w=699&amp;ssl=1 699w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua.jpg?resize=200%2C113&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua.jpg?resize=696%2C392&amp;ssl=1 696w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-126092\" class=\"wp-caption-text\">Jos\u00e9 Tom\u00e1s Jorquera, administrador de Panader\u00eda Moderna, junto a sus tradicionales panes de pascua.<\/figcaption><\/figure>\n<figure id=\"attachment_126093\" aria-describedby=\"caption-attachment-126093\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-126093\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua-2.jpg?resize=640%2C361&#038;ssl=1\" alt=\"Certificaci\u00f3n del segundo puesto en \u2018Mejor Pan de Pascua en Chile 2023\u2019.\" width=\"640\" height=\"361\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua-2.jpg?w=699&amp;ssl=1 699w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua-2.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua-2.jpg?resize=200%2C113&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua-2.jpg?resize=696%2C392&amp;ssl=1 696w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-126093\" class=\"wp-caption-text\">Certificaci\u00f3n del segundo puesto en \u2018Mejor Pan de Pascua en Chile 2023\u2019.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Pan de Pascua de la \u2018Panader\u00eda Moderna\u2019 de San Felipe fue elegido como el segundo mejor de Chile, luego de un an\u00e1lisis realizado por la Asociaci\u00f3n Gremial de Industriales del Pan&#8230;<\/p>\n","protected":false},"author":482,"featured_media":126093,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[103],"tags":[],"class_list":["post-126091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica-2"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2023\/12\/pan-de-pascua-2.jpg?fit=699%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/126091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=126091"}],"version-history":[{"count":2,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/126091\/revisions"}],"predecessor-version":[{"id":126095,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/126091\/revisions\/126095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/126093"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=126091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=126091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=126091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}