{"id":12632,"date":"2012-01-11T08:21:12","date_gmt":"2012-01-11T12:21:12","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=12632"},"modified":"2012-01-11T08:21:12","modified_gmt":"2012-01-11T12:21:12","slug":"de-piscina-y-cine-disfrutaran-160-ninos-en-tres-centros-para-hijos-de-madres-temporeras","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/de-piscina-y-cine-disfrutaran-160-ninos-en-tres-centros-para-hijos-de-madres-temporeras\/","title":{"rendered":"De piscina y cine disfrutar\u00e1n 160 ni\u00f1os en tres centros para hijos de madres temporeras"},"content":{"rendered":"<figure id=\"attachment_12634\" aria-describedby=\"caption-attachment-12634\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/12632\/centro-madres-temporeras-2\" rel=\"attachment wp-att-12634\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12634\" title=\"centro madres temporeras 2\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/centro-madres-temporeras-2.jpg?resize=600%2C450\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/centro-madres-temporeras-2.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/centro-madres-temporeras-2.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/centro-madres-temporeras-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/centro-madres-temporeras-2.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/centro-madres-temporeras-2.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-12634\" class=\"wp-caption-text\">Los ni\u00f1os y ni\u00f1as que participan en los centros tendr\u00e1n variadas actividades durante los 45 d\u00edas que dura la iniciativa.<\/figcaption><\/figure>\n<p>Desde el martes 3 de enero est\u00e1n en funcionamiento los centros para hijos de mujeres temporeras, un programa a cargo de la Municipalidad de San Felipe, que significa una importante inversi\u00f3n de la corporaci\u00f3n edilicia y que tiene como objetivo trabajar con los ni\u00f1os mientras sus madres trabajan en la temporada de verano.<\/p>\n<p>La iniciativa es uno de los programas m\u00e1s importantes que tiene el municipio y donde existe una inversi\u00f3n tanto de esta entidad como del IND y del Ministerio de Desarrollo Social, que es el encargado de coordinar con servicios como la Junaeb para la entrega de las raciones alimenticias.<\/p>\n<p>Este a\u00f1o, tal como en anteriores versiones del programa, existen tres centros ubicados en el Liceo San Felipe, que tiene un cupo para 70 ni\u00f1os; el liceo Carmela Carvajal en Curim\u00f3n, que tiene un cupo de 45 ni\u00f1os, y el liceo Heriberto Berm\u00fadez en el sector de Algarrobal con igual cupo.<\/p>\n<p>Los centros todav\u00eda cuentan con cupos, por ello aquellas mam\u00e1s interesadas deben trasladarse directamente a los establecimientos que son sedes e inscribir a los ni\u00f1os, los que deben tener entre 6 y 12 a\u00f1os de edad. Adem\u00e1s se debe presentar el contrato de trabajo de la trabajadora y el certificado de nacimiento del ni\u00f1o.<\/p>\n<p>\u00abEsto no es la extensi\u00f3n del colegio, son netamente actividades sociorecreativas y culturales, la idea es que los ni\u00f1os vengan a estas escuelas de verano a pasarlo bien, a entretenerse. Cada centro contempla salidas a lugares culturales como museos y a los recintos donde trabajan las madres, para promocionar el programa y para acercar a las mujeres, para que ellas tengan la confianza absoluta de que sus hijos van a estar bien cuidados y con actividades que son de inter\u00e9s de los ni\u00f1os\u00bb, se\u00f1al\u00f3 Patricia Lolas, encargada del programa.<\/p>\n<p>Los ni\u00f1os adem\u00e1s del trabajo que realizar\u00e1n en los centros, tendr\u00e1n visitas a la piscina dos veces por semana, iniciativa donde el municipio ha colocado importantes recursos destinados al traslado de los peque\u00f1os.<\/p>\n<p>Adem\u00e1s el programa Senda Previene y la OPD tambi\u00e9n realizar\u00e1n actividades en los centros, a lo que se suma la visita de los ni\u00f1os a tarde de cine.<\/p>\n<p>El programa significa una importante inversi\u00f3n en lo que se refiere a recursos humanos, ya que el municipio realiz\u00f3 un proceso de selecci\u00f3n donde se contrat\u00f3 a 13 encargados para los respectivos centros, adem\u00e1s de un equipo de profesionales que apoyan la labor del encargado, a los que se suman los profesionales que dispuso el IND para llevar a cabo el programa.<\/p>\n<p>Respecto del traslado de los ni\u00f1os, adem\u00e1s de la adquisici\u00f3n de materiales y alimentaci\u00f3n extraordinaria, el municipio ha dispuesto un mill\u00f3n de pesos, lo que en total significa una inversi\u00f3n general del programa, cercana a los 11 millones de pesos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el martes 3 de enero est\u00e1n en funcionamiento los centros para hijos de mujeres temporeras, un programa a cargo de la Municipalidad de San Felipe, que significa una importante inversi\u00f3n de&#8230;<\/p>\n","protected":false},"author":482,"featured_media":12633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-12632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/centro-madres-temporeras.jpg?fit=600%2C450&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=12632"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/12633"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=12632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=12632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=12632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}