{"id":12716,"date":"2012-01-12T09:05:56","date_gmt":"2012-01-12T13:05:56","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=12716"},"modified":"2012-01-12T09:05:56","modified_gmt":"2012-01-12T13:05:56","slug":"madre-pide-justicia-para-su-hija-abusada-por-indigente-que-fue-liberado","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/madre-pide-justicia-para-su-hija-abusada-por-indigente-que-fue-liberado\/","title":{"rendered":"Madre pide justicia para su hija abusada por indigente que fue liberado"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_12717\" aria-describedby=\"caption-attachment-12717\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/12716\/nancy-berrios-gonzalez\" rel=\"attachment wp-att-12717\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12717\" title=\"Nancy Berrios Gonz\u00e1lez\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/Nancy-Berrios-Gonz%C3%A1lez-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/Nancy-Berrios-Gonz%C3%A1lez.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/Nancy-Berrios-Gonz%C3%A1lez.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/Nancy-Berrios-Gonz%C3%A1lez.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/Nancy-Berrios-Gonz%C3%A1lez.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/Nancy-Berrios-Gonz%C3%A1lez.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-12717\" class=\"wp-caption-text\">Nancy Berr\u00edos Gonz\u00e1lez, madre de la menor de 15 a\u00f1os F.P.V.B., quien fue v\u00edctima de abuso sexual.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Sujeto irrumpi\u00f3 de madrugada en su casa donde vive sola con su hija de 15 a\u00f1os, de quien abus\u00f3 mientras dorm\u00edan. Fue denunciado y detenido, quedando en libertad el mismo d\u00eda.<\/strong><\/li>\n<\/ul>\n<p>Pablo Salinas Sald\u00edas &#8211; psalinas@eltrabajo.cl<\/p>\n<p>Un desesperado llamado a las autoridades judiciales formul\u00f3 Nancy Berr\u00edos Gonz\u00e1lez, madre de la menor de 15 a\u00f1os F.P.V.B., quien fue v\u00edctima de abuso sexual cuando un hombre indigente irrumpi\u00f3 en el dormitorio de la menor realiz\u00e1ndole tocaciones en todo su cuerpo mientras dorm\u00eda en su vivienda ubicada en la comuna de Santa Mar\u00eda.<\/p>\n<p>Seg\u00fan el relato de Nancy Berr\u00edos y la propia v\u00edctima a Diario El Trabajo, los hechos se produjeron alrededor de las cuatro de la madrugada del lunes, cuando ella y su hija se encontraban durmiendo, circunstancia en que el hombre identificado como E.A.N.S., un indigente de 40 a\u00f1os que habita en el estero San Francisco del sector San Jos\u00e9 de esa comuna, irrumpi\u00f3 en la vivienda ingresando por una ventana y dirigi\u00e9ndose hasta el dormitorio de la menor, a quien comenz\u00f3 a realizarle tocaciones aprovechando que dorm\u00eda.<\/p>\n<p>\u00abMe busc\u00f3 hasta llegar a mi pieza y me alumbr\u00f3 con un encendedor, cuando intent\u00e9 prender la l\u00e1mpara de mi velador, no prend\u00eda. Y despert\u00e9 con mucho susto para ver quien en esos instantes estaba tocando todo mi cuerpo, solo ve\u00eda una persona alta y al verla a contraluz me di cuenta que era ese tipo. Como yo grit\u00e9, \u00e9l sali\u00f3 arrancando, al darnos cuenta la ventana estaba abierta y la cortina corrida y en el sill\u00f3n estaba la huella de su zapatilla\u00bb, relat\u00f3 la muchacha afectada.<\/p>\n<p>El sujeto fue detenido por Carabineros de la comuna de Santa Mar\u00eda, pasando a control de detenci\u00f3n el pasado lunes ante el Juzgado de Garant\u00eda de San Felipe, donde qued\u00f3 en libertad.<\/p>\n<p>La fiscal Yasmina Aspe, a cargo del caso, consultada por esta situaci\u00f3n, indic\u00f3: \u00abCuando se realiza la audiencia de control de detenci\u00f3n y revisan los antecedentes del parte policial, que ten\u00eda la descripci\u00f3n del hecho y las declaraciones b\u00e1sicamente de quien se refer\u00eda como v\u00edctima y adem\u00e1s su madre, los antecedentes que estaban en el parte no eran suficientes para poder formular cargos en ese minuto, que es lo que implica una formalizaci\u00f3n en la investigaci\u00f3n. Lo m\u00e1s importante que uno tiene que llegar a la conclusi\u00f3n de que hayan antecedentes serios para poder atribu\u00edrselos a una persona para una conducta en un contexto de delito, como los antecedentes no eran suficientes para eso, se ampli\u00f3 el control de detenci\u00f3n del imputado hasta el d\u00eda siguiente. Entonces por la tarde del mismo d\u00eda se tom\u00f3 una nueva declaraci\u00f3n a las personas involucradas, la v\u00edctima y su madre, estas declaraciones no eran coincidentes con el parte policial. Esto se puede entender como es una denuncia que est\u00e1 recepcionando, bajo un marco de nerviosismo o de alguna alteraci\u00f3n a prop\u00f3sito de los hechos, en esta nueva declaraci\u00f3n detallada y esa nueva informaci\u00f3n que se aporta no es suficiente para poder formalizar investigaci\u00f3n. Esto no implica que la investigaci\u00f3n termina\u00bb, destac\u00f3.<\/p>\n<p>La Fiscal Aspe recalc\u00f3 que el \u00abMinisterio P\u00fablico est\u00e1 diciendo hoy d\u00eda `no tengo antecedentes suficientes para formularle cargos y por lo tanto para pedir medidas cautelares\u00b4, pero la investigaci\u00f3n contin\u00faa y se tienen que decretar diligencias, porque as\u00ed lo instru\u00ed particularmente, para poder determinar luego si efectivamente esos antecedentes aparecen y si se formulan nuevos cargos en la persona denunciada. Como Ministerio P\u00fablico tenemos la obligaci\u00f3n de investigar con objetividad, eso implica lo que perjudica a una persona denunciada y con el mismo celo lo que lo favorece, y por lo tanto el an\u00e1lisis de los antecedentes lo tenemos que hacer desde un punto de vista objetivo y para poder imputar a una persona en un delito\u00bb, enfatiz\u00f3.<\/p>\n<p>Sin embargo, la madre apunt\u00f3 que el acusado ha mantenido conductas reiterativas en contra de su hija, acos\u00e1ndola y haci\u00e9ndole propuestas sexuales en la v\u00eda p\u00fablica, ofreci\u00e9ndole dinero a cambio, por lo que hace un llamado de atenci\u00f3n a la autoridad policial y judicial, ya que se siente desamparada desde que enviud\u00f3 hace unos meses, solicitando los resguardos correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Sujeto irrumpi\u00f3 de madrugada en su casa donde vive sola con su hija de 15 a\u00f1os, de quien abus\u00f3 mientras dorm\u00edan. Fue denunciado y detenido, quedando en libertad el mismo&#8230;<\/p>\n","protected":false},"author":482,"featured_media":12717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-12716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/Nancy-Berrios-Gonz%C3%A1lez.jpg?fit=600%2C450&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=12716"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/12717"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=12716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=12716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=12716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}