{"id":12860,"date":"2012-01-17T08:23:18","date_gmt":"2012-01-17T12:23:18","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=12860"},"modified":"2012-01-17T08:23:18","modified_gmt":"2012-01-17T12:23:18","slug":"vecinos-de-villa-los-alamos-participan-en-taller-para-mejorar-la-convivencia-barrial","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/vecinos-de-villa-los-alamos-participan-en-taller-para-mejorar-la-convivencia-barrial\/","title":{"rendered":"Vecinos de Villa Los \u00c1lamos participan en taller para mejorar la convivencia barrial"},"content":{"rendered":"<figure id=\"attachment_12861\" aria-describedby=\"caption-attachment-12861\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/12860\/vecinos-participantes-1\" rel=\"attachment wp-att-12861\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12861\" title=\"vecinos participantes (1)\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/vecinos-participantes-1.jpg?resize=600%2C450\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/vecinos-participantes-1.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/vecinos-participantes-1.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/vecinos-participantes-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/vecinos-participantes-1.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/vecinos-participantes-1.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-12861\" class=\"wp-caption-text\">Una importante participaci\u00f3n de los vecinos se registr\u00f3 en el taller, los que llegaron desde distintos sectores de la comuna.<\/figcaption><\/figure>\n<ul>\n<li><strong>Vecinos conocieron distintas estrategias de asociatividad para mejorar la relaci\u00f3n entre ellos y superar conflictos que se puedan generar en los barrios a trav\u00e9s de una actividad organizada por la Junta de Vecinos de Santa Br\u00edgida.<\/strong><\/li>\n<\/ul>\n<p>Con la presencia de autoridades de la provincia y de los vecinos de las villa Los \u00c1lamos y otros sectores de la comuna, adem\u00e1s de tres destacados acad\u00e9micos e investigadores, se realiz\u00f3 este viernes la jornada taller \u2018Fortalecimiento de la Asociatividad y la Convivencia Barrial\u2019, una actividad organizada por la junta de vecinos de la poblaci\u00f3n Santa Br\u00edgida.<\/p>\n<p>La actividad, que tuvo una importante convocatoria, instancia donde llegaron vecinos de varios sectores de la comuna, se realiz\u00f3 en la villa Los \u00c1lamos y ten\u00eda como objetivo entregar diversas herramientas a los pobladores para mejorar las relaciones entre ellos y as\u00ed resolver de mejor manera los conflictos que se puedan generar al interior de estos sectores, lo que redundar\u00eda en que las personas puedan sentirse parte del barrio en que viven.<\/p>\n<p>Para conocer en detalle estos aspectos, fueron invitados tres especialistas en estos temas, todos con una destacada trayectoria nacional e internacional.<\/p>\n<p>Ellos abordaron variadas tem\u00e1ticas, ya que la variedad de sus profesiones permitieron analizar estos temas desde distintas miradas, aunque todas giraron en torno a la prevenci\u00f3n de la delincuencia y la violencia.<\/p>\n<p>Franz Vanderschuren analiz\u00f3 el tema \u2018Cultura de la Prevenci\u00f3n\u2019, instancia en que explic\u00f3 qu\u00e9 es la prevenci\u00f3n y por qu\u00e9 ese aspecto constituye un elemento de cohesi\u00f3n social.<\/p>\n<p>Durante su intervenci\u00f3n dijo que la prevenci\u00f3n une a los vecinos, \u00abporque si no nos ponemos de acuerdo para prevenir lo que puede ser un crimen, los delitos o la violencia, es muy dif\u00edcil que la gente se mantenga unida, por ello es un deber hacer la prevenci\u00f3n\u00bb.<\/p>\n<p>Adem\u00e1s explic\u00f3 que se debe hacer un diagn\u00f3stico de lo que son los delitos, sus causas y a partir de ah\u00ed se define, con la gente, lo que es un plan de acci\u00f3n para trabajar en ese tema.<\/p>\n<p>En tanto Rosa Mar\u00eda Olave desarroll\u00f3 el tema \u2018Conflictos Vecinales\u2019, y desde ese \u00e1mbito se\u00f1al\u00f3 que es importante poder abordar los conflictos a trav\u00e9s de una serie de estrategias para prevenir estas situaciones.<\/p>\n<p>\u00abCreo que el \u00e1mbito de la resoluci\u00f3n de conflictos es un espacio para que las personas puedan aprender a dialogar, aprender a entenderse y poder establecer ciertos acuerdos, en base a las diferencias que se establecen por cualquier motivo y creo que el desaf\u00edo es c\u00f3mo desarrollar una cultura de m\u00e1s di\u00e1logo, una cultura que implique poder dialogar sobre esas diferencias, podamos generar el espacio para que el otro entienda la perspectiva de cada cual\u00bb.<\/p>\n<p>Por su parte Ezio Mmosciatti abord\u00f3 el tema \u2018Identidad Barrial\u2019, y en ese sentido explic\u00f3 que los barrios no son tan distintos a las personas, tienen una identidad y ella se constituye por distintos factores, los que tienen que ver con su gen\u00e9tica, su origen, con su historia, con lo que quiere ser el barrio y con lo que se proyecta en relaci\u00f3n a lo que son las comunidades.<\/p>\n<p>\u00abPorque un barrio se puede considerar muy bonito y muy tranquilo, pero si el resto de la sociedad lo estigmatiza, finalmente ah\u00ed va a haber un roce y eso va a necesariamente influir en su identidad, por eso hay una serie de factores que inciden en la identidad del barrio, como inciden en nuestras propias identidades\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vecinos conocieron distintas estrategias de asociatividad para mejorar la relaci\u00f3n entre ellos y superar conflictos que se puedan generar en los barrios a trav\u00e9s de una actividad organizada por la Junta de&#8230;<\/p>\n","protected":false},"author":482,"featured_media":12861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-12860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/vecinos-participantes-1.jpg?fit=600%2C450&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=12860"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/12861"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=12860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=12860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=12860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}