{"id":12952,"date":"2012-01-18T08:22:58","date_gmt":"2012-01-18T12:22:58","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=12952"},"modified":"2012-01-18T08:22:58","modified_gmt":"2012-01-18T12:22:58","slug":"nuevamente-y-por-cuarta-vez-en-15-dias-entran-a-robar-en-hogar-de-cristo","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/nuevamente-y-por-cuarta-vez-en-15-dias-entran-a-robar-en-hogar-de-cristo\/","title":{"rendered":"Nuevamente y por cuarta vez en 15 d\u00edas entran a robar en Hogar de Cristo"},"content":{"rendered":"<figure id=\"attachment_12953\" aria-describedby=\"caption-attachment-12953\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/12952\/robo-hogar-de-cristo-7\" rel=\"attachment wp-att-12953\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12953\" title=\"robo hogar de cristo (7)\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/robo-hogar-de-cristo-7.jpg?resize=600%2C403\" alt=\"\" width=\"600\" height=\"403\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/robo-hogar-de-cristo-7.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/robo-hogar-de-cristo-7.jpg?resize=200%2C134&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/robo-hogar-de-cristo-7.jpg?resize=300%2C201&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/robo-hogar-de-cristo-7.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/robo-hogar-de-cristo-7.jpg?resize=400%2C268&amp;ssl=1 400w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-12953\" class=\"wp-caption-text\">Por este forado ingresaron los antisociales que robaron una importante cantidad de mercader\u00eda.<\/figcaption><\/figure>\n<ul>\n<li><strong>Los antisociales ingresaron por un forado que hicieron en una de las puertas para robar mercader\u00eda.<\/strong><\/li>\n<\/ul>\n<p>Por cuarta vez en lo que va del mes de enero, desconocidos ingresaron a la sede del Hogar de Cristo en San Felipe y robaron una importante cantidad de mercader\u00eda que se utiliza para preparar las comidas de los abuelitos que llegan d\u00eda a d\u00eda hasta el lugar.<\/p>\n<p>El hecho qued\u00f3 al descubierto en la ma\u00f1ana del lunes reci\u00e9n pasado, cuando la directora del hogar, Andrea Quiroz, lleg\u00f3 hasta las dependencias y se encontr\u00f3 con un forado que los delincuentes hab\u00edan hecho en una de las puertas que dan hacia el patio de la construcci\u00f3n.<\/p>\n<p>Ante esta situaci\u00f3n un sentimiento de rabia e impotencia sinti\u00f3 la directora, ya que esta era la cuarta vez que entraban a robar, y lo que m\u00e1s la sorprende es que los delincuentes se dirigen a lugares espec\u00edficos donde se encuentra la mercader\u00eda. De hecho en este \u00faltimo robo, los sujetos recorrieron gran parte de las instalaciones, hasta llegar donde estaba guardada la comida, lo que hace pensar a Quiroz que se trata de sujetos que act\u00faan \u2018dateados\u2019.<\/p>\n<p>\u00abEllos llegan justo donde tienen que llegar, hacen tira justo lo que tienen que hacer tira, igual es complejo pensar que no estuvieran \u2018dateados\u2019\u00bb.<\/p>\n<p>Esta vez, a diferencia de la primera oportunidad en que se llevaron un triciclo que ten\u00eda el Hogar, sustrajeron s\u00f3lo comida, entre la que se cuentan cajas con aceite, az\u00facar, harina, es decir dejaron el lugar absolutamente desabastecido.<\/p>\n<p>Lo m\u00e1s complejo para el Hogar de Cristo es que con la realidad que viven actualmente, implementar medidas de seguridad se hace muy dif\u00edcil, ya que no existe presupuesto para esos fines.<\/p>\n<p>\u00abDentro de lo que es el presupuesto mensual de nosotros, tenemos estipulado 10 mil pesos mensuales para seguridad, y eso no abastece lo que realmente necesitamos. Vamos a tener que sacar plata de donde no hay para cambiar puertas, lo que ellos van haciendo tira, nosotros vamos ordenando y en realidad hoy d\u00eda (ayer) es martes y las condiciones no est\u00e1n todav\u00eda para hacerlo\u00bb, explica Quiroz.<\/p>\n<p>La directora del establecimiento interpuso nuevamente la denuncia en la Polic\u00eda de Investigaciones, tal como en los anteriores robos, y el martes estuvo en la Fiscal\u00eda para ver el avance del proceso, pero constat\u00f3 que la investigaci\u00f3n no ha tenido mucho desarrollo, ya que no existen evidencias ni pistas de los delincuentes.<\/p>\n<p>\u00abNo hay mucho avance, de hecho no creemos que lleguen a encontrar algo, porque no hay muchas pruebas, no hay ning\u00fan imputado en la causa\u00bb.<\/p>\n<p>Quiroz avalu\u00f3 la mercader\u00eda que se llevaron en alrededor de 400 mil pesos, una suma que ella reconoce que puede ser baja, pero explica que el da\u00f1o al patrimonio del edificio es m\u00e1s elevado.<\/p>\n<p>\u00abNos est\u00e1n haciendo tira puertas que son antiguas, esas cosas son s\u00faper caras, es dif\u00edcil poner la misma calidad de lo que est\u00e1n haciendo tira\u00bb.<\/p>\n<p>La situaci\u00f3n tiene a la directora bastante afectada, por eso hizo un llamado a los empresarios de la zona y a la comunidad en general a que se sensibilicen y puedan ayudar al Hogar de Cristo, ya que todav\u00eda se mantiene atendiendo a 28 abuelitos, los que llegan todos los d\u00edas a almorzar, tomar once y cenar. Ellos pasan toda la tarde en el lugar, asistiendo a talleres o simplemente haci\u00e9ndose compa\u00f1\u00eda, para luego volver a sus hogares, que muchas veces es s\u00f3lo una pieza que logran arrendar en las inmediaciones.<\/p>\n<p>\u00abSon 28 abuelitos que vienen todos los d\u00edas y est\u00e1n completamente focalizados, no son personas que no les corresponda estar ac\u00e1, hay personas completamente que est\u00e1n dentro del perfil de usuario que tiene el Hogar de Cristo, y son de la comuna, entonces no podemos cerrar los ojitos y pensar que no pasa nada\u00bb, sostuvo Quiroz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los antisociales ingresaron por un forado que hicieron en una de las puertas para robar mercader\u00eda. Por cuarta vez en lo que va del mes de enero, desconocidos ingresaron a la sede&#8230;<\/p>\n","protected":false},"author":482,"featured_media":12953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-12952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/robo-hogar-de-cristo-7.jpg?fit=600%2C403&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=12952"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/12953"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=12952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=12952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=12952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}