{"id":12968,"date":"2012-01-19T08:21:20","date_gmt":"2012-01-19T12:21:20","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=12968"},"modified":"2012-01-19T08:21:20","modified_gmt":"2012-01-19T12:21:20","slug":"unos-90-ninos-de-putaendo-viajaron-a-campamento-escolar-de-verano","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/unos-90-ninos-de-putaendo-viajaron-a-campamento-escolar-de-verano\/","title":{"rendered":"Unos 90 ni\u00f1os de Putaendo viajaron a campamento escolar de verano"},"content":{"rendered":"<figure id=\"attachment_12969\" aria-describedby=\"caption-attachment-12969\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/12968\/campamento-escolar\" rel=\"attachment wp-att-12969\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12969\" title=\"campamento escolar\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-escolar.jpg?resize=600%2C403\" alt=\"\" width=\"600\" height=\"403\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-escolar.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-escolar.jpg?resize=200%2C134&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-escolar.jpg?resize=300%2C201&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-escolar.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-escolar.jpg?resize=400%2C268&amp;ssl=1 400w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-12969\" class=\"wp-caption-text\">Familiares y amigos despiden a los ni\u00f1os que participan de este campamento escolar.<\/figcaption><\/figure>\n<p><strong>PUTAENDO.-<\/strong> Con todas las ganas y el entusiasmo de vivir una m\u00e1gica aventura como la que entrega un campamento de verano, cerca de 90 ni\u00f1os de distintos puntos de la comuna viajaron la ma\u00f1ana de este martes a la ciudad de Graneros.<\/p>\n<p>Los peque\u00f1os estudiantes de los distintos establecimientos educacionales, beneficiados por la Junaeb, compartir\u00e1n y disfrutar\u00e1n diferentes actividades recreativas en este primer campeonato escolar para j\u00f3venes de 8 a 13 y 14 a 18 a\u00f1os, ocasi\u00f3n donde los peque\u00f1os se dividieron en dos grupos, viajando el primero de ellos hasta la ciudad de Graneros y otros hasta el sector de Picarqu\u00edn.<\/p>\n<p>Los estudiantes fueron despedidos por familiares y amigos, quienes entusiasmados por esta hermosa experiencia les desearon mucho \u00e9xito en su viaje que se extender\u00e1 hasta el 25 de enero del presente a\u00f1o.<\/p>\n<p>Los ni\u00f1os y j\u00f3venes van a cargo de funcionarios del \u00e1rea de Educaci\u00f3n de la Municipalidad de Putaendo, cuyo viaje se enmarca dentro del proyecto denominado \u2018Campamentos Escolares\u2019, el que contempla un segundo viaje desde el 30 de enero al 6 de febrero, cuyo campamento se realizar\u00e1 en el sector de Con Con.<\/p>\n<p><strong>Patricio Gallardo M.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUTAENDO.- Con todas las ganas y el entusiasmo de vivir una m\u00e1gica aventura como la que entrega un campamento de verano, cerca de 90 ni\u00f1os de distintos puntos de la comuna viajaron&#8230;<\/p>\n","protected":false},"author":482,"featured_media":12969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-12968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-escolar.jpg?fit=600%2C403&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=12968"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/12968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/12969"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=12968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=12968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=12968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}