{"id":13034,"date":"2012-01-20T08:20:29","date_gmt":"2012-01-20T12:20:29","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=13034"},"modified":"2012-01-20T08:20:29","modified_gmt":"2012-01-20T12:20:29","slug":"despues-de-mas-de-dos-decadas-este-sabado-vuelve-la-chaya-a-san-felipe","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/despues-de-mas-de-dos-decadas-este-sabado-vuelve-la-chaya-a-san-felipe\/","title":{"rendered":"Despu\u00e9s de m\u00e1s de dos d\u00e9cadas este s\u00e1bado vuelve la Chaya a San Felipe"},"content":{"rendered":"<figure id=\"attachment_13035\" aria-describedby=\"caption-attachment-13035\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/13034\/jaime-amar-11\" rel=\"attachment wp-att-13035\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13035\" title=\"jaime amar\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/jaime-amar-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/jaime-amar.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/jaime-amar.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/jaime-amar.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/jaime-amar.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/jaime-amar.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-13035\" class=\"wp-caption-text\">El Alcalde Jaime Amar confirm\u00f3 la parrilla de artistas que estar\u00e1n presentes en una nueva versi\u00f3n, luego de muchos a\u00f1os, de la Chaya en San Felipe.<\/figcaption><\/figure>\n<p>Despu\u00e9s de varias d\u00e9cadas, este s\u00e1bado vuelve el carnaval de la Chaya a San Felipe.<\/p>\n<p>La actividad se desarrollar\u00e1 desde este s\u00e1bado 21 hasta el s\u00e1bado 28 de enero, en la plaza de Armas de la comuna, la que contar\u00e1 con la presencia de destacados artistas locales y nacionales.<\/p>\n<p>La animaci\u00f3n durante todos los d\u00edas del carnaval estar\u00e1 a cargo del conocido Nelson Sagredo, mientras que la orquesta estable de esta fiesta ser\u00e1 Los Charros del Valle.<\/p>\n<p>La jornada del s\u00e1bado comenzar\u00e1 a las 21:30 horas con la presentaci\u00f3n de Los Wachiturros, Macho y El Rey (del programa Yingo), , adem\u00e1s de los grandes \u00e9xitos de Rigeo en vivo.<\/p>\n<p>Esa noche adem\u00e1s los asistentes podr\u00e1n participar de concursos con llamativos premios y conocer\u00e1n a las candidatas a reina de San Felipe 2012.<\/p>\n<p>Al otro d\u00eda en tanto la jornada ser\u00e1 de fiesta ranchera, y para ello est\u00e1n invitados los artistas locales y nacionales de esta corriente musical.<\/p>\n<p>El lunes ser\u00e1 la fiesta Remember con m\u00fasica del recuerdo, donde se presentar\u00e1 el show de Luis Dimas y Zalo Reyes.<\/p>\n<p>Para el martes estar\u00e1 preparada la Noche Retro, con m\u00fasica de los 70 y 80, jornada que contar\u00e1 con bandas que hacen tributos a esta \u00e9poca.<\/p>\n<p>El humor no estar\u00e1 ausente en el carnaval, por eso el mi\u00e9rcoles se realizar\u00e1 el carnaval del humor, con la presentaci\u00f3n de los atletas de la risa en vivo.<\/p>\n<p>El jueves 26 se realizar\u00e1 teatro al aire libre, y para ese d\u00eda se espera la presentaci\u00f3n de la obra \u2018\u00bfQui\u00e9n se queda con mam\u00e1?\u2019.<\/p>\n<p>El viernes 27 el carnaval recibir\u00e1 la presencia de los mejores dobles que existen en el pa\u00eds de los grandes artistas nacionales e internacionales.<\/p>\n<p>El carnaval culmina el pr\u00f3ximo s\u00e1bado 28 con el baile de Clausura, jornada en que se presentar\u00e1 en vivo el Grupo Red.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de varias d\u00e9cadas, este s\u00e1bado vuelve el carnaval de la Chaya a San Felipe. La actividad se desarrollar\u00e1 desde este s\u00e1bado 21 hasta el s\u00e1bado 28 de enero, en la plaza&#8230;<\/p>\n","protected":false},"author":482,"featured_media":13035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-13034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/jaime-amar.jpg?fit=600%2C450&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=13034"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/13035"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=13034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=13034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=13034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}