{"id":13195,"date":"2012-01-25T02:54:08","date_gmt":"2012-01-25T06:54:08","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=13195"},"modified":"2012-01-25T02:54:08","modified_gmt":"2012-01-25T06:54:08","slug":"alumnos-municipalizados-participan-en-campamento-de-matematica-en-la-upla","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/alumnos-municipalizados-participan-en-campamento-de-matematica-en-la-upla\/","title":{"rendered":"Alumnos municipalizados participan en Campamento de Matem\u00e1tica en la UPLA"},"content":{"rendered":"<figure id=\"attachment_13196\" aria-describedby=\"caption-attachment-13196\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/13195\/campamento-3\" rel=\"attachment wp-att-13196\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13196\" title=\"campamento 3\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-3.jpg?resize=600%2C416\" alt=\"\" width=\"600\" height=\"416\" \/><\/a><figcaption id=\"caption-attachment-13196\" class=\"wp-caption-text\">Alumnos de diversos establecimientos de ense\u00f1anza municipal participaron del Campamento de Matem\u00e1tica realizado en el Campus San Felipe de la Upla.<\/figcaption><\/figure>\n<p>Un grupo de 18 estudiantes de Primero a Tercero Medio de establecimientos del sistema de educaci\u00f3n municipal, particip\u00f3 en el \u201cCampamento de Matem\u00e1ticas\u201d, realizado en el Campus San Felipe de la Universidad de Playa Ancha.<\/p>\n<p>La actividad acad\u00e9mica estuvo a cargo de la docente Ruth Galindo Navarro, Directora del Departamento de Educaci\u00f3n y Pedagog\u00eda, y su objetivo fue acercar a los estudiantes a la ciencia, a la matem\u00e1tica y a la vez permitirles conocer la Universidad: \u00abEste encuentro tuvo por finalidad trabajar, a trav\u00e9s de visiones participativas relacionadas con el aprendizaje y articulaci\u00f3n de las ciencias, en un contexto libre, donde los alumnos desarrollaron m\u00f3dulos de aprendizaje de matem\u00e1tica y de computaci\u00f3n, integrados a deporte y recreaci\u00f3n\u00bb, explic\u00f3 la docente.<\/p>\n<p>Tambi\u00e9n participaron acad\u00e9micos y ayudantes de los distintos departamentos disciplinarios del Campus, que atendieron a estudiantes seleccionados por los liceos dependientes de la Daem de San Felipe, y adem\u00e1s se cont\u00f3 con el auspicio de Libroteca Saavedra, Farmacia Prat, Conservera Penztke y la Ilustre Municipalidad de San Felipe.<\/p>\n<p>Galindo se mostr\u00f3 satisfecha por el entusiasmo que demostraron los estudiantes de Ense\u00f1anza Media, que pudieron aprender en un ambiente recreativo: \u00abEste campamento se desarroll\u00f3 durante tres d\u00edas, desde las 9.00 hasta las 14.00 horas, y esperamos seguir replicando esta experiencia cada a\u00f1o, con el objetivo de vincular el quehacer universitario de nuestra casa de estudios con el nivel medio educativo, aportando efectivamente a la formaci\u00f3n integral de los j\u00f3venes del Valle de Aconcagua\u00bb, se\u00f1al\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de 18 estudiantes de Primero a Tercero Medio de establecimientos del sistema de educaci\u00f3n municipal, particip\u00f3 en el \u201cCampamento de Matem\u00e1ticas\u201d, realizado en el Campus San Felipe de la Universidad&#8230;<\/p>\n","protected":false},"author":482,"featured_media":13196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-13195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/01\/campamento-3.jpg?fit=600%2C416&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=13195"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/13196"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=13195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=13195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=13195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}