{"id":13523,"date":"2012-02-02T11:00:24","date_gmt":"2012-02-02T14:00:24","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=13523"},"modified":"2012-02-02T11:00:24","modified_gmt":"2012-02-02T14:00:24","slug":"vecinos-de-jahuel-y-santa-filomena-piden-mas-proteccion-a-las-autoridades","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/vecinos-de-jahuel-y-santa-filomena-piden-mas-proteccion-a-las-autoridades\/","title":{"rendered":"Vecinos de Jahuel y Santa Filomena piden m\u00e1s protecci\u00f3n a las autoridades"},"content":{"rendered":"<figure id=\"attachment_13524\" aria-describedby=\"caption-attachment-13524\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/13523\/alcalde-se-reunio\" rel=\"attachment wp-att-13524\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13524\" title=\"alcalde se reunio\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/alcalde-se-reunio.jpg?resize=600%2C450\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/alcalde-se-reunio.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/alcalde-se-reunio.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/alcalde-se-reunio.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/alcalde-se-reunio.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/alcalde-se-reunio.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-13524\" class=\"wp-caption-text\">El edil en su exposici\u00f3n respald\u00f3 lo se\u00f1alado por la Gobernadora Patricia Boffa hace d\u00edas, en el sentido de que a\u00fan no hay autorizaci\u00f3n para la empresa para reiniciar las explotaciones. <\/figcaption><\/figure>\n<p><strong>SANTA MAR\u00cdA.-<\/strong> En la sede de la Cooperativa de Agua Potable Santa Filomena se llev\u00f3 a cabo una importante reuni\u00f3n para tratar la situaci\u00f3n de las faenas mineras en Jahuel. Asistieron a esta actividad el Alcalde Claudio Zurita, los concejales de la comuna, el Consejero Regional Eduardo Le\u00f3n \u00a0y representantes de las diferentes organizaciones y comunidades afectadas en estas actividades.<\/p>\n<p>La inquietud de los vecinos se debe principalmente a versiones que indican que los trabajos se podr\u00edan reiniciar. El Edil en su exposici\u00f3n manifest\u00f3 que a\u00fan no hay nada concreto y se respald\u00f3 en lo se\u00f1alado por la Gobernadora Patricia Boffa hace d\u00edas, en el sentido de que a\u00fan no hay autorizaci\u00f3n para la empresa para reiniciar las explotaciones.\u00a0<\/p>\n<p><strong>TODO EL MUNDO ALERTA<\/strong><\/p>\n<p>Por su parte, as\u00ed como la comunidad de Jahuel y sectores aleda\u00f1os se encuentran en estado de alerta, el Alcalde Zurita destac\u00f3 que tanto \u00e9l como los Concejales y el municipio en general,\u00a0 siguen agotando instancias para proteger a los vecinos y vecinas que han visto afectada su calidad de vida con estas actividades econ\u00f3micas. \u00a0Entre otras cosas, se est\u00e1 coordinando en conjunto con la Gobernaci\u00f3n una reuni\u00f3n con Sernageomin y CONAF, para examinar la situaci\u00f3n de los permisos y las especies nativas que rodean la zona intervenida. Lo anterior se suma a todas las reuniones sostenidas con personeros de Gobierno, llegando incluso una delegaci\u00f3n a exponer ante la Comisi\u00f3n de Medio Ambiente de la C\u00e1mara en Valpara\u00edso.<\/p>\n<p>Lo que m\u00e1s preocupa a los vecinos y a las autoridades en este caso, es el impacto ambiental y el da\u00f1o ecol\u00f3gico que tienen estas labores, esto se suma a la situaci\u00f3n de la sequ\u00eda que afecta a la zona del sector alto de Santa Mar\u00eda, que adem\u00e1s ha visto disminuir el agua proveniente de las vertientes desde el sector donde se ubican las mineras.<\/p>\n<p>Finalmente el alcalde se\u00f1al\u00f3 que se est\u00e1 trabajando en un proyecto ecol\u00f3gico para que se declare al sector de El Saino como Santuario de la Naturaleza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTA MAR\u00cdA.- En la sede de la Cooperativa de Agua Potable Santa Filomena se llev\u00f3 a cabo una importante reuni\u00f3n para tratar la situaci\u00f3n de las faenas mineras en Jahuel. Asistieron a&#8230;<\/p>\n","protected":false},"author":482,"featured_media":13524,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-13523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/alcalde-se-reunio.jpg?fit=600%2C450&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=13523"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/13524"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=13523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=13523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=13523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}