{"id":13592,"date":"2012-02-03T09:46:26","date_gmt":"2012-02-03T12:46:26","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=13592"},"modified":"2012-02-03T09:46:26","modified_gmt":"2012-02-03T12:46:26","slug":"mario-guerrero-pondra-la-cuota-de-romanticismo-en-noche-inaugural-del-festival","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/mario-guerrero-pondra-la-cuota-de-romanticismo-en-noche-inaugural-del-festival\/","title":{"rendered":"Mario Guerrero pondr\u00e1 la cuota de romanticismo en noche inaugural del festival"},"content":{"rendered":"<figure id=\"attachment_13593\" aria-describedby=\"caption-attachment-13593\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/13592\/mario-guerrero-4\" rel=\"attachment wp-att-13593\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13593\" title=\"mario guerrero (4)\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/mario-guerrero-4-300x272.jpg?resize=300%2C272\" alt=\"\" width=\"300\" height=\"272\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/mario-guerrero-4.jpg?resize=300%2C272&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/mario-guerrero-4.jpg?resize=165%2C150&amp;ssl=1 165w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/mario-guerrero-4.jpg?resize=150%2C136&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/mario-guerrero-4.jpg?resize=400%2C362&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/mario-guerrero-4.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-13593\" class=\"wp-caption-text\">Mario Guerrero traer\u00e1 sus grandes \u00e9xitos y los asistentes podr\u00e1n conocer las canciones de su nuevo \u00e1lbum.<\/figcaption><\/figure>\n<ul>\n<li><strong>Presentar\u00e1 sus grandes \u00e9xitos y sus fan\u00e1ticos podr\u00e1n conocer las canciones de su nuevo \u00e1lbum.<\/strong><\/li>\n<\/ul>\n<p>Despu\u00e9s de un mes de intenso trabajo, donde el cantante y compositor Mario Guerrero estuvo dedicado completamente a su nuevo disco, los asistentes a la XIII versi\u00f3n del Festival Palmenia Pizarro podr\u00e1n disfrutar nuevamente de una de sus presentaciones.<\/p>\n<p>Y eso porque el cantante es uno de los confirmados para el tradicional evento art\u00edstico del verano en San Felipe.<\/p>\n<p>Mario se presentar\u00e1 hoy viernes en la cancha del Estadio Municipal con un show que estar\u00e1 cargado de romanticismo, tal como \u00e9l lo adelant\u00f3 en una conversaci\u00f3n telef\u00f3nica sostenida en exclusiva con Diario El Trabajo desde Santiago.<\/p>\n<p>El cantautor record\u00f3 presentaciones anteriores en la comuna y destac\u00f3 la realizaci\u00f3n del festival, donde se re\u00fane una importante cantidad de personas.<\/p>\n<p>\u00abHace mucho tiempo estuve en el Festival Palmenia Pizarro, es un gran festival, donde se junta bastante gente, entonces volver a encontrarme con el festival, donde la puesta en escena es con una banda, con m\u00fasicos, y ha pasado bastante tiempo, han pasado canciones que han sonado y que siguen estando presente en las radios, entonces va a ser bonito escuchar cantar a todo San Felipe y sus alrededores conmigo, todas las canciones rom\u00e1nticas. Yo soy el artista que coloca la cuota de romanticismo esa noche\u00bb.<\/p>\n<p>Sobre la actuaci\u00f3n adelant\u00f3 que los asistentes podr\u00e1n disfrutar de sus grandes \u00e9xitos y tambi\u00e9n podr\u00e1n conocer algunas de las canciones que forman parte de su \u00faltimo \u00e1lbum.<\/p>\n<p>\u00abNo podr\u00eda dejar ning\u00fan tema afuera, y espero tener la oportunidad de poder presentar mi \u00faltimo sencillo dentro de este show, y tampoco puedo dejar afuera Te amar\u00e9, que es un \u00e9xito importante dentro de mi carrera\u00bb, dijo el cantante.<\/p>\n<p>Enero ha sido un mes de mucho trabajo para el artista, ya que estuvo completamente dedicado a la creaci\u00f3n de su nueva producci\u00f3n, un disco que est\u00e1 pronto a salir.<\/p>\n<p>Asimismo durante este tiempo estuvo trabajando en la formaci\u00f3n de un equipo multidisciplinario, que estar\u00e1 enfocado especialmente en internacionalizar su carrera.<\/p>\n<p>\u00abHe tenido la oportunidad de contar con grandes personas, grandes profesionales, y donde estamos trabajando en conjunto para desarrollar mi carrera tanto ac\u00e1 como en el extranjero. Nos interesan mucho mercados como Per\u00fa, Argentina, sobre todo que son muy rom\u00e1nticos en la parte del sur. A m\u00ed me encanta Colombia y por mi parte, como compositor, seguir potenciando mi relaci\u00f3n con los grandes compositores de la m\u00fasica mexicana\u00bb.<\/p>\n<p>Este nuevo disco nuevamente trae mucho romanticismo, bastante amor y desamor, cuenta Mario, es decir es una producci\u00f3n que tendr\u00e1 bastante variedad.<\/p>\n<p>\u00abEs un disco que tiene de todo, una suavidad fresca, una suavidad de lo que suena afuera, donde se logra intimidad con una pura guitarra y un solo piano, me gusta eso, no sobresaturar con tanta producci\u00f3n\u00bb.<\/p>\n<p>Durante el verano adem\u00e1s el artista estar\u00e1 presente en varios festivales a lo largo de todo el pa\u00eds, donde destaca el evento Viva Dichato, con el que se busca volver a potenciar el turismo en esa zona tan afectada por el terremoto del 2010.<\/p>\n<p>La fiesta del verano en San Felipe finalmente lleg\u00f3 y la invitaci\u00f3n a disfrutar de la buena m\u00fasica y del humor la realiz\u00f3 Mario Guerreo especialmente a todos los vecinos de la comuna.<\/p>\n<p>\u00abRom\u00e1nticos y rom\u00e1nticas no pueden faltar, si quieren cantarle al coraz\u00f3n, al amor, si quieren invitar a su pareja, este es el lugar indicado para poder cantarle al o\u00eddo y disfrutar de m\u00fasica rom\u00e1ntica\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentar\u00e1 sus grandes \u00e9xitos y sus fan\u00e1ticos podr\u00e1n conocer las canciones de su nuevo \u00e1lbum. Despu\u00e9s de un mes de intenso trabajo, donde el cantante y compositor Mario Guerrero estuvo dedicado completamente&#8230;<\/p>\n","protected":false},"author":482,"featured_media":13593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-13592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/mario-guerrero-4.jpg?fit=600%2C544&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=13592"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/13593"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=13592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=13592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=13592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}