{"id":13629,"date":"2012-02-06T09:45:34","date_gmt":"2012-02-06T12:45:34","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=13629"},"modified":"2012-02-06T09:45:34","modified_gmt":"2012-02-06T12:45:34","slug":"cancion-%e2%80%9cmanos-de-mi-pueblo%e2%80%9d-gano-xiii-festival-palmenia-pizarro","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/cancion-%e2%80%9cmanos-de-mi-pueblo%e2%80%9d-gano-xiii-festival-palmenia-pizarro\/","title":{"rendered":"Canci\u00f3n \u201cManos de mi pueblo\u201d gan\u00f3 XIII Festival Palmenia Pizarro"},"content":{"rendered":"<figure id=\"attachment_13630\" aria-describedby=\"caption-attachment-13630\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/13629\/miguel-cadiz\" rel=\"attachment wp-att-13630\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13630\" title=\"miguel cadiz\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/miguel-cadiz-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/miguel-cadiz.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/miguel-cadiz.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/miguel-cadiz.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/miguel-cadiz.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/miguel-cadiz.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-13630\" class=\"wp-caption-text\">Con \u201cManos de mi pueblo\u201d, Miguel C\u00e1diz se llev\u00f3 el primer lugar del XIII Festival de la Canci\u00f3n.<\/figcaption><\/figure>\n<ul>\n<li><strong>Evento cautiv\u00f3 a los asistentes con destacados artistas nacionales y que no estuvo exento de problemas<\/strong><\/li>\n<\/ul>\n<p>Sylvia Vergara &#8211; <a href=\"mailto:svergara@eltrabajo.cl\">svergara@eltrabajo.cl<\/a><\/p>\n<p>Miguel C\u00e1diz, con el tema \u201cManos de mi pueblo\u201d fue el Ganador del XIII Festival de la Canci\u00f3n Palmenia Pizarro, una versi\u00f3n que destac\u00f3 por el nivel de los participantes y de los artistas invitados, pero que no estuvo exenta de problemas, protagonizados especialmente por los guardias de seguridad y por la falta de preparaci\u00f3n de sus animadores.<\/p>\n<p>La primera noche del festival comenz\u00f3 pasadas las 21 horas, cuando los animadores del festival, nuevamente Pablo Schilling y Mar\u00eda Eugenia Larra\u00edn, saludaron al p\u00fablico y comenzaron a presentar a los artistas. Esa noche la animadora fue pifiada, generando la incomodidad de la modelo.<\/p>\n<p>El impasse fue superado con la presentaci\u00f3n del Grupo Dixon, los artistas locales del festival, y quienes presentaron un show s\u00f3lido, tal como ocurre en todas sus actuaciones.<\/p>\n<p><strong>BUENA COMPETENCIA<\/strong><\/p>\n<p>Luego fue el turno de la competencia, donde destacados cantautores compitieron por ser la canci\u00f3n ganadora del certamen.<\/p>\n<p>M\u00e1s tarde, subieron al escenario \u2018Macho y El Rey\u2019, quienes conquistaron al p\u00fablico juvenil que se dio cita en el recinto deportivo, a quienes hicieron bailar y cantar durante toda su presentaci\u00f3n.<\/p>\n<p>Y tal como lo hab\u00eda anunciado, Mario Guerrero puso el romanticismo en la fr\u00eda noche sanfelipe\u00f1a con sus grandes \u00e9xitos y nuevas canciones que cautivaron a los asistentes, estos llegaron en gran cantidad a verlo actuar.<\/p>\n<p>La primera noche del festival termin\u00f3 con la presentaci\u00f3n de la Sonora Bar\u00f3n. Luego de m\u00e1s de diez minutos que los t\u00e9cnicos demoraron en instalar los equipos y a la improvisaci\u00f3n de los animadores, el p\u00fablico al parecer comenz\u00f3 a aburrirse y s\u00f3lo lo m\u00e1s fan\u00e1ticos siguieron fiel a la banda.<\/p>\n<p>El grupo hizo bailar a los pocos asistentes que quedaban en el Municipal, culminando su show cerca de las 2 de la ma\u00f1ana.<\/p>\n<p>La segunda noche de festival promet\u00eda hacer bailar y cantar a los asistentes, adem\u00e1s de sacar m\u00e1s de alguna carcajada con la presentaci\u00f3n de \u201cPujillay\u201d.<\/p>\n<p>Ese d\u00eda destac\u00f3 la presencia en el escenario del Ballet Municipal de San Felipe, un grupo s\u00f3lido y que ha presentado sus coreograf\u00edas en variados escenarios.<\/p>\n<p>Nuevamente los animadores en el escenario y tal como la noche anterior, m\u00e1s lectura de tarjetas y mala improvisaci\u00f3n.<\/p>\n<p>Luego de saludar a los asistentes, presentaron al Grupo Natalino, quienes cantaron sus \u00e9xitos.<\/p>\n<p><strong>ENANITOS VERDES<\/strong><\/p>\n<p>Pero sin dudas, los m\u00e1s esperados eran los \u201cEnanitos Verdes\u201d, el grupo mendocino que encant\u00f3 al p\u00fablico con sus grandes \u00e9xitos.<\/p>\n<p>\u201cLamento Boliviano\u201d y \u201cTus viejas cartas\u201d fueron algunos de sus \u00e9xitos de todos los tiempos que fueron coreados por los miles de asistentes al Municipal, aunque muchos echaron de menos \u201cTe vi en un tren\u201d, otro de los cl\u00e1sicos del grupo.<\/p>\n<p>Actuaron por m\u00e1s de una hora y agradecieron al p\u00fablico que los acompa\u00f1\u00f3 en esta segunda jornada de festival.<\/p>\n<p>\u201cMientras Dios lo permita vamos a seguir tocando y mientras la gente nos responda como esta noche, \u00bfC\u00f3mo podr\u00edamos dejar de hacerlo?\u201d, se\u00f1alaron al bajar del escenario<\/p>\n<p><strong>EL GRAN GANADOR<\/strong><\/p>\n<p>La noche continu\u00f3 con la premiaci\u00f3n de la Canci\u00f3n Ganadora, trofeo que qued\u00f3 en manos de Miguel C\u00e1diz, el artista local agradeci\u00f3 el premio y se\u00f1al\u00f3 que su principal objetivo era entregar su mensaje.<\/p>\n<p>\u201cMuy contento, muy emocionado, jam\u00e1s imagin\u00e9 este momento, lo que m\u00e1s me tiene emocionado es el mensaje que quer\u00eda enviar, un mensaje de esperanza, decirle a todo el mundo que no importa como est\u00e9n de \u00e1nimo, que con sus propias manos somos capaces de expresar sentimientos, y ser solidarios\u201d.<\/p>\n<p>El premio lo dedic\u00f3 a toda la gente del Valle, los temporeros, las nanas, los trabajadores en general.<\/p>\n<p>Luego, fue el turno del Grupo humorista Pujillay, quienes sac\u00f3 m\u00e1s de una carcajada a los asistentes y cerca de las 2 de la madrugada, subi\u00f3 al escenario \u201cLa Noche\u201d, la agrupaci\u00f3n aconcag\u00fcina que hizo bailar a los asistentes con sus cumbias y fueron los encargados de cerrar la segunda noche y el Festival de la Canci\u00f3n.<\/p>\n<p><strong>DIF\u00cdCIL PARA LA PRENSA<\/strong><\/p>\n<p>Menci\u00f3n aparte merecen los guardias encargados de la seguridad del evento, quienes se encargaron de hacer, en todo momento, bastante dif\u00edcil el trabajo de la Prensa.<\/p>\n<p>Tal como ocurri\u00f3 el a\u00f1o pasado, la Prensa fue obligada a ubicarse en un sector, donde era imposible para los reporteros gr\u00e1ficos y camar\u00f3grafos captar las mejores im\u00e1genes, muchas de las cuales ser\u00edan exhibidas a nivel nacional.<\/p>\n<p>En varios momentos la situaci\u00f3n se volvi\u00f3 bastante desagradable, e incluso fue necesario que personal de Relaciones P\u00fablicas del municipio intercediera para que la gente de la Prensa pudiera hacer su trabajo.<\/p>\n<p>Sin embargo, con el correr de los minutos fue posible observar bastante gente sin credencial que se ubic\u00f3 cerca del escenario, ante el nulo accionar de los guardias, quienes los dejaron ubicarse en el lugar, sin colocar ning\u00fan l\u00edmite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento cautiv\u00f3 a los asistentes con destacados artistas nacionales y que no estuvo exento de problemas Sylvia Vergara &#8211; svergara@eltrabajo.cl Miguel C\u00e1diz, con el tema \u201cManos de mi pueblo\u201d fue el Ganador&#8230;<\/p>\n","protected":false},"author":482,"featured_media":13630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-13629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/miguel-cadiz.jpg?fit=600%2C450&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=13629"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/13630"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=13629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=13629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=13629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}