{"id":13641,"date":"2012-02-06T09:57:22","date_gmt":"2012-02-06T12:57:22","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=13641"},"modified":"2012-02-06T09:57:22","modified_gmt":"2012-02-06T12:57:22","slug":"sip-de-carabineros-detiene-a-dos-delincuentes-robando-en-un-automovil","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/sip-de-carabineros-detiene-a-dos-delincuentes-robando-en-un-automovil\/","title":{"rendered":"SIP de Carabineros detiene a dos delincuentes robando en un autom\u00f3vil"},"content":{"rendered":"<figure id=\"attachment_13642\" aria-describedby=\"caption-attachment-13642\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/archives\/13641\/detencion1\" rel=\"attachment wp-att-13642\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13642\" title=\"Detencion1\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/Detencion1.jpg?resize=600%2C450\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/Detencion1.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/Detencion1.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/Detencion1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/Detencion1.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/Detencion1.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-13642\" class=\"wp-caption-text\">\u2018El Guat\u00f3n Alex\u2019 fue capturado por la SIP de Carabineros.<\/figcaption><\/figure>\n<p>Personal de la Secci\u00f3n de Investigaci\u00f3n Policial (SIP) de Carabineros, logr\u00f3 la detenci\u00f3n de dos sujetos implicados en el robo de art\u00edculos de auto, hecho ocurrido el mi\u00e9rcoles reci\u00e9n pasado.<\/p>\n<p>El hecho ocurri\u00f3 en la comuna de Santa Mar\u00eda, cuando Cristi\u00e1n L.R., de 25 a\u00f1os de edad, dej\u00f3 su autom\u00f3vil estacionado cerca de la estaci\u00f3n de servicio Copec. Al regresar a buscar el veh\u00edculo se percat\u00f3 del robo de varias especies desde el interior del m\u00f3vil, entre las que se contaban la radio del veh\u00edculo, dos parlantes, adem\u00e1s de un amplificador y una bazuca marcha Kenwood, art\u00edculos que se encontraban en el interior del maletero.<\/p>\n<p><strong>\u2018EL GUAT\u00d3N ALEX\u2019<\/strong><\/p>\n<p>Un d\u00eda despu\u00e9s de ocurrido el hecho, el afectado recibi\u00f3 un llamado a su celular realizado por un sujeto que \u00e9l identific\u00f3 como el \u2018Guat\u00f3n Alex\u2019, quien le se\u00f1al\u00f3 que hasta su taller mec\u00e1nico le hab\u00edan ido a ofrecer un amplificador y una bazuca, art\u00edculos que manten\u00eda en su poder.<\/p>\n<p>De inmediato Cristi\u00e1n se traslad\u00f3 al taller mec\u00e1nico, donde reconoci\u00f3 los art\u00edculos como de su propiedad y que hab\u00edan sido robados el d\u00eda anterior.<\/p>\n<p>Ante esta situaci\u00f3n y viendo que el sujeto del taller mec\u00e1nico no le devolvi\u00f3 los art\u00edculos, ya que argument\u00f3 haber pagado por ellos, el afectado se dirigi\u00f3 hasta la tenencia de Santa Mar\u00eda, donde fue comunicado con personal de la SIP quienes adoptaron el procedimiento.<\/p>\n<p>Con todos los antecedentes informados por Cristi\u00e1n, el personal especializado de Carabineros comenz\u00f3 a realizar diligencias, en primer lugar, para identificar al sujeto se\u00f1alado por la v\u00edctima como el \u2018Guat\u00f3n Alex\u2019, quien result\u00f3 ser un individuo que mantiene un taller de vulcanizaci\u00f3n y reparaci\u00f3n de motocicletas en La Troya, por lo que el personal policial se traslado hasta ese lugar, no encontrando moradores, hecho que se repiti\u00f3 en varias oportunidades.<\/p>\n<p>Adem\u00e1s, seg\u00fan informaci\u00f3n entregada por colaboradores al personal de la SIP, se pudo establecer que un sujeto apodado \u2018El Johny\u2019 hab\u00eda visitado el taller del \u2018Guat\u00f3n Alex\u2019, por lo que se comenz\u00f3 a realizar diligencias tendientes a ubicar este nuevo sujeto, quien ya es conocido por la SIP al haber sido detenido anteriormente.<\/p>\n<p>Fue as\u00ed que el viernes, pasado el medio d\u00eda, en calle Chorrillos esquina Diego de Almagro, el personal de la SIP se percat\u00f3 de la presencia de \u2018El Johny\u2019, a quien se le efectu\u00f3 un control de identidad, encontrando en una mochila que portaba dos parlantes marca Pionner y una radio de veh\u00edculo de la misma marca. Los efectivos policiales le consultaron por la procedencia de los art\u00edculos, se\u00f1alando que los hab\u00eda comprado en la calle la noche anterior, por lo que fue trasladado hasta la unidad policial para verificar la procedencia de las especies.<\/p>\n<p>Asimismo al realizar un control de identidad al \u2018Guat\u00f3n Alex\u2019, quien finalmente fue ubicado en la cancha de San Alfonso, en el sector de La Troya, quien hizo entrega voluntaria de una \u2018bazuca\u2019 marca Kenwood y un amplificador, especies que manten\u00eda en su veh\u00edculo.<\/p>\n<p><strong>EVIDENCIAS<\/strong><\/p>\n<p>Todas las especies fueron exhibidas a la v\u00edctima del robo, quien las reconoci\u00f3 como de su propiedad, por lo que se procedi\u00f3 a la detenci\u00f3n de Jonathan Urbina Rebolledo, alias \u2018El Johny\u2019, y de Alex B\u00e1ez Cuadra, alias el \u2018Guat\u00f3n Alex\u2019.<\/p>\n<p>Cabe destacar que ambos imputados registran condenas por distintos delitos. En el caso de Jonathan Urbina, registra condenas desde el a\u00f1o 2004 por delitos de robo y receptaci\u00f3n, \u00e9sta \u00faltima ocurrida el a\u00f1o 2010, mientras que Alex B\u00e1ez registra condenas desde el a\u00f1o 2007 por el delito de tenencia de arma de fuego, el 2009 por tr\u00e1fico en peque\u00f1as cantidades y el a\u00f1o 2010 por receptaci\u00f3n y tr\u00e1fico il\u00edcito en peque\u00f1as cantidades.<\/p>\n<p>Los imputados fueron puestos a disposici\u00f3n del Tribunal de Garant\u00eda de San Felipe para el Control de Detenci\u00f3n que deb\u00eda realizarse el s\u00e1bado reci\u00e9n pasado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal de la Secci\u00f3n de Investigaci\u00f3n Policial (SIP) de Carabineros, logr\u00f3 la detenci\u00f3n de dos sujetos implicados en el robo de art\u00edculos de auto, hecho ocurrido el mi\u00e9rcoles reci\u00e9n pasado. El hecho&#8230;<\/p>\n","protected":false},"author":482,"featured_media":13642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-13641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2012\/02\/Detencion1.jpg?fit=600%2C450&ssl=1","_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=13641"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/13641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/13642"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=13641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=13641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=13641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}