{"id":2388,"date":"2011-08-03T19:06:05","date_gmt":"2011-08-03T19:06:05","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=2388"},"modified":"2011-08-03T19:06:05","modified_gmt":"2011-08-03T19:06:05","slug":"vecina-de-llay-llay-afectada-por-compleja-enfermedad-que-le-impide-moverse-3","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/vecina-de-llay-llay-afectada-por-compleja-enfermedad-que-le-impide-moverse-3\/","title":{"rendered":"Vecina de Llay Llay afectada por compleja enfermedad que le impide moverse"},"content":{"rendered":"<p>Realizar\u00e1n bingo a beneficio este s\u00e1badoEl pr\u00f3ximo s\u00e1bado 6 de agosto en la comuna de Llay Llay se realizar\u00e1 un bingo a beneficio de una de sus vecinas que sufre hace 5 a\u00f1os la enfermedad Esclerosis Lateral Amiotr\u00f3fica, conocida como ELA, y que se hizo m\u00e1s conocida ya que tambi\u00e9n afecta al c\u00e9lebre cient\u00edfico Stephen Hawking.   La gravedad de la enfermedad ha motivado a un grupo de amigas de Pamela Huerta a realizar distintas actividades para apoyarla en los gastos que debe realizar para conseguir distintos elementos que son esenciales para su tratamiento.Seg\u00fan cuenta Ana Fredes, Pamela present\u00f3 los primeros s\u00edntomas hace 5 a\u00f1os, pero s\u00f3lo hace 3 que tiene la confirmaci\u00f3n de que se trata de esta enfermedad y hace dos a\u00f1os que est\u00e1 declarada.\u00abNo est\u00e1 postrada en cama, todav\u00eda no llega a eso, pero con la enfermedad se le van muriendo los m\u00fasculos y las neuronas y no tiene movimiento en sus manos ni en sus piernas, s\u00f3lo mueve su cabeza, no habla y es muy poco lo que se le entiende\u00bb.Efectivamente  esta es una enfermedad degenerativa de tipo neuromuscular, por la cual unas c\u00e9lulas del sistema nervioso, llamadas motoneuronas, disminuyen gradualmente su funcionamiento y mueren, provocando una par\u00e1lisis muscular progresiva.Adem\u00e1s del bingo, sus amigos ya realizaron un campeonato de baby f\u00fatbol, el que tambi\u00e9n permiti\u00f3 recaudar recursos para comprar un respirador Dipack, que le hac\u00eda bastante falta a Pamela. Ahora la idea es reunir m\u00e1s recursos que permitan comprar las drogas que necesita la mujer, que tienen un valor de 800 mil pesos por frasco que consume en forma mensual y debe  ser encargado a Argentina, ya que en Chile no est\u00e1 disponible, adem\u00e1s de una cama antiescaras, ya que ella permanece todo el d\u00eda acostada en su cama.El bingo es en el Cuerpo de Bomberos de Llay Llay, a partir de las 19:30 horas, donde se sortear\u00e1n interesantes premios.La invitaci\u00f3n es a los aconcag\u00fcinos para que participen y puedan ayudar a esta mujer que realmente lo necesita.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizar\u00e1n bingo a beneficio este s\u00e1badoEl pr\u00f3ximo s\u00e1bado 6 de agosto en la comuna de Llay Llay se realizar\u00e1 un bingo a beneficio de una de sus vecinas que sufre hace 5&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2388","post","type-post","status-publish","format-standard","hentry","category-cronica"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/2388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=2388"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/2388\/revisions"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=2388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=2388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=2388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}