{"id":37971,"date":"2013-09-16T10:04:32","date_gmt":"2013-09-16T13:04:32","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=37971"},"modified":"2013-09-16T10:04:32","modified_gmt":"2013-09-16T13:04:32","slug":"elisabeth-loreto-valdes-madre-que-robo-a-sus-tres-hijas-me-las-llevo-porque-no-son-perros-ni-gatos-para-que-las-regalen","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/elisabeth-loreto-valdes-madre-que-robo-a-sus-tres-hijas-me-las-llevo-porque-no-son-perros-ni-gatos-para-que-las-regalen\/","title":{"rendered":"Elisabeth Loreto Vald\u00e9s, madre que \u2018rob\u00f3\u2019 a sus tres hijas: \u00abMe las llevo porque no son perros ni gatos para que las regalen\u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_37972\" aria-describedby=\"caption-attachment-37972\" style=\"width: 317px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/elisabeth-loreto.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-37972 \" title=\"Elisabeth Loreto Vald\u00e9s, angustiada madre que apost\u00f3 todo por sus hijas y se las llev\u00f3 clandestinamente de la Aldea S.O.S. de Quilpu\u00e9.\" alt=\"Elisabeth Loreto Vald\u00e9s, angustiada madre que apost\u00f3 todo por sus hijas y se las llev\u00f3 clandestinamente de la Aldea S.O.S. de Quilpu\u00e9.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/elisabeth-loreto.jpg?resize=317%2C307\" width=\"317\" height=\"307\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/elisabeth-loreto.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/elisabeth-loreto.jpg?resize=154%2C150&amp;ssl=1 154w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/elisabeth-loreto.jpg?resize=300%2C290&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/elisabeth-loreto.jpg?resize=150%2C145&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/elisabeth-loreto.jpg?resize=400%2C387&amp;ssl=1 400w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><\/a><figcaption id=\"caption-attachment-37972\" class=\"wp-caption-text\">Elisabeth Loreto Vald\u00e9s, angustiada madre que apost\u00f3 todo por sus hijas y se las llev\u00f3 clandestinamente de la Aldea S.O.S. de Quilpu\u00e9.<\/figcaption><\/figure>\n<p>Luego que en Diario El Trabajo hici\u00e9ramos de conocimiento p\u00fablico el calvario familiar que desde hace a\u00f1os ven\u00eda viviendo una familia en Santa Mar\u00eda, calvario generado porque un tribunal de Familia les quit\u00f3 a esta pareja a tres de sus hijas y de las cuales dos ser\u00edan dadas en adopci\u00f3n en cualquier momento, Elisabeth Loreto Vald\u00e9s y Mario Aravena se jugaron el todo por el todo y optaron por robarse a sus propias hijas de la Aldea S.O.S. de Quilpu\u00e9, centro de menores a las orden del Sename en el que permanec\u00edan las ni\u00f1as.<\/p>\n<p>De forma Exclusiva Diario El Trabajo logr\u00f3 hablar v\u00eda telef\u00f3nica con la angustiada madre.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00abHASTA PRESA\u00a0IR\u00c9 POR MIS HIJAS\u00bb<\/strong><\/p>\n<p>Asegurando estar en tierras del Norte, fue Elisabeth Loreto Vald\u00e9s quien habl\u00f3 con nuestro medio v\u00eda telef\u00f3nica, para explicar detalladamente lo que est\u00e1 haciendo para permanecer junto a sus peque\u00f1as.<\/p>\n<p><strong>&#8211; \u00bfQu\u00e9 pas\u00f3 con sus ni\u00f1as?<\/strong><\/p>\n<p>&#8211; \u00abYo no me aguant\u00e9 este atropello, mi esposo y yo decidimos este viernes robarnos las ni\u00f1as, no puedo permitir que \u2018las regalen\u2019 a nadie, ellas no son un perrito ni un gato, para que a la primera alguien pueda disponer de ellas como si fueran un sill\u00f3n o un juguete, son mis hijas y dar\u00e9 todo de m\u00ed para que ellas sean felices\u00bb.<\/p>\n<p><strong>&#8211; \u00bfSe siente usted con firmeza para hacerse cargo de las tres menores?<\/strong><\/p>\n<p>&#8211; \u00abClaro que s\u00e9 que tengo que afirmarme bien, mis hijas me dan fuerza para seguir adelante tambi\u00e9n, es verdad que comet\u00ed algunos errores, pero el precio que me cobra el Estado no es comparado con mi error, lo que hice la har\u00eda de nuevo, llegar\u00e9 hasta las \u00faltimas consecuencias\u00bb.<\/p>\n<p><strong>&#8211; \u00bfTienen miedo que les capture la Polic\u00eda?<\/strong><\/p>\n<p>&#8211; \u00abClaro que tenemos mucho miedo, desde que emprendimos nuestra hu\u00edda con las ni\u00f1as, vivimos con el temor que en cualquier momento la Polic\u00eda tire la puerta de nuestro nuevo apartamento a patadas\u00bb.<\/p>\n<p><strong>&#8211; \u00bfIr\u00edas presa por amor a tus hijas?<\/strong><\/p>\n<p>&#8211; \u00abSi debiera ir presa por ellas, lo har\u00eda, s\u00f3lo le pido nuevamente a alg\u00fan abogado y a las autoridades, que me ayuden. Estoy haciendo esto tambi\u00e9n orientada por otras madres que est\u00e1n en las mismas condiciones que la m\u00eda, ellas lo han logrado y por tel\u00e9fono nos hablamos a\u00fan sin conocernos\u00bb.<\/p>\n<p>Para entender la magnitud de lo hecho por esta pareja de vecinos de Santa Mar\u00eda, debemos tomar en cuenta que el Sename ten\u00eda un papel estelar en la vida de toda esta familia, pues Elisabeth Loreto Vald\u00e9s y Mario Aravena, padres de las peque\u00f1itas Brigadit de cinco a\u00f1itos, Constanza de tres y G\u00e9nesis de diez a\u00f1os, ni\u00f1as que por orden del Juzgado de Familia de Quilpu\u00e9 hab\u00edan sido remitidas al Sename, deriv\u00e1ndolas esta instituci\u00f3n a la Aldea S.O.S. de esa ciudad.<\/p>\n<p>Este caso se suma a cientos que en todo Chile est\u00e1n en desarrollo, casos en el que los padres biol\u00f3gicos deciden \u2018robarse\u2019 a sus propios hijos de establecimientos en los que a sus hijos se les retiene contra su voluntad por \u00f3rdenes del Estado.<\/p>\n<p>Roberto Gonz\u00e1lez Short<\/p>\n<p>rgonzalez@eltrabajo<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Luego que en Diario El Trabajo hici\u00e9ramos de conocimiento p\u00fablico el calvario familiar que desde hace a\u00f1os ven\u00eda viviendo una familia en Santa Mar\u00eda, calvario generado porque un tribunal de Familia&#8230;<\/p>\n","protected":false},"author":482,"featured_media":37972,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-37971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/elisabeth-loreto.jpg?fit=529%2C512&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/37971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=37971"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/37971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/37972"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=37971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=37971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=37971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}