{"id":38046,"date":"2013-09-23T10:20:17","date_gmt":"2013-09-23T13:20:17","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38046"},"modified":"2013-09-23T10:20:17","modified_gmt":"2013-09-23T13:20:17","slug":"briant-y-aduanas-incautan-millonario-cargamento-de-marihuana","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/briant-y-aduanas-incautan-millonario-cargamento-de-marihuana\/","title":{"rendered":"Briant y Aduanas incautan millonario cargamento de marihuana"},"content":{"rendered":"<figure id=\"attachment_38047\" aria-describedby=\"caption-attachment-38047\" style=\"width: 529px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/marihuana1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38047\" title=\"Las autoridades dieron cuenta de este nuevo cargamento de estupefacientes il\u00edcitos, quedando detenidos los autores de este nuevo trasiego de marihuana.\" alt=\"Las autoridades dieron cuenta de este nuevo cargamento de estupefacientes il\u00edcitos, quedando detenidos los autores de este nuevo trasiego de marihuana.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/marihuana1.jpg?resize=529%2C353\" width=\"529\" height=\"353\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/marihuana1.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/marihuana1.jpg?resize=200%2C133&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/marihuana1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/marihuana1.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/marihuana1.jpg?resize=400%2C266&amp;ssl=1 400w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-38047\" class=\"wp-caption-text\">Las autoridades dieron cuenta de este nuevo cargamento de estupefacientes il\u00edcitos, quedando detenidos los autores de este nuevo trasiego de marihuana.<\/figcaption><\/figure>\n<p><strong>LOS ANDES<\/strong>.- En una exitosa diligencia, la Brigada Antinarc\u00f3ticos de la PDI de Los Andes junto al Servicio Nacional de Aduanas, lograron la desarticulaci\u00f3n de una banda de traficantes argentinos que ingreso al pa\u00eds un millonario cargamento de marihuana prensada. La diligencia se llev\u00f3 a cabo en virtud de la detecci\u00f3n en el Complejo Los Libertadores el pasado viernes de un cami\u00f3n argentino cargado con 193 paquetes de marihuana ocultos en los neum\u00e1ticos de repuesto.<\/p>\n<p>En total se incautaron 107 kilos de marihuana avaluada en dosis en la suma de casi $537 millones, adem\u00e1s de dos veh\u00edculos y tel\u00e9fonos celulares. All\u00ed fue detenido el conductor del veh\u00edculo identificado como el ciudadano argentino Marco Roberto Campos, de 35 a\u00f1os. Posteriormente en coordinaci\u00f3n con el Ministerio P\u00fablico, el d\u00eda domingo se llev\u00f3 adelante una entrega vigilada de la droga en el paradero 27 de la comuna de Calle Larga, donde fueron detenidos receptores identificados como Cintia Romina Deliberto (27), Anal\u00eda Evangelina Herrera (27) y Dami\u00e1n Jonathan Beltr\u00e1n Ponce (24), todos de nacionalidad argentina.<\/p>\n<p>Los detenidos fueron puestos a disposici\u00f3n del Tribunal de Garant\u00eda de Los Andes y formalizados por Tr\u00e1fico il\u00edcito de drogas, quedando todos en Prisi\u00f3n Preventiva.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LOS ANDES.- En una exitosa diligencia, la Brigada Antinarc\u00f3ticos de la PDI de Los Andes junto al Servicio Nacional de Aduanas, lograron la desarticulaci\u00f3n de una banda de traficantes argentinos que ingreso&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38047,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-38046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/marihuana1.jpg?fit=529%2C353&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38046"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38047"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}