{"id":38085,"date":"2013-09-24T10:09:43","date_gmt":"2013-09-24T13:09:43","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38085"},"modified":"2013-09-24T10:09:43","modified_gmt":"2013-09-24T13:09:43","slug":"mas-de-900-controles-vehiculares-realizo-carabineros-en-fiestas-patrias","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/mas-de-900-controles-vehiculares-realizo-carabineros-en-fiestas-patrias\/","title":{"rendered":"M\u00e1s de 900 controles vehiculares realiz\u00f3 Carabineros en Fiestas Patrias"},"content":{"rendered":"<figure id=\"attachment_38086\" aria-describedby=\"caption-attachment-38086\" style=\"width: 528px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/fiscalizacion.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38086\" title=\"Siete detenidos por conducci\u00f3n en estado de ebriedad, fue el saldo del trabajo policial realizado el largo fin de semana en San Felipe.\" alt=\"Siete detenidos por conducci\u00f3n en estado de ebriedad, fue el saldo del trabajo policial realizado el largo fin de semana en San Felipe.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/fiscalizacion.jpg?resize=528%2C397\" width=\"528\" height=\"397\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/fiscalizacion.jpg?w=528&amp;ssl=1 528w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/fiscalizacion.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/fiscalizacion.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/fiscalizacion.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/fiscalizacion.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><\/a><figcaption id=\"caption-attachment-38086\" class=\"wp-caption-text\">Siete detenidos por conducci\u00f3n en estado de ebriedad, fue el saldo del trabajo policial realizado el largo fin de semana en San Felipe.<\/figcaption><\/figure>\n<p>Un positivo balance, a pesar de la v\u00edctima fatal en un accidente en el sector de El Array\u00e1n en Catemu, efectu\u00f3 el comisario subrogante de Carabineros de San Felipe, capit\u00e1n Alfredo Castillo, al trabajo policial desplegado durante el largo fin de semana de Fiestas Patrias, en que se realizaron m\u00e1s de 900 controles vehiculares en toda la provincia.<\/p>\n<p>Seg\u00fan inform\u00f3 el personero policial, del total de controles, hubo siete personas que fueron detenidas por conducir veh\u00edculos bajo los efectos del alcohol, registr\u00e1ndose adem\u00e1s una baja significativa de accidentes de tr\u00e1nsito graves, pendencias y ri\u00f1as en las fondas y ramadas realizadas en las seis comunas de la provincia.<\/p>\n<p>Asimismo, destac\u00f3 que hubo una baja tasa de denuncias por robo, siendo el m\u00e1s grave el registrado en la bomba de bencina Terpel, donde un sujeto ingres\u00f3 por el techo de las oficinas administrativas y sustrajo la suma de 420 mil pesos en monedas.<\/p>\n<p>El oficial indic\u00f3 que tal como ocurri\u00f3 a lo largo de todo Chile, hubo intensos controles vehiculares en las distintas carreteras, ramadas y fondas en las diferentes comunas; \u201cdesarroll\u00e1ndose en estos recintos las fiestas en total normalidad esencialmente por la exigencia de guardias de seguridad\u201d.<\/p>\n<p>En cuanto a accidentes graves, el caso m\u00e1s lamentable fue la colisi\u00f3n y volcamiento de un autom\u00f3vil en Catemu que cost\u00f3 la vida a una persona; \u201cdonde el conductor perdi\u00f3 el control del veh\u00edculo al colisionar levemente con otro m\u00f3vil, chocando con un \u00e1rbol y volcando en el lugar, muriendo en forma instant\u00e1nea el copiloto. Justamente en este caso tuvo influencia el alcohol, porque el conductor marc\u00f3 0.63 en el test de Intoxilyzer que se le efectu\u00f3 en el sitio del suceso\u201d.<\/p>\n<p>Se\u00f1al\u00f3 que en total hubo siete detenidos por conducci\u00f3n en estado de ebriedad, lo que refleja una disminuci\u00f3n importante respecto del a\u00f1o pasado, tomando en cuenta que en la provincia se realizaron desde el viernes 13 hasta este domingo 22, un total de 916 controles vehiculares con 294 ex\u00e1menes de intoxilyzer en total en la provincia.<\/p>\n<p>\u201cDe estos 916 controles, 217 fueron en San Felipe, donde desde el martes 17 se aplicaron 31 Intoxilyzer. Arrojando todo este trabajo un resultado positivo en cuanto a las personas que conduc\u00edan bajo los efectos del alcohol, porque hubo s\u00f3lo 7 detenidos en esas condiciones, lo que es favorable porque se disminuy\u00f3 en comparaci\u00f3n al 2012, lo que hablar\u00eda que la comunidad est\u00e1 tomando conciencia de lo grave que es conducir bajo la ingesta alcoh\u00f3lica\u201d, puntualiz\u00f3 el jefe subrogante de la Segunda Comisar\u00eda de San Felipe.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un positivo balance, a pesar de la v\u00edctima fatal en un accidente en el sector de El Array\u00e1n en Catemu, efectu\u00f3 el comisario subrogante de Carabineros de San Felipe, capit\u00e1n Alfredo Castillo,&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38086,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-38085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/fiscalizacion.jpg?fit=528%2C397&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38085"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38086"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}