{"id":38113,"date":"2013-09-25T10:11:19","date_gmt":"2013-09-25T13:11:19","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38113"},"modified":"2013-09-25T10:11:19","modified_gmt":"2013-09-25T13:11:19","slug":"insertan-laboralmente-en-supermercado-a-alumnos-con-capacidades-diferentes","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/insertan-laboralmente-en-supermercado-a-alumnos-con-capacidades-diferentes\/","title":{"rendered":"Insertan laboralmente en supermercado a alumnos con capacidades diferentes"},"content":{"rendered":"<figure id=\"attachment_38114\" aria-describedby=\"caption-attachment-38114\" style=\"width: 529px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/tottus.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38114\" title=\"Pedro Salinas y Pablo Vergara, Jefe Bodega y Gerente Tottus, junto al ex alumno Miguel \u00c1ngel Maturana Castro y la Directora de la escuela, Beatriz Gallardo.\" alt=\"Pedro Salinas y Pablo Vergara, Jefe Bodega y Gerente Tottus, junto al ex alumno Miguel \u00c1ngel Maturana Castro y la Directora de la escuela, Beatriz Gallardo.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/tottus.jpg?resize=529%2C397\" width=\"529\" height=\"397\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/tottus.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/tottus.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/tottus.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/tottus.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/tottus.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-38114\" class=\"wp-caption-text\">Pedro Salinas y Pablo Vergara, Jefe Bodega y Gerente Tottus, junto al ex alumno Miguel \u00c1ngel Maturana Castro y la Directora de la escuela, Beatriz Gallardo.<\/figcaption><\/figure>\n<p>Sin duda alguna, que uno de los objetivos fundamentales de la educaci\u00f3n de los ni\u00f1os y ni\u00f1as que asisten diariamente a los distintos establecimientos educacionales del pa\u00eds, es lograr el m\u00e1ximo de capacidades para hacer realidad los sue\u00f1os y metas que se proponen en la etapa escolar.<\/p>\n<p>Cuando se logran estos objetivos, resulta doblemente reconfortante saber que esas metas alcanzadas involucran a j\u00f3venes con capacidades diferentes, quienes muchas veces deben lidiar con la discriminaci\u00f3n o la ignorancia del medio al momento de postular a oportunidades superiores, tales como fuentes laborales, entre otras.<\/p>\n<p>Es por eso que, buscando derribar estos mitos y dentro de las l\u00edneas de acci\u00f3n que abarcan las labores desarrolladas diariamente por los profesionales de la Escuela Especial Sagrado Coraz\u00f3n de San Felipe, est\u00e1n las que abarcan principalmente el multi d\u00e9ficit o retos m\u00faltiples y que implica una tarea m\u00e1s focalizada, adem\u00e1s de las que est\u00e1n orientadas a la inserci\u00f3n laboral.<\/p>\n<p>Es en esta \u00faltima l\u00ednea en la cual ubicamos a Miguel \u00c1ngel Maturana Castro, alumno destacado de este establecimiento educacional municipalizado, quien en agosto pasado, gracias al alto nivel alcanzado en sus jornadas escolares diarias, logr\u00f3 ser insertado laboralmente en la Empresa Tottus de San Felipe, en donde hasta el d\u00eda de hoy y con gran \u00e9xito, desempe\u00f1a labores como Operario de Bodega.<\/p>\n<p>Este joven que ingres\u00f3 al establecimiento el a\u00f1o 1997 y que actualmente tiene 27 a\u00f1os, ha logrado ingresar a la vida laboral gracias a las habilidades adquiridas junto a los profesionales de la escuela Sagrado Coraz\u00f3n, y a la oportunidad que le entrega esta importante empresa, la cual ha entendido las necesidades y carencias de oportunidades de las personas con capacidades diferentes, quienes habitualmente no tienen la posibilidad de ingresar y desarrollarse de manera plena a las diferentes actividades laborales ofrecidas en el mercado.<\/p>\n<p>De acuerdo con lo se\u00f1alado por Beatriz Gallardo Morales, Directora de la escuela Sagrado Coraz\u00f3n, \u201cmuchas veces los empresarios reaccionan con temor ante la solicitud de incluir a nuestros j\u00f3venes a sus empresas, desconociendo absolutamente las cualidades y aptitudes que poseen, temor que incluso, en ciertas circunstancias, tambi\u00e9n abarca a los padres, ignorando que la posibilidades y ventajas de insertarlos laboralmente se transforman en una nueva alternativa de desarrollar otras cualidades para los j\u00f3venes\u201d.<\/p>\n<p>Por su parte, para Pablo Vergara, Gerente de Tienda Tottus San Felipe, dijo que \u201cla experiencia es tremendamente satisfactoria, ya que despu\u00e9s de un a\u00f1o, los resultados han sido \u00f3ptimos, permitiendo a cerca de 7 j\u00f3venes participar de estas pasant\u00edas inclusivas, las que adem\u00e1s est\u00e1n dentro de las pol\u00edticas de nuestra empresa, y que es generar los espacios y las posibilidades a toda la comunidad\u201d.<\/p>\n<p>Pedro Salinas Pav\u00e9s, Jefe de la Secci\u00f3n Bodega, en tanto, sostuvo que \u201ces gratificante poder entregar a nuestros trabajadores, la posibilidad de desarrollarse plenamente en lo laboral, destacando las cualidades positivas de estos alumnos, y que son el respeto, puntualidad y seriedad al momento de realizar sus labores\u201d.<\/p>\n<p>La Escuela Sagrado Coraz\u00f3n fue destacada a principios del mes de septiembre por la Seremi de Educaci\u00f3n, por cumplir con todas las exigencias educacionales, sello que busca ser mantenido en el tiempo como una caracter\u00edstica de la administraci\u00f3n del Alcalde Patricio Freire.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin duda alguna, que uno de los objetivos fundamentales de la educaci\u00f3n de los ni\u00f1os y ni\u00f1as que asisten diariamente a los distintos establecimientos educacionales del pa\u00eds, es lograr el m\u00e1ximo de&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38114,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-38113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/tottus.jpg?fit=529%2C397&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38113"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38114"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}