{"id":38145,"date":"2013-09-26T09:53:08","date_gmt":"2013-09-26T12:53:08","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38145"},"modified":"2013-09-26T09:53:08","modified_gmt":"2013-09-26T12:53:08","slug":"dia-abierto-en-la-escuela-agricola-el-jueves-3-de-octubre","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/dia-abierto-en-la-escuela-agricola-el-jueves-3-de-octubre\/","title":{"rendered":"\u2018D\u00eda Abierto\u2019 en la Escuela Agr\u00edcola el jueves 3 de octubre"},"content":{"rendered":"<figure id=\"attachment_38146\" aria-describedby=\"caption-attachment-38146\" style=\"width: 529px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/agricola1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38146\" title=\"Estas jovencitas cursan la carrera de Servicio de Alimentaci\u00f3n Colectiva en la Escuela Agr\u00edcola, misma que tendr\u00e1 sus puertas abiertas al p\u00fablico durante todo el jueves 3 de octubre.\" alt=\"Estas jovencitas cursan la carrera de Servicio de Alimentaci\u00f3n Colectiva en la Escuela Agr\u00edcola, misma que tendr\u00e1 sus puertas abiertas al p\u00fablico durante todo el jueves 3 de octubre.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/agricola1.jpg?resize=529%2C372\" width=\"529\" height=\"372\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/agricola1.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/agricola1.jpg?resize=200%2C140&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/agricola1.jpg?resize=300%2C210&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/agricola1.jpg?resize=150%2C105&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/agricola1.jpg?resize=400%2C281&amp;ssl=1 400w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-38146\" class=\"wp-caption-text\">Estas jovencitas cursan la carrera de Servicio de Alimentaci\u00f3n Colectiva en la Escuela Agr\u00edcola, misma que tendr\u00e1 sus puertas abiertas al p\u00fablico durante todo el jueves 3 de octubre.<\/figcaption><\/figure>\n<p>La Escuela Agr\u00edcola ha organizado para el jueves 3 de octubre desde las 09:00 a 16:00 horas, un D\u00eda Abierto, oportunidad en que los alumnos de 8\u00ba a\u00f1o b\u00e1sico y sus apoderados, podr\u00e1n visitar dicho establecimiento y as\u00ed poder informar sobre el quehacer educacional de esa casa de estudios; conociendo en terreno el ambiente en que se desarrolla el a\u00f1o acad\u00e9mico en la Agr\u00edcola. En la Escuela Agr\u00edcola se imparten las especialidades T\u00e9cnico Agropecuario de nivel medio y Servicio de Alimentaci\u00f3n Colectiva.<\/p>\n<p>Estas instalaciones educativas son las m\u00e1s antiguas en su g\u00e9nero en el pa\u00eds y es administrada por la Corporaci\u00f3n Educacional de la Sociedad Nacional de Agricultura, lo que sin duda es un gran respaldo y apoyo en la gesti\u00f3n docente y en el posterior desarrollo profesional de los sanfelipe\u00f1os egresados.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Escuela Agr\u00edcola ha organizado para el jueves 3 de octubre desde las 09:00 a 16:00 horas, un D\u00eda Abierto, oportunidad en que los alumnos de 8\u00ba a\u00f1o b\u00e1sico y sus apoderados,&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38146,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-38145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/agricola1.jpg?fit=529%2C372&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38145"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38146"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}