{"id":38160,"date":"2013-09-26T10:02:39","date_gmt":"2013-09-26T13:02:39","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38160"},"modified":"2013-09-26T10:02:39","modified_gmt":"2013-09-26T13:02:39","slug":"hoy-se-realizara-feria-preventiva-en-la-esquina-colorada","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/hoy-se-realizara-feria-preventiva-en-la-esquina-colorada\/","title":{"rendered":"Hoy se realizar\u00e1 Feria Preventiva en la Esquina Colorada"},"content":{"rendered":"<figure id=\"attachment_38161\" aria-describedby=\"caption-attachment-38161\" style=\"width: 317px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/alexis-guerrero.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-38161 \" title=\"Alexis Guerrero, soci\u00f3logo a cargo del Plan Barrio en Paz Residencial en San Felipe.\" alt=\"Alexis Guerrero, soci\u00f3logo a cargo del Plan Barrio en Paz Residencial en San Felipe.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/alexis-guerrero.jpg?resize=317%2C238\" width=\"317\" height=\"238\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/alexis-guerrero.jpg?w=528&amp;ssl=1 528w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/alexis-guerrero.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/alexis-guerrero.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/alexis-guerrero.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/alexis-guerrero.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><\/a><figcaption id=\"caption-attachment-38161\" class=\"wp-caption-text\">Alexis Guerrero, soci\u00f3logo a cargo del Plan Barrio en Paz Residencial en San Felipe.<\/figcaption><\/figure>\n<p>Para hoy est\u00e1 programada la realizaci\u00f3n de una Feria Preventiva denominada \u2018Los ni\u00f1os y ni\u00f1as construyen barrios m\u00e1s seguros a trav\u00e9s de la prevenci\u00f3n\u2019, que organiza el Plan Barrio en Paz Residencial.<\/p>\n<p>La informaci\u00f3n la entreg\u00f3 el encargado de este programa, soci\u00f3logo Alexis Guerrero, quien se\u00f1al\u00f3 que la actividad se realizar\u00e1 en la p\u00e9rgola de la Alameda Chacabuco esquina de Maip\u00fa, justo en el sector popularmente conocido como la Esquina Colorada, con la finalidad de avanzar hacia la recuperaci\u00f3n de espacios p\u00fablicos de la ciudad de San Felipe.<\/p>\n<p>\u201cA esta feria acudir\u00e1n diferentes instancias que trabajan el tema de la prevenci\u00f3n, como es la PDI, Carabineros, Bomberos, Senda \u2013 Previene; Barrio en Paz Residencial y el Cesfam Segismundo Iturra, para realizar una actividad dirigida a los j\u00f3venes, a los alumnos de las escuelas que viven en el sector y para el resto de la comunidad escolar de San Felipe.<\/p>\n<p>\u201cLa idea es que puedan asistir. Habr\u00e1 eventos art\u00edsticos, hip \u2013 hop, una serie de espect\u00e1culos destinados a los ni\u00f1os, con la idea de construir desde los espacios p\u00fablicos, el tema de la prevenci\u00f3n y lugares m\u00e1s seguros\u201d, expres\u00f3 Alexis Guerrero.<\/p>\n<p>En el \u00e1mbito de la prevenci\u00f3n, el soci\u00f3logo reconoce que esta es la primera actividad masiva que se realiza, por lo que est\u00e1n todos los alumnos invitados, aun cuando esta iniciativa se enmarca tambi\u00e9n en el aniversario de la Escuela Jos\u00e9 Manso de Velasco.<\/p>\n<p>Guerrero record\u00f3 que el tema de la prevenci\u00f3n no s\u00f3lo pasa por evitar el consumo de drogas, sino tambi\u00e9n en su m\u00e1s amplio espectro, por lo que se hace necesaria la participaci\u00f3n de la comunidad, y particularmente de la comunidad escolar.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para hoy est\u00e1 programada la realizaci\u00f3n de una Feria Preventiva denominada \u2018Los ni\u00f1os y ni\u00f1as construyen barrios m\u00e1s seguros a trav\u00e9s de la prevenci\u00f3n\u2019, que organiza el Plan Barrio en Paz Residencial&#8230;.<\/p>\n","protected":false},"author":482,"featured_media":38161,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/alexis-guerrero.jpg?fit=528%2C396&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38160"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38161"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}