{"id":38189,"date":"2013-09-27T10:04:55","date_gmt":"2013-09-27T13:04:55","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38189"},"modified":"2013-09-27T10:04:55","modified_gmt":"2013-09-27T13:04:55","slug":"hoy-parten-actividades-de-celebracion-de-la-fiesta-de-la-virgen-de-andacollo","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/hoy-parten-actividades-de-celebracion-de-la-fiesta-de-la-virgen-de-andacollo\/","title":{"rendered":"Hoy parten actividades de celebraci\u00f3n de la Fiesta de la Virgen de Andacollo"},"content":{"rendered":"<figure id=\"attachment_38190\" aria-describedby=\"caption-attachment-38190\" style=\"width: 528px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/virgen-de-andacollo.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38190\" title=\"La imagen de la Virgen de Andacollo presidir\u00e1 la procesi\u00f3n que se realizar\u00e1 el pr\u00f3ximo domingo 6 de octubre.\" alt=\"La imagen de la Virgen de Andacollo presidir\u00e1 la procesi\u00f3n que se realizar\u00e1 el pr\u00f3ximo domingo 6 de octubre.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/virgen-de-andacollo.jpg?resize=528%2C332\" width=\"528\" height=\"332\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/virgen-de-andacollo.jpg?w=528&amp;ssl=1 528w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/virgen-de-andacollo.jpg?resize=200%2C125&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/virgen-de-andacollo.jpg?resize=300%2C188&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/virgen-de-andacollo.jpg?resize=150%2C94&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/virgen-de-andacollo.jpg?resize=400%2C251&amp;ssl=1 400w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><\/a><figcaption id=\"caption-attachment-38190\" class=\"wp-caption-text\">La imagen de la Virgen de Andacollo presidir\u00e1 la procesi\u00f3n que se realizar\u00e1 el pr\u00f3ximo domingo 6 de octubre.<\/figcaption><\/figure>\n<ul>\n<li><strong>El domingo 6 de agosto finaliza la fiesta, con una gran procesi\u00f3n por las calles de San Felipe.<\/strong><\/li>\n<\/ul>\n<p>Una invitaci\u00f3n abierta a la comunidad para que participe a contar de hoy viernes en las actividades de celebraci\u00f3n de la Fiesta de la Virgen de Andacollo, formul\u00f3 el p\u00e1rroco de la Iglesia que lleva ese nombre, padre Juan Cort\u00e9s Malbr\u00e1n.<\/p>\n<p>En conferencia de prensa, el religioso se\u00f1al\u00f3 que cada a\u00f1o, la Parroquia celebra la Fiesta de la Virgen del Rosario de Andacollo, que coincide con la fiesta chica de Andacollo mismo, logrando el a\u00f1o pasado una excelente respuesta de los fieles cat\u00f3licos, con una hermosa experiencia que se tradujo en la participaci\u00f3n de m\u00e1s de 5 mil personas que acudieron a la procesi\u00f3n de la Virgen.<\/p>\n<p>\u201cFue bastante concurrida: nueve cuadras de procesi\u00f3n, se calcula que se reunieron cinco mil personas en el sector de la Plaza de Armas, por lo que queremos invitar a todos los fieles, a concurrir a esta fiesta, la cual es el anhelo en el coraz\u00f3n, que nos recuerda a la \u00e9poca en que estaba el Padre Cardenio Toro, y se hac\u00eda esta fiesta multitudinaria, sentida de la ciudad de San Felipe, que convocaba a todos sus alrededores\u201d, se\u00f1al\u00f3 el Padre Juan Cort\u00e9s.<\/p>\n<p>Las actividades contemplan desde hoy viernes 27 y hasta el s\u00e1bado 5 de Octubre, la Novena de la Virgen; mientras que este viernes tambi\u00e9n se realiza el traslado de la imagen de la Virgen de Andacollo desde el templo parroquial hasta la Capilla Cristo Resucitado.<\/p>\n<p>A las 20.30 horas de hoy en tanto, se realizar\u00e1 el homenaje de los cantores a lo divino en la Capilla Cristo Resucitado.<\/p>\n<p>El domingo 29 de septiembre se realizar\u00e1 la Misa con la familia campesina, donde habr\u00e1 oraci\u00f3n por Chile, mientras que el 2 de octubre a las 16.00 horas se realizar\u00e1 la misa de la santa unci\u00f3n con toda la comunidad adulta mayor, para luego el viernes 4 de octubre, despu\u00e9s de la novena, realizar el V\u00eda Crucis por el Templo Parroquial de Andacollo.<\/p>\n<p>El s\u00e1bado 5 de octubre, se realizar\u00e1 misa a las 07.00 horas, en tanto que a las 20.30 horas se realizar\u00e1 la presentaci\u00f3n de los bailes religiosos en el Templo Parroquial. Posteriormente la imagen de la Virgen recorrer\u00e1 las calles Diego de Almagro, Pedro de Valdivia, S\u00e9ptimo de L\u00ednea, Julio Figueroa, para regresar al Templo Parroquial.<\/p>\n<p>Finalmente, el d\u00eda 6 de octubre pr\u00f3ximo habr\u00e1 misas a las 07.00, 09.00, 11.00 y 13.00 horas, para luego a las 16.00 iniciar la solemne procesi\u00f3n que saldr\u00e1 por Diego de Almagro para llegar a Chorrillos, seguir por Merced, Yungay, Prat, Maip\u00fa, Enc\u00f3n, Hermanos Carrera y Templo Parroquial.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo 6 de agosto finaliza la fiesta, con una gran procesi\u00f3n por las calles de San Felipe. Una invitaci\u00f3n abierta a la comunidad para que participe a contar de hoy viernes&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38190,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-38189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/virgen-de-andacollo.jpg?fit=528%2C332&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38189"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38190"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}