{"id":38195,"date":"2013-09-27T10:07:51","date_gmt":"2013-09-27T13:07:51","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38195"},"modified":"2013-09-27T10:07:51","modified_gmt":"2013-09-27T13:07:51","slug":"municipio-de-panquehue-realizara-este-domingo-segunda-corrida-familiar","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/municipio-de-panquehue-realizara-este-domingo-segunda-corrida-familiar\/","title":{"rendered":"Municipio de Panquehue realizar\u00e1 este domingo Segunda Corrida Familiar"},"content":{"rendered":"<figure id=\"attachment_38196\" aria-describedby=\"caption-attachment-38196\" style=\"width: 528px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/corrida-3-2.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38196\" title=\"Municipalidad de Panquehue espera contar con un gran marco de participantes para la corrida familiar de este domingo.\" alt=\"Municipalidad de Panquehue espera contar con un gran marco de participantes para la corrida familiar de este domingo.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/corrida-3-2.jpg?resize=528%2C293\" width=\"528\" height=\"293\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/corrida-3-2.jpg?w=528&amp;ssl=1 528w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/corrida-3-2.jpg?resize=200%2C110&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/corrida-3-2.jpg?resize=300%2C166&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/corrida-3-2.jpg?resize=150%2C83&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/corrida-3-2.jpg?resize=400%2C221&amp;ssl=1 400w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><\/a><figcaption id=\"caption-attachment-38196\" class=\"wp-caption-text\">Municipalidad de Panquehue espera contar con un gran marco de participantes para la corrida familiar de este domingo.<\/figcaption><\/figure>\n<p><strong>PANQUEHUE<\/strong>.- El Departamento de Educaci\u00f3n, a trav\u00e9s de la Coordinaci\u00f3n de Educaci\u00f3n Extraescolar, el Centro de Salud Familiar y el Programa Promoci\u00f3n de la Salud en conjunto con la Ilustre Municipalidad de Panquehue; tienen contemplada para este domingo 29 de septiembre, a partir de las 09:30 horas, la realizaci\u00f3n de la Segunda Corrida Familiar Panquehue.<\/p>\n<p>La informaci\u00f3n la entreg\u00f3 uno de los encargados de la organizaci\u00f3n del evento deportivo, Sebasti\u00e1n Astudillo, quien se\u00f1al\u00f3 que esta corrida est\u00e1 orientada para que participen todas las familias panquehuinas y del Valle de Aconcagua, incluyendo ni\u00f1os, ni\u00f1as, j\u00f3venes, adultos y adultos mayores.<\/p>\n<p>\u201cEl objetivo de esta corrida es fomentar y promover, en todos los sectores de nuestra comunidad, la pr\u00e1ctica de actividades recreativas y deportivas; integrando a toda la familia, permitiendo estimular, desarrollar, reforzar y consolidar estilos de vida saludable, la convivencia familiar y comunal, y h\u00e1bitos de autocuidado personal\u201d, explic\u00f3 Astudillo.<\/p>\n<p>Para participar de esta corrida familiar, los interesados se deben inscribir v\u00eda Internet bajando la ficha de inscripci\u00f3n del grupo de Facebook \u2018Deportes Panquehue\u2019 y reenviarla al e-mail deportespanquehue@gmail.com. Una vez registrada la inscripci\u00f3n, el participante recibir\u00e1 un correo de notificaci\u00f3n. La inscripci\u00f3n en esta corrida es gratuita.<\/p>\n<p>Tambi\u00e9n se podr\u00e1n inscribir el d\u00eda de la prueba, en el punto de inicio de la corrida, hasta 30 minutos antes de la largada, es decir desde las 08:00 hasta las 09:30 horas.<\/p>\n<p>La distancia de 12 kil\u00f3metros est\u00e1 autorizada libremente para la categor\u00eda juvenil y mayores, es decir para personas desde los 16 a\u00f1os de edad en adelante, a\u00fan cuando se contemplan distancias de 2 y 5 kil\u00f3metros.<\/p>\n<p>Seg\u00fan inform\u00f3 Sebasti\u00e1n Astudillo, colaboran con esta actividad el Instituto Nacional del Deporte, que aportar\u00e1 con el Team IND, el cual ser\u00e1 el encargado de realizar el calentamiento previo a la corrida. Asimismo est\u00e1n colaborando Carabineros del Ret\u00e9n Panquehue y Bomberos.<\/p>\n<p>La salida de los corredores ser\u00e1 el frontis del Centro de Salud Familiar, ubicado en el sector La Pirca, en la comuna de Panquehue.<\/p>\n<p>El programa contempla de 08:00 a 09:30 las inscripciones y entrega de los n\u00fameros para la carrera, de 09:30 a 10:00 calentamiento masivo, 10:00 inicio de la carrera y 11:30 premiaci\u00f3n.<\/p>\n<p>Finalmente Sebasti\u00e1n Astudillo inform\u00f3 que la organizaci\u00f3n entregar\u00e1, a todos los participantes, hidrataci\u00f3n y fruta en los puestos designados para ello.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PANQUEHUE.- El Departamento de Educaci\u00f3n, a trav\u00e9s de la Coordinaci\u00f3n de Educaci\u00f3n Extraescolar, el Centro de Salud Familiar y el Programa Promoci\u00f3n de la Salud en conjunto con la Ilustre Municipalidad de&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38196,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/corrida-3-2.jpg?fit=528%2C293&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38195"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38196"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}