{"id":38216,"date":"2013-09-27T10:22:07","date_gmt":"2013-09-27T13:22:07","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38216"},"modified":"2013-09-27T10:22:07","modified_gmt":"2013-09-27T13:22:07","slug":"roban-camion-cargado-con-productos-de-la-conservera-pentzke","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/roban-camion-cargado-con-productos-de-la-conservera-pentzke\/","title":{"rendered":"Roban cami\u00f3n cargado con productos de la Conservera Pentzke"},"content":{"rendered":"<figure id=\"attachment_38217\" aria-describedby=\"caption-attachment-38217\" style=\"width: 317px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/capitan-alfredo-castillo-2.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-38217 \" title=\"Capit\u00e1n Alfredo Castillo, comisario subrogante de Carabineros de San Felipe.\" alt=\"Capit\u00e1n Alfredo Castillo, comisario subrogante de Carabineros de San Felipe.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/capitan-alfredo-castillo-2.jpg?resize=317%2C238\" width=\"317\" height=\"238\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/capitan-alfredo-castillo-2.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/capitan-alfredo-castillo-2.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/capitan-alfredo-castillo-2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/capitan-alfredo-castillo-2.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/capitan-alfredo-castillo-2.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><\/a><figcaption id=\"caption-attachment-38217\" class=\"wp-caption-text\">Capit\u00e1n Alfredo Castillo, comisario subrogante de Carabineros de San Felipe.<\/figcaption><\/figure>\n<p>Un cami\u00f3n marca Mercedes Benz, perteneciente a la Conservera Pentzke de San Felipe, fue sustra\u00eddo con la totalidad de su carga, correspondiente a productos de la empresa, siendo encontrado gracias al sistema GPS que pose\u00eda, en la comuna de San Bernardo.<\/p>\n<p>El hecho fue denunciado en Carabineros a la 01.00 horas de la madrugada de ayer, por el conductor del cami\u00f3n, identificado como Rodrigo Antonio Ram\u00edrez Nieto, con domicilio en la Villa Sue\u00f1o Dorado del sector La Pirca en Panquehue. Cerca de las 20.30 horas, el conductor lleg\u00f3 a su casa para cenar y asearse, dejando el cami\u00f3n patente DL YX 58, en las afueras de su domicilio, para posteriormente seguir con destino a la ciudad de Coquimbo donde deb\u00eda dejar el cargamento de mercader\u00eda.<\/p>\n<p>Al salir de su casa, el cami\u00f3n ya no estaba, dando cuenta de lo sucedido a Carabineros del Ret\u00e9n Panquehue e informando que el veh\u00edculo pose\u00eda un sistema GPS, lo que permiti\u00f3 rastrearlo.<\/p>\n<p>Por orden del fiscal de turno Julio Palacios, se iniciaron las diligencias que permitieron finalmente, a eso de las 05.00 horas de la madrugada de ayer, dar con el cami\u00f3n en la comuna de San Bernardo, en el kil\u00f3metro 10.900 de la Ruta 5 Sur, sin el cargamento, cuyo aval\u00fao se desconoce, pero ascender\u00eda a varios millones de pesos.<\/p>\n<p>El capit\u00e1n Alfredo Castillo, comisario subrogante de Carabineros de San Felipe, se\u00f1al\u00f3 que contin\u00faan las diligencias para establecer la identidad de los autores de este robo, en tanto que se presume que la mercader\u00eda podr\u00eda ser vendida en la Regi\u00f3n Metropolitana, seguramente, a bajo costo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cami\u00f3n marca Mercedes Benz, perteneciente a la Conservera Pentzke de San Felipe, fue sustra\u00eddo con la totalidad de su carga, correspondiente a productos de la empresa, siendo encontrado gracias al sistema&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-38216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/09\/capitan-alfredo-castillo-2.jpg?fit=529%2C397&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38216"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38217"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}