{"id":38627,"date":"2013-10-11T09:52:17","date_gmt":"2013-10-11T12:52:17","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38627"},"modified":"2013-10-11T09:52:17","modified_gmt":"2013-10-11T12:52:17","slug":"exitosa-jornada-conmemoracion-dia-mundial-de-la-salud-mental","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/exitosa-jornada-conmemoracion-dia-mundial-de-la-salud-mental\/","title":{"rendered":"Exitosa Jornada conmemoraci\u00f3n D\u00eda Mundial de la Salud Mental"},"content":{"rendered":"<figure id=\"attachment_38628\" aria-describedby=\"caption-attachment-38628\" style=\"width: 529px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/jornada-salud-mental.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38628\" title=\"Con la participaci\u00f3n de profesionales del \u00e1rea de salud mental de los establecimientos de la Red Asistencial, se realiz\u00f3 una serie de exposiciones relacionadas con los trastornos del \u00e1nimo.\" alt=\"Con la participaci\u00f3n de profesionales del \u00e1rea de salud mental de los establecimientos de la Red Asistencial, se realiz\u00f3 una serie de exposiciones relacionadas con los trastornos del \u00e1nimo.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/jornada-salud-mental.jpg?resize=529%2C286\" width=\"529\" height=\"286\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/jornada-salud-mental.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/jornada-salud-mental.jpg?resize=200%2C108&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/jornada-salud-mental.jpg?resize=300%2C162&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/jornada-salud-mental.jpg?resize=150%2C81&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/jornada-salud-mental.jpg?resize=400%2C216&amp;ssl=1 400w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-38628\" class=\"wp-caption-text\">Con la participaci\u00f3n de profesionales del \u00e1rea de salud mental de los establecimientos de la Red Asistencial, se realiz\u00f3 una serie de exposiciones relacionadas con los trastornos del \u00e1nimo.<\/figcaption><\/figure>\n<p>El lema de este a\u00f1o corresponde a \u201cSalud mental en el adulto mayor\u201d, por lo que la actividad tuvo especial \u00e9nfasis en la alta prevalencia de este tipo de trastornos en personas pertenecientes a este grupo.<\/p>\n<p>Debido a la alta prevalencia de los trastornos del \u00e1nimo en la poblaci\u00f3n en general, y tomando en cuenta que es la principal causa de consulta en los establecimientos de atenci\u00f3n primaria de la Red, el Servicio de Salud Aconcagua desarroll\u00f3 una jornada enfocada en este tipo de patolog\u00edas, esto en el contexto de la Semana de la Salud Mental.<\/p>\n<p>Durante la actividad, que cont\u00f3 con exposiciones de destacados especialistas de Aconcagua y otros establecimientos del pa\u00eds, se realiz\u00f3 un especial \u00e9nfasis en las personas de la tercera edad, ya que debido al aumento de la poblaci\u00f3n adulto mayor, la demanda de atenci\u00f3n por trastornos del \u00e1nimo se hace cada vez m\u00e1s frecuente y se espera que este sea un grupo prioritario en las d\u00e9cadas venideras.<\/p>\n<p>\u201cNo s\u00f3lo hay actividades de car\u00e1cter l\u00fadico y de recreaci\u00f3n, como las que hemos desarrollado en el Hospital Psiqui\u00e1trico Philippe Pinel, sino tambi\u00e9n el equipo de Salud Mental ha puesto un \u00e9nfasis importante en las actividades acad\u00e9micas como esta jornada, al punto que est\u00e1 incluida dentro del programa de capacitaci\u00f3n de nuestro Servicio de Salud Aconcagua\u201d, destac\u00f3 el Director del Servicio, Rodrigo Infante.<\/p>\n<p>La autoridad destac\u00f3 adem\u00e1s que dentro del trabajo que se hace en la organizaci\u00f3n, se ha relevado de manera constante la labor de los equipos de salud mental. \u201cNo s\u00f3lo tenemos que preocuparnos de la salud f\u00edsica, sino de todas las \u00e1reas en las que una persona puede verse afectada. En ese marco, hemos buscado que los equipos de salud mental cuenten con todo lo necesario para desarrollar su labor, donde destaca el liderazgo que ejerce la Dra. Iris Boisier, ya que su mirada como Psiquiatra y como Subdirectora de Gesti\u00f3n Asistencial, ha permitido que nuestro equipo ampl\u00ede su mirada frente a estas patolog\u00edas y las consideremos al mismo nivel de cualquier otra\u201d, sostuvo Infante.<\/p>\n<p>Esta actividad se enmarca, adem\u00e1s en la incorporaci\u00f3n del diagn\u00f3stico y tratamiento del trastorno bipolar a las Garant\u00edas Expl\u00edcitas en Salud, GES a contar del mes de julio de este a\u00f1o. As\u00ed tambi\u00e9n se enfatiz\u00f3 en que los Centros de Salud Familiar de cada comuna cuentan con equipos altamente capacitados para recibir a quienes presenten s\u00edntomas depresivos, en donde podr\u00e1n recibir la atenci\u00f3n correspondiente, de manera gratuita y con una alta calidad t\u00e9cnica. La Salud Mental es un pilar fundamental de nuestro bienestar y la responsabilidad de su cuidado es tarea de todos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lema de este a\u00f1o corresponde a \u201cSalud mental en el adulto mayor\u201d, por lo que la actividad tuvo especial \u00e9nfasis en la alta prevalencia de este tipo de trastornos en personas&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38628,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/jornada-salud-mental.jpg?fit=529%2C286&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38627"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38628"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}