{"id":38668,"date":"2013-10-14T10:02:57","date_gmt":"2013-10-14T13:02:57","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38668"},"modified":"2013-10-14T10:02:57","modified_gmt":"2013-10-14T13:02:57","slug":"colegio-de-bellavista-defiende-su-derecho-a-existir-ante-eventual-cierre","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/colegio-de-bellavista-defiende-su-derecho-a-existir-ante-eventual-cierre\/","title":{"rendered":"Colegio de Bellavista defiende su derecho a existir ante eventual cierre"},"content":{"rendered":"<figure id=\"attachment_38669\" aria-describedby=\"caption-attachment-38669\" style=\"width: 317px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/claudio-alvarez-director-esc-bellavista.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-38669 \" title=\"El Director (s) Claudio Alvarez explic\u00f3 sus argumentos para mantener abierto el \u00fanico colegio del sector.\" alt=\"El Director (s) Claudio Alvarez explic\u00f3 sus argumentos para mantener abierto el \u00fanico colegio del sector.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/claudio-alvarez-director-esc-bellavista.jpg?resize=317%2C289\" width=\"317\" height=\"289\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/claudio-alvarez-director-esc-bellavista.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/claudio-alvarez-director-esc-bellavista.jpg?resize=164%2C150&amp;ssl=1 164w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/claudio-alvarez-director-esc-bellavista.jpg?resize=150%2C136&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/claudio-alvarez-director-esc-bellavista.jpg?resize=400%2C363&amp;ssl=1 400w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><\/a><figcaption id=\"caption-attachment-38669\" class=\"wp-caption-text\">El Director (s) Claudio Alvarez explic\u00f3 sus argumentos para mantener abierto el \u00fanico colegio del sector.<\/figcaption><\/figure>\n<p>Contin\u00faan las repercusiones tras filtrarse la propuesta del pro PADEM de cerrar dos colegios de la administraci\u00f3n municipal de San Felipe.<\/p>\n<p>Todas las fuentes municipales se\u00f1alan que solo se trat\u00f3 de una sugerencia del equipo asesor en educaci\u00f3n al Concejo Municipal, y que tras ventilarse la posible medida por la prensa, los propios colegios reaccionaron en defensa de los intereses de su comunidad.<\/p>\n<p>Uno de esos colegios aludidos es la escuela Carolina Ocampo Garc\u00eda de Bellavista, que recibi\u00f3 la visita del concejal Basilio Muena para enterarse en terreno de la situaci\u00f3n que les aqueja.<\/p>\n<p>El concejal se\u00f1al\u00f3 a Diario el Trabajo que tras \u201cvisitar Radio 10 y escuchar los planteamientos del director de un colegio, adem\u00e1s de aceptar el compromiso de revisar con los mismos docentes o directores la realidad de los colegios aludidos, decid\u00ed venir a hablar con el director de este colegio en Bellavista, y nada m\u00e1s entrar y ver a los ni\u00f1os en sus salas abiertas, con un ambiente de mucha paz y tranquilidad, realizando trabajos en grupo, uno no hace m\u00e1s que ratificar que sacarlos de este entorno es lo peor que les podr\u00eda pasar\u201d.<\/p>\n<p>Claudio \u00c1lvarez es el director subrogante del establecimiento, y al hablar con nuestro medio se\u00f1al\u00f3 que \u201cnosotros vamos a hacer todo lo que est\u00e9 a nuestro alcance para que el colegio no se cierre. Si me pides mi opini\u00f3n, el sistema es malo y perverso, y no ha habido gobierno que lo arregle\u201d. Se\u00f1ala que tiempo atr\u00e1s habl\u00f3 con el alcalde Patricio Freire y \u00e9l le dijo que no era partidario de cerrar la escuela. Por lo que \u201cestoy confiado en que eso no pase con este colegio\u201d.<\/p>\n<p>En tanto Muena agreg\u00f3 que transmitir\u00e1 \u201ca quien corresponda, la necesidad de conservar estos colegios porque son una necesidad real de las comunidades en los que se emplazan. No es posible que en materia presupuestaria se corte por el hilo m\u00e1s delgado. No es posible que el hilo m\u00e1s delgado sean estos ni\u00f1os que lo \u00fanico que necesitan es que los recursos que el ministerio env\u00eda para ellos, sean invertidos justamente en sus necesidades. Junto al concejal Rodolfo Silva hemos planteado a la DAEM que deben existir otras formas de optimizar los recursos, sin tener que afectar a los colegios rurales\u201d.<\/p>\n<p>El colegio de Bellavista tiene una matr\u00edcula de 65 alumnos y est\u00e1 inserta en la localidad de Bellavista desde 1957. Hace algunos a\u00f1os se agruparon varios cursos, y con esa medida se \u201cperjudic\u00f3 la matr\u00edcula del colegio, ya que la gente no quiere que sus hijos se mezclen con otros niveles y se los llevan a otros colegios\u201d.<\/p>\n<p>Claudio Alvares se encuentra confiado de que la reuni\u00f3n que deben sostener hoy lunes en la direcci\u00f3n Municipal de Educaci\u00f3n, arrojar\u00e1 m\u00e1s claridad en torno a esta preocupaci\u00f3n que tienen. Mientras tanto la incertidumbre se mantiene entre los padres y apoderados del sector, a la espera de que el municipio entregue su \u00faltima palabra sobre el destino de \u00e9ste y los dem\u00e1s 23 colegios que administra.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contin\u00faan las repercusiones tras filtrarse la propuesta del pro PADEM de cerrar dos colegios de la administraci\u00f3n municipal de San Felipe. Todas las fuentes municipales se\u00f1alan que solo se trat\u00f3 de una&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38669,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/claudio-alvarez-director-esc-bellavista.jpg?fit=529%2C481&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38668"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38669"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}