{"id":38695,"date":"2013-10-15T09:49:42","date_gmt":"2013-10-15T12:49:42","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38695"},"modified":"2013-10-15T09:49:57","modified_gmt":"2013-10-15T12:49:57","slug":"por-insalubre-clausuran-parqueadero-de-la-empresa-pullman-en-los-andes","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/por-insalubre-clausuran-parqueadero-de-la-empresa-pullman-en-los-andes\/","title":{"rendered":"Por insalubre clausuran parqueadero de la empresa Pullman en Los Andes"},"content":{"rendered":"<figure id=\"attachment_38696\" aria-describedby=\"caption-attachment-38696\" style=\"width: 529px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/pullman-laberinto16.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38696\" title=\"Vecinos del sector estaban tan felices con la clausura que hasta posaron para Diario El Trabajo.\" alt=\"Vecinos del sector estaban tan felices con la clausura que hasta posaron para Diario El Trabajo.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/pullman-laberinto16.jpg?resize=529%2C325\" width=\"529\" height=\"325\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/pullman-laberinto16.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/pullman-laberinto16.jpg?resize=200%2C122&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/pullman-laberinto16.jpg?resize=300%2C184&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/pullman-laberinto16.jpg?resize=150%2C92&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/pullman-laberinto16.jpg?resize=400%2C245&amp;ssl=1 400w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-38696\" class=\"wp-caption-text\">Vecinos del sector estaban tan felices con la clausura que hasta posaron para Diario El Trabajo.<\/figcaption><\/figure>\n<ul>\n<li><strong>Vecinos de la poblaci\u00f3n Jardines Familiares hab\u00edan reclamado al municipio por las condiciones de este recinto ubicado en calle El Laberinto.<\/strong><\/li>\n<\/ul>\n<p><strong>LOS ANDES<\/strong>.- Inspectores municipales procedieron la tarde de este lunes a clausurar el parqueadero y garaje de la empresa de buses Pullman ubicado en la calle El Laberinto.<\/p>\n<p>La decisi\u00f3n se tom\u00f3 luego de las reiteradas denuncias de los vecinos respecto a las condiciones higi\u00e9nicas y de salubridad del recinto.<\/p>\n<p>En ese lugar deben pernoctar los conductores y auxiliares de la empresa que realiza recorridos a Santiago y Valpara\u00edso. Adem\u00e1s se lavan las m\u00e1quinas al terminar cada jornada y ruidos molestos al encender los motores.<\/p>\n<p>El Jefe del Departamento Jur\u00eddico de la Municipalidad, abogado Juan Pablo Pozo, se\u00f1al\u00f3 que la clausura se debi\u00f3 a las denuncias reiteradas de los vecinos en contra de este recinto que funciona desde hace 14 a\u00f1os.<\/p>\n<p>\u201cLa idea es poder regularizar este parqueadero donde llegan y pernoctan una gran cantidad de buses, adem\u00e1s se hac\u00edan trabajos de lavado de camiones y buses provocando situaciones muy complejas, incluso de dramas familiares\u201d, sostuvo.<\/p>\n<p>Pozo indic\u00f3 que como municipio se reunieron con los dirigentes vecinales la semana pasada y el alcalde Navarro se comprometi\u00f3 a la clausura de este lugar, \u201csituaci\u00f3n que fue conversada con la empresa, se les puso en conocimiento y definitivamente esto se tradujo en que el viernes se hizo una visita a este lugar por parte de las direcciones de Obras, Tr\u00e1nsito y Jur\u00eddico y nos percatamos de la existencia de buses en el interior siendo lavados, lo cual est\u00e1 terminantemente prohibido por nuestro plan regulador comunal, dado que en esta zona no est\u00e1 permitido la existencia de parqueaderos\u201d.<\/p>\n<p>El abogado sostuvo que se colocaron los sellos que no pueden ser rotos por el personal de la empresa de buses.<\/p>\n<p>El abogado dijo que el cierre es definitivo, \u201cy la \u00fanica posibilidad de que este parqueadero pueda existir contempla una modificaci\u00f3n del plan regulador comunal, lo cual es inviable\u201d.<\/p>\n<p>Agreg\u00f3 que si la empresa llegara a hacer una rotura de sellos estar\u00edan cometiendo un delito, \u201cpor lo tanto pasar\u00eda lo que es la justicia penal\u201d.<\/p>\n<p>En tanto el Presidente de la Junta de Vecinos, Pedro Manr\u00edquez, plante\u00f3 que desde el a\u00f1o 2002 han insistido ante las autoridades comunales para una soluci\u00f3n a este problema, \u201cpero nunca hicieron nada por solucionarlo y aqu\u00ed son muchos los vecinos perjudicados\u201d.<\/p>\n<p>El dirigente agradeci\u00f3 al alcalde Navarro por haber escuchado esta sentida demanda de los vecinos, \u201cpues gracias a ello se tom\u00f3 una determinaci\u00f3n de cerrarlo de una vez por todas y dar por solucionado el problema\u201d.<\/p>\n<p>Record\u00f3 que el encendido de motores comenzaba a las 4 y media de la madrugada, y a parte del ruido, deb\u00edan soportar los gases, la limpieza indebida de los ba\u00f1os y muchas otras cosas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vecinos de la poblaci\u00f3n Jardines Familiares hab\u00edan reclamado al municipio por las condiciones de este recinto ubicado en calle El Laberinto. LOS ANDES.- Inspectores municipales procedieron la tarde de este lunes a&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38696,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/pullman-laberinto16.jpg?fit=529%2C325&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38695"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38696"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}