{"id":38699,"date":"2013-10-15T09:51:15","date_gmt":"2013-10-15T12:51:15","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38699"},"modified":"2013-10-15T09:51:15","modified_gmt":"2013-10-15T12:51:15","slug":"benefician-a-15-mujeres-con-recursos-del-fondo-concursable-capital-semilla","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/benefician-a-15-mujeres-con-recursos-del-fondo-concursable-capital-semilla\/","title":{"rendered":"Benefician a 15 mujeres con recursos del fondo concursable Capital Semilla"},"content":{"rendered":"<figure id=\"attachment_38700\" aria-describedby=\"caption-attachment-38700\" style=\"width: 529px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/capital-semilla.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38700\" title=\"Un total de 15 mujeres pertenecientes al programa \u2018Mujer Trabajadora y Jefa de Hogar\u2019, fueron favorecidas con el Fondo Concursable Capital Semilla del Sernam.\" alt=\"Un total de 15 mujeres pertenecientes al programa \u2018Mujer Trabajadora y Jefa de Hogar\u2019, fueron favorecidas con el Fondo Concursable Capital Semilla del Sernam.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/capital-semilla.jpg?resize=529%2C355\" width=\"529\" height=\"355\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/capital-semilla.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/capital-semilla.jpg?resize=200%2C134&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/capital-semilla.jpg?resize=300%2C201&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/capital-semilla.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/capital-semilla.jpg?resize=400%2C268&amp;ssl=1 400w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-38700\" class=\"wp-caption-text\">Un total de 15 mujeres pertenecientes al programa \u2018Mujer Trabajadora y Jefa de Hogar\u2019, fueron favorecidas con el Fondo Concursable Capital Semilla del Sernam.<\/figcaption><\/figure>\n<ul>\n<li><strong>Ellas forman parte del programa Mujer Trabajadora y Jefa de Hogar.<\/strong><\/li>\n<\/ul>\n<p>Quince mujeres pertenecientes al programa \u2018Mujer Trabajadora y Jefa de Hogar\u2019, que postularon al Fondo Concursable Capital Semilla del Sernam, recibieron este jueves el cheque que les permite continuar con su emprendimiento.<\/p>\n<p>Durante el mes de septiembre pasado, unas 40 mujeres participantes del programa municipal postularon al fondo concursable, siendo quince las seleccionadas y quienes recibieron el cheque, en una ceremonia realizada en el Sal\u00f3n de Honor de la Municipalidad y que estuvo encabezada por el director de Desarrollo Comunitario del municipio, Pablo Silva.<\/p>\n<p>Los recursos, que superan los 132 mil pesos para cada una, les permitir\u00e1n potenciar sus microemprendimientos y comprar insumos, que a su vez las ayudar\u00e1n a aumentar sus ventas.<\/p>\n<p>Las mujeres seleccionadas, que tienen emprendimientos relacionados con confecci\u00f3n de art\u00edculos para el hogar, corte y confecci\u00f3n, reposter\u00eda y peluquer\u00eda, entre otras, se mostraron felices con este beneficio, que les permitir\u00e1 seguir avanzando en sus emprendimientos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ellas forman parte del programa Mujer Trabajadora y Jefa de Hogar. Quince mujeres pertenecientes al programa \u2018Mujer Trabajadora y Jefa de Hogar\u2019, que postularon al Fondo Concursable Capital Semilla del Sernam, recibieron&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38700,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/capital-semilla.jpg?fit=529%2C355&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38699"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38700"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}