{"id":38702,"date":"2013-10-15T09:52:42","date_gmt":"2013-10-15T12:52:42","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38702"},"modified":"2013-10-15T09:52:42","modified_gmt":"2013-10-15T12:52:42","slug":"con-aumento-considerable-de-publico-registro-civil-sigue-poniendose-al-dia","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/con-aumento-considerable-de-publico-registro-civil-sigue-poniendose-al-dia\/","title":{"rendered":"Con aumento considerable de p\u00fablico Registro Civil sigue poni\u00e9ndose \u2018al d\u00eda\u2019"},"content":{"rendered":"<figure id=\"attachment_38703\" aria-describedby=\"caption-attachment-38703\" style=\"width: 529px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/ragistro-civil-1-porta.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38703\" title=\"Alrededor de un 30 por ciento ha aumentado la afluencia de p\u00fablico en el Registro Civil de San Felipe.\" alt=\"Alrededor de un 30 por ciento ha aumentado la afluencia de p\u00fablico en el Registro Civil de San Felipe.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/ragistro-civil-1-porta.jpg?resize=529%2C364\" width=\"529\" height=\"364\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/ragistro-civil-1-porta.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/ragistro-civil-1-porta.jpg?resize=200%2C137&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/ragistro-civil-1-porta.jpg?resize=300%2C206&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/ragistro-civil-1-porta.jpg?resize=150%2C103&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/ragistro-civil-1-porta.jpg?resize=400%2C275&amp;ssl=1 400w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-38703\" class=\"wp-caption-text\">Alrededor de un 30 por ciento ha aumentado la afluencia de p\u00fablico en el Registro Civil de San Felipe.<\/figcaption><\/figure>\n<ul>\n<li><strong>Cientos de usuarios mantienen tiempos de espera de hasta dos horas para ser atendidos.<\/strong><\/li>\n<\/ul>\n<p>Cientos de usuarios permanecen de manera constante en las oficinas del Registro Civil de San Felipe. La gran mayor\u00eda acude por renovaci\u00f3n de c\u00e9dulas de identidad y certificados, y en menor medida para otros tr\u00e1mites.<\/p>\n<p>Seg\u00fan los usuarios, el tiempo de espera puede alcanzar las dos horas en algunos casos, \u201csobre todo si hay que sacar carn\u00e9\u201d nos dice uno de los usuarios, el que agrega que \u201clas se\u00f1oritas atienden muy r\u00e1pido, pero hay mucha gente haciendo el tr\u00e1mite. Mire, yo saqu\u00e9 el n\u00famero 72 y van reci\u00e9n en el 8. Vengo a sacar carn\u00e9 porque se me perdieron los documentos, y ahora me entero que dan un documento nuevo y el tr\u00e1mite es un poco m\u00e1s demoroso\u201d.<\/p>\n<p>Las funcionarias dicen que han atendido a \u201ctoda m\u00e1quina\u201d y que \u201cse nota un aumento grande, sobre todo de la gente que necesita hacer tr\u00e1mites de estudios o matr\u00edcula\u201d.<\/p>\n<p>Haciendo un c\u00e1lculo por atenciones, estiman que se ha visto un aumento de alrededor del 30% sobre los tr\u00e1mites normales para esta \u00e9poca, pero que creen que las cifras van a ir normaliz\u00e1ndose con el correr de las semanas.<\/p>\n<p>A\u00fan as\u00ed, comentaron a Diario El Trabajo que el d\u00eda 4 de octubre en que las oficinas estuvieron abiertas, muy poca gente se acerc\u00f3 a realizar tr\u00e1mites, por lo que recordaron que la direcci\u00f3n nacional dispuso de la apertura de las oficinas de San Felipe y Los Andes para este 19 con la posibilidad de realizar tr\u00e1mites como renovar o sacar C\u00e9dula para chilenos, pasaportes y tr\u00e1mites de inscripci\u00f3n de veh\u00edculos.<\/p>\n<p>En total se estima que unas 4 mil atenciones se dejaron de hacer en las dos provincias durante los 17 d\u00edas que el servicio estuvo paralizado por las demandas de los trabajadores, y que en alg\u00fan momento puso en jaque al gobierno.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cientos de usuarios mantienen tiempos de espera de hasta dos horas para ser atendidos. Cientos de usuarios permanecen de manera constante en las oficinas del Registro Civil de San Felipe. La gran&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38703,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/ragistro-civil-1-porta.jpg?fit=529%2C364&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38702"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38703"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}