{"id":38790,"date":"2013-10-17T09:59:00","date_gmt":"2013-10-17T12:59:00","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38790"},"modified":"2013-10-17T09:59:00","modified_gmt":"2013-10-17T12:59:00","slug":"alcalde-freire-preocupado-por-peligro-de-canalon-donde-se-banan-ninos-del-sector-sur-de-san-felipe","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/alcalde-freire-preocupado-por-peligro-de-canalon-donde-se-banan-ninos-del-sector-sur-de-san-felipe\/","title":{"rendered":"Alcalde Freire preocupado por peligro de canal\u00f3n donde se ba\u00f1an ni\u00f1os del sector sur de San Felipe"},"content":{"rendered":"<figure id=\"attachment_38791\" aria-describedby=\"caption-attachment-38791\" style=\"width: 529px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/canalon.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38791\" title=\"El Alcalde Patricio Freire pidi\u00f3 que se tape este canal\u00f3n por el evidente peligro que conlleva para los ni\u00f1os del sector.\" alt=\"El Alcalde Patricio Freire pidi\u00f3 que se tape este canal\u00f3n por el evidente peligro que conlleva para los ni\u00f1os del sector.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/canalon.jpg?resize=529%2C310\" width=\"529\" height=\"310\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/canalon.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/canalon.jpg?resize=200%2C117&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/canalon.jpg?resize=300%2C175&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/canalon.jpg?resize=150%2C87&amp;ssl=1 150w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/canalon.jpg?resize=400%2C234&amp;ssl=1 400w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><figcaption id=\"caption-attachment-38791\" class=\"wp-caption-text\">El Alcalde Patricio Freire pidi\u00f3 que se tape este canal\u00f3n por el evidente peligro que conlleva para los ni\u00f1os del sector.<\/figcaption><\/figure>\n<p>Su preocupaci\u00f3n por la peligrosidad que significa la existencia del canal\u00f3n, en las condiciones en que actualmente se encuentra, manifest\u00f3 el Alcalde Patricio Freire, quien se reuni\u00f3 la ma\u00f1ana de este mi\u00e9rcoles con los vecinos del sector sur de la comuna, por donde pasa el acueducto.<\/p>\n<p>A primera hora de la ma\u00f1ana de este mi\u00e9rcoles el jefe comunal se traslad\u00f3 al lugar y pudo constatar que por el canal\u00f3n estaba corriendo agua turbia, desconociendo su origen. Ante ello manifest\u00f3 su preocupaci\u00f3n, ya que al encontrarse este lugar abierto a la poblaci\u00f3n, permite que los ni\u00f1os se acerquen a ba\u00f1arse al lugar y que sean arrastrados por la fuerza de la corriente.<\/p>\n<p>\u201cEstamos muy preocupados de ver la fuerza con que est\u00e1 bajando el agua en el canal\u00f3n, por los vecinos y los ni\u00f1os, el peligro que significa tener el canal\u00f3n abierto. No quiero pensar en verano, los ni\u00f1os van a tener la tentaci\u00f3n de meterse en el canal\u00f3n, as\u00ed que pido tapar este canal\u00f3n a la brevedad posible o hacer un muro que significa un costo enorme, pero esto as\u00ed como est\u00e1 reviste un tremendo peligro\u201d, dijo el Alcalde Freire.<\/p>\n<p>Los vecinos se encuentran muy preocupados por esta situaci\u00f3n, ya que es com\u00fan que los ni\u00f1os se acerquen a ba\u00f1arse al r\u00edo y ahora al ver el canal\u00f3n con agua pueden repetir esa acci\u00f3n, poniendo en riesgo su vida.<\/p>\n<p>\u201cLos ni\u00f1os se ba\u00f1an en la tarde y puede pasar una desgracia muy grande, queremos que se cierre\u201d, dijo Alex Zamora, integrante de un grupo cultural del sector.<\/p>\n<p>Uno de los ni\u00f1os que vive en el sector reconoci\u00f3 que junto a sus amigos se ba\u00f1an en el r\u00edo, aunque tienen claro el peligro que significa.<\/p>\n<p>\u201cA m\u00ed me gusta venir a ba\u00f1arme al r\u00edo, pero esto es un peligro para la sociedad, por \u00faltimo que lo tapen arriba\u201d, pidi\u00f3 el peque\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su preocupaci\u00f3n por la peligrosidad que significa la existencia del canal\u00f3n, en las condiciones en que actualmente se encuentra, manifest\u00f3 el Alcalde Patricio Freire, quien se reuni\u00f3 la ma\u00f1ana de este mi\u00e9rcoles&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38791,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/canalon.jpg?fit=529%2C310&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38790"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38791"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}