{"id":38827,"date":"2013-10-18T09:43:19","date_gmt":"2013-10-18T12:43:19","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=38827"},"modified":"2013-10-18T09:43:19","modified_gmt":"2013-10-18T12:43:19","slug":"afirmo-diputado-rivas-nuevos-pozos-en-llay-llay-pondran-en-riesgo-napas-subterraneas","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/afirmo-diputado-rivas-nuevos-pozos-en-llay-llay-pondran-en-riesgo-napas-subterraneas\/","title":{"rendered":"Afirm\u00f3 Diputado Rivas: \u201cNuevos pozos en Llay Llay pondr\u00e1n en riesgo napas subterr\u00e1neas\u201d"},"content":{"rendered":"<figure id=\"attachment_38828\" aria-describedby=\"caption-attachment-38828\" style=\"width: 370px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/rivasdoh-cristian-veliz.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-38828 \" title=\"Diputado Rivas junto al Director Regional de la DOH, Cristian V\u00e9liz, en visita de semanas atr\u00e1s a pozos secos en estadio fiscal de San Felipe.\" alt=\"Diputado Rivas junto al Director Regional de la DOH, Cristian V\u00e9liz, en visita de semanas atr\u00e1s a pozos secos en estadio fiscal de San Felipe.\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/rivasdoh-cristian-veliz.jpg?resize=370%2C431\" width=\"370\" height=\"431\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/rivasdoh-cristian-veliz.jpg?w=529&amp;ssl=1 529w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/rivasdoh-cristian-veliz.jpg?resize=129%2C150&amp;ssl=1 129w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/rivasdoh-cristian-veliz.jpg?resize=258%2C300&amp;ssl=1 258w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/rivasdoh-cristian-veliz.jpg?resize=400%2C465&amp;ssl=1 400w\" sizes=\"auto, (max-width: 370px) 100vw, 370px\" \/><\/a><figcaption id=\"caption-attachment-38828\" class=\"wp-caption-text\">Diputado Rivas junto al Director Regional de la DOH, Cristian V\u00e9liz, en visita de semanas atr\u00e1s a pozos secos en estadio fiscal de San Felipe.<\/figcaption><\/figure>\n<p>El Diputado de Aconcagua Gaspar Rivas, a prop\u00f3sito de la promulgaci\u00f3n de Decreto de Escasez H\u00eddrica para las provincias de San Felipe y Los Andes, expres\u00f3 abiertamente sus aprensiones a la construcci\u00f3n de cuatro nuevos pozos en Llay Llay; \u201cporque podr\u00eda tener efectos nefastos en napas subterr\u00e1neas de la comuna\u201d.<\/p>\n<p>El parlamentario puntualiz\u00f3 que si bien un decreto de escasez h\u00eddrica puede tener sus beneficios, el valle de Aconcagua no ha tenido buenas experiencias; \u201cporque recordemos que el decreto que termin\u00f3 el 8 de mayo pasado, hubo serios problemas con las napas por el funcionamiento de la bater\u00eda de pozos en Curim\u00f3n y que deriv\u00f3 en una manifestaci\u00f3n ciudadana donde particip\u00e9 activamente para expresa mi disconformidad y de que no est\u00e1bamos dispuestos a tolerar que una gota m\u00e1s de agua de Aconcagua se saqueara parar llev\u00e1rsela a Quillota o la tercera secci\u00f3n del R\u00edo Aconcagua.<\/p>\n<p>\u201cHoy d\u00eda ese fantasma que estuvo dormido por algunos meses vuelve a despertar con la promulgaci\u00f3n de este nuevo decreto de escasez h\u00eddrica, y la amenaza se cierne sobre nuestro valle nuevamente, aunque ya se ha sido m\u00e1s que solidario con la tercera secci\u00f3n en este marco de sequ\u00eda estructural que enfrenta la regi\u00f3n y gran parte del pa\u00eds\u201d, dijo Rivas.<\/p>\n<p>El Diputado enf\u00e1ticamente sostuvo que le gustar\u00eda estar destacando las cosas positivas que tiene un decreto de escasez h\u00eddrica; \u201ccomo es la posibilidad de liberar m\u00e1s f\u00e1cil recursos p\u00fablicos, de manera menos burocr\u00e1tica, como por ejemplo la perforaci\u00f3n y profundizaci\u00f3n de pozos de APR en comunas como Santa Mar\u00eda, donde es muy poco lo que se ha hecho por esas comunidades.<\/p>\n<p>\u201cPero lamentablemente lo que tenemos que hacer es ponernos en alerta por la preocupaci\u00f3n que significa que vuelvan a poner en funcionamiento la bater\u00eda de pozos de Curim\u00f3n, en Panquehue espec\u00edficamente en el sector de Escorial y ahora con especial atenci\u00f3n en la comuna de Llay Llay, donde este decreto trae la grave noticia de que la DOH va a perforar cuatro nuevos pozos, que se van agregar a los once pozos ya existentes, completando una bater\u00eda de quince pozos en esa comuna, sumando ya por lo menos 55 pozos en el valle de Aconcagua que est\u00e1n destinados principal y preferentemente para sacar el agua de nuestras napas subterr\u00e1neas y llev\u00e1rsela a la tercera secci\u00f3n del r\u00edo Aconcagua \u201d, advirti\u00f3 el parlamentario.<\/p>\n<p>El legislador sostuvo que el propio Director Regional de Obras Hidr\u00e1ulicas, Cristian V\u00e9liz, reconoci\u00f3 que el objetivo de perforar estos nuevos pozos en Llay Llay; \u201cno es agua para esa comuna, sino que abiertamente para reducir el peso que tienen los pozos de Curim\u00f3n y Panquehue en lo que se refiere al aporte que har\u00edan en agua a la tercera secci\u00f3n y Petorca\u201d.<\/p>\n<p>Iniciativa a la que el Diputado Rivas se opone abiertamente; \u201cporque resulta que ahora Llay Llay va a tener que cargar con todo este impuesto aporte que hace el valle de Aconcagua en agua para la tercera secci\u00f3n del r\u00edo, producto sin duda de intereses pol\u00edticos y de lo que se desprende de las declaraciones de la Diputad Andrea Molina en torno a la puesta en funcionamiento de los pozos en Llay Llay.<\/p>\n<p>\u201cCon esto se est\u00e1 ratificando que aqu\u00ed hay una inversi\u00f3n fantasma, que esa inversi\u00f3n que se hace en Aconcagua, derechamente no est\u00e1 destinada a beneficiar a las comunas de las provincias de Los Andes y San Felipe, sino que solamente pensando en la tercera secci\u00f3n, ahondando el estigma que nuestro valle siempre es usado para suplir necesidades en el resto de la regi\u00f3n, pero cuando se trata de que nuestras provincias reciban alg\u00fan beneficio, siempre es postergado\u201d, sentenci\u00f3 Rivas.<\/p>\n<p>\u201cPorque el agua de Aconcagua debe ser para Aconcagua, reitero mi compromiso con las comunidades para defenderla y por eso mismo me pongo en estado de alerta para levantar nuevamente la voz y oponerme a que aprovech\u00e1ndose de este decreto de escasez h\u00eddrica, se insista en saquear nuestra agua poniendo en funcionamiento las bater\u00edas de pozos en Curim\u00f3n, Panquehue y ahora Llay Llay\u201d, advirti\u00f3 el parlamentario.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Diputado de Aconcagua Gaspar Rivas, a prop\u00f3sito de la promulgaci\u00f3n de Decreto de Escasez H\u00eddrica para las provincias de San Felipe y Los Andes, expres\u00f3 abiertamente sus aprensiones a la construcci\u00f3n&#8230;<\/p>\n","protected":false},"author":482,"featured_media":38828,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2013\/10\/rivasdoh-cristian-veliz.jpg?fit=529%2C615&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=38827"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/38827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/38828"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=38827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=38827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=38827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}