{"id":60810,"date":"2015-08-10T09:21:30","date_gmt":"2015-08-10T12:21:30","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=60810"},"modified":"2015-08-10T09:21:30","modified_gmt":"2015-08-10T12:21:30","slug":"autoridades-realizan-positivo-balance-ante-paso-de-frente-de-mal-tiempo","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/autoridades-realizan-positivo-balance-ante-paso-de-frente-de-mal-tiempo\/","title":{"rendered":"Autoridades realizan positivo balance ante paso de frente de mal tiempo"},"content":{"rendered":"<figure id=\"attachment_60811\" aria-describedby=\"caption-attachment-60811\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Foto-Rio-Frente-a-Parque-Municipal.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-60811 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Foto-Rio-Frente-a-Parque-Municipal-300x198.jpg?resize=300%2C198\" alt=\"Autoridades municipales estuvieron constantemente monitoreando los posibles da\u00f1os que pudiera dejar el sistema frontal en la ciudad.\" width=\"300\" height=\"198\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Foto-Rio-Frente-a-Parque-Municipal.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Foto-Rio-Frente-a-Parque-Municipal.jpg?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Foto-Rio-Frente-a-Parque-Municipal.jpg?resize=227%2C150&amp;ssl=1 227w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Foto-Rio-Frente-a-Parque-Municipal.jpg?resize=400%2C264&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Foto-Rio-Frente-a-Parque-Municipal.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-60811\" class=\"wp-caption-text\">Autoridades municipales estuvieron constantemente monitoreando los posibles da\u00f1os que pudiera dejar el sistema frontal en la ciudad.<\/figcaption><\/figure>\n<ul>\n<li><strong>Notorias medidas preventivas, atenci\u00f3n oportuna y problemas menores marcaron los d\u00edas del temporal. \u201cLa lluvia es una bendici\u00f3n para Putaendo\u201d, destac\u00f3 la m\u00e1xima autoridad comunal<\/strong><\/li>\n<\/ul>\n<p><strong>PUTAENDO<\/strong>.- Un balance positivo en l\u00edneas generales realiz\u00f3 el alcalde Guillermo Reyes Cortez, sobre las consecuencias que dej\u00f3 el frente de mal tiempo de los \u00faltimos tres d\u00edas en Putaendo.<br \/>\nAl mediod\u00eda del viernes, la m\u00e1xima autoridad comunal revisaba crecidas del R\u00edo Putaendo en el sector Juan Rozas, para evitar alguna emergencia. En ese contexto, el alcalde realiz\u00f3 un resumen de lo acontecido en la comuna con la lluvia.<br \/>\n\u201cNo tenemos ning\u00fan albergado, algunos damnificados por aniego y muy pocas personas con dificultades de techo. El mayor peligro estaba en la bajada de peque\u00f1os esteros en sectores de Las Coimas, Quebrada y Sahond\u00e9, que generaron mayores caudales. Tuvimos que extremar nuestras acciones arrendando maquinaria. En un momento tuvimos cuatro retroexcavadoras funcionando simult\u00e1neamente en distintos puntos\u201d, expres\u00f3 el alcalde.<br \/>\nPor otro lado, problemas con un poste de electricidad que cedi\u00f3 en Piguch\u00e9n y el peligro de un pretil construido sin permiso cerca de la Escuela Renacer, fueron resueltos oportunamente. Se destac\u00f3 la labor de la Oficina de Emergencia comunal que trabaja arduamente desde la tarde del mi\u00e9rcoles en todos los sectores.<br \/>\nEl edil putaendino resalt\u00f3, adem\u00e1s, la labor preventiva que viene realizando el municipio desde enero de este a\u00f1o. \u201cHemos arrendado m\u00e1quinas para encausar esteros en Guzmanes, Quebrada de Herrera, Granallas, etc. y eso nos ayud\u00f3 a que no hubiera desbordes. Tambi\u00e9n cerca de 200 familias de escasos recursos comenzaron a trabajar en mejorar sus viviendas, fundamentalmente sus techos y ayudamos en esa tarea. Logramos minimizar los da\u00f1os con este tipo de medidas hechas con anticipaci\u00f3n\u201d.<br \/>\nSobre la crecida en el r\u00edo, actualmente se trabaja para evitar que un brazo del afluente llegue hasta el Parque Municipal. La Oficina de Emergencia atender\u00e1 todo el fin de semana y el Liceo Manuel Mar\u00edn Fritis qued\u00f3 destinado como eventual albergue si es el temporal contin\u00faa y deja familias damnificadas.<br \/>\n\u201cLa lluvia es una bendici\u00f3n para Putaendo\u201d, concluy\u00f3 Reyes, debido a que el agua ca\u00edda sirve para mitigar la sequ\u00eda que ha afectado por a\u00f1os a la comuna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notorias medidas preventivas, atenci\u00f3n oportuna y problemas menores marcaron los d\u00edas del temporal. \u201cLa lluvia es una bendici\u00f3n para Putaendo\u201d, destac\u00f3 la m\u00e1xima autoridad comunal PUTAENDO.- Un balance positivo en l\u00edneas generales&#8230;<\/p>\n","protected":false},"author":482,"featured_media":60811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-60810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Foto-Rio-Frente-a-Parque-Municipal.jpg?fit=530%2C350&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=60810"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/60811"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=60810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=60810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=60810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}