{"id":60822,"date":"2015-08-10T09:30:27","date_gmt":"2015-08-10T12:30:27","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=60822"},"modified":"2015-08-10T09:30:27","modified_gmt":"2015-08-10T12:30:27","slug":"afectados-insisten-que-ocurrio-un-desastre-ecologico-en-vertedero-la-hormiga","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/afectados-insisten-que-ocurrio-un-desastre-ecologico-en-vertedero-la-hormiga\/","title":{"rendered":"Afectados insisten que ocurri\u00f3 un desastre ecol\u00f3gico en vertedero La Hormiga"},"content":{"rendered":"<figure id=\"attachment_60823\" aria-describedby=\"caption-attachment-60823\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Relleno-sanitario-1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-60823 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Relleno-sanitario-1-300x198.jpg?resize=300%2C198\" alt=\"As\u00ed se ve el lugar 24 horas despu\u00e9s del accidente, las c\u00e1rcavas del derrumbe del morro de basura.\" width=\"300\" height=\"198\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Relleno-sanitario-1.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Relleno-sanitario-1.jpg?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Relleno-sanitario-1.jpg?resize=227%2C150&amp;ssl=1 227w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Relleno-sanitario-1.jpg?resize=400%2C264&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Relleno-sanitario-1.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-60823\" class=\"wp-caption-text\">As\u00ed se ve el lugar 24 horas despu\u00e9s del accidente, las c\u00e1rcavas del derrumbe del morro de basura.<\/figcaption><\/figure>\n<p>A 24 horas del incidente ocurrido quebrada abajo del vertedero La Hormiga, los hermanos Olmedo volvieron a registrar en im\u00e1genes las consecuencias de las \u00faltimas lluvias. Seg\u00fan indicaron a trav\u00e9s de un comunicado, lo encontrado super\u00f3 con creces lo apreciado el primer d\u00eda, ya que el agua barrosa ocultaba mucho de lo que qued\u00f3 expuesto cuando baj\u00f3 el caudal. El comunicado se\u00f1ala textualmente:<br \/>\nEs as\u00ed que se pudo observar desde las alturas el g\u00e9nesis de lo sucedido, al menos el origen en parte de la basura que fue a dar al cauce del estero, posteriormente a los canales de regad\u00edo y al predio de los hermanos Olmedo y as\u00ed sucesivamente quebrada abajo hasta qui\u00e9n sabe d\u00f3nde.<br \/>\nEn la parte delantera del relleno, existe un gran morro de desperdicios, el cual fue socavado por la gran cantidad de agua acumulada en la abundante lluvia del d\u00eda jueves 6. Esta c\u00e1rcava abierta al morro de basura se transform\u00f3 en el transportador en cascada de gran cantidad de material que posteriormente termin\u00f3 en el cauce del estero que no est\u00e1 a m\u00e1s de 30 metros del morro, sin ninguna protecci\u00f3n ni separaci\u00f3n que impida su ca\u00edda al lecho en casos como \u00e9ste.<br \/>\nEs all\u00ed donde vale preguntarse si el proyecto es coherente, ya que estamos hablando de gran cantidad de basura que proviene de todo tipo de fuentes, ya sean industriales, domiciliarias, y hospitalarias, por lo tanto debiera haber un cuidado infalible al respecto de su manejo. Y parece, al menos riesgoso, que el cauce del estero de la Quebrada Muerta, que es el desaguador natural de todo este rinc\u00f3n convertido en Relleno Sanitario, tenga su salida conectada al canal de regad\u00edo, lo cual, en vez de mitigar alguna situaci\u00f3n de emergencia, sirve de conductor para ampliar la contaminaci\u00f3n por medio del propio canal de regad\u00edo a muchos predios agr\u00edcolas quebrada abajo. Poniendo en riesgo el mismo funcionamiento del canal como tal.<br \/>\nFrancisco Olmedo manifest\u00f3 su molestia contra la actitud que ha tenido la empresa: \u201cLa empresa en vez de admitir su falla y solucionar de una vez su mal funcionamiento, ha intentado desmentir lo indesmentible y confundir a la opini\u00f3n p\u00fablica con comunicados que no se apegan a la realidad, y adem\u00e1s hubo un medio de comunicaci\u00f3n radial que yo pensaba que era serio, y que neg\u00f3 lo sucedido con claras intenciones de confundir a la opini\u00f3n p\u00fablica. Lo bueno es que subimos el video a las redes sociales y en 24 horas ya ten\u00eda sobre 12.000 visitas, y adem\u00e1s todos los otros medios del valle publicaron la noticia donde queda demostrado que lo que denunciamos es la verdad y lo comprobaremos en tribunales\u201d.<br \/>\nEn resumen, da para pensar que el personal a cargo del relleno en el momento de la crisis, no se preocup\u00f3 de mitigarla, sino que sigui\u00f3 recibiendo camiones con basura, y trabajando normalmente cuando a plena vista la situaci\u00f3n era anormal. Con 500 metros cuadrados de nylon para cubrir el morro de basura y maquinaria haciendo un muro de contenci\u00f3n que impidiera el paso de cualquier derrumbe al estero, tal vez nada de esto hubiera sucedido. Por otra parte, el equipo de relaciones p\u00fablicas del relleno tampoco hizo una labor adecuada, amenazando al autor del reportaje con demanda por alarma p\u00fablica y exigiendo el silencio, cuando hubiera sido mucho m\u00e1s f\u00e1cil aceptar el error de manejo, ofrecer una cuadrilla de limpieza a los hermanos Olmedo y una cantidad de camiones con tierra para recuperar la capa laborable de la parcela y qui\u00e9n sabe si esa mitigaci\u00f3n hubiera calmado los \u00e1nimos. Una empresa cuando proyecta grandeza debe actuar con grandeza.<br \/>\n<strong>Roberto Mercado Aced<\/strong><\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"640\" data-carousel-extra='null' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 640px; height: 213px;\" data-original-width=\"640\" data-original-height=\"213\" > <div class=\"gallery-group images-1\" style=\"width: 320px; height: 213px;\" data-original-width=\"320\" data-original-height=\"213\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/eltrabajo.cl\/portal\/afectados-insisten-que-ocurrio-un-desastre-ecologico-en-vertedero-la-hormiga\/canal-de-regadio-contaminado\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"209\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"60824\" data-orig-file=\"https:\/\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg\" data-orig-size=\"530,350\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1438968326&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Canal de regadio contaminado\" data-image-description=\"&lt;p&gt;As\u00ed se ve el canal de regad\u00edo lleno de desperdicios, comprobando que s\u00ed hubo contaminaci\u00f3n.&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg?fit=300%2C198&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg?fit=530%2C350&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg?w=316&#038;h=209&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg?w=530&amp;ssl=1 530w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg?resize=227%2C150&amp;ssl=1 227w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Canal-de-regadio-contaminado.jpg?resize=400%2C264&amp;ssl=1 400w\" width=\"316\" height=\"209\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"209\" itemprop=\"http:\/\/schema.org\/image\" title=\"Canal de regadio contaminado\" alt=\"As\u00ed se ve el canal de regad\u00edo lleno de desperdicios, comprobando que s\u00ed hubo contaminaci\u00f3n.\" style=\"width: 316px; height: 209px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> As\u00ed se ve el canal de regad\u00edo lleno de desperdicios, comprobando que s\u00ed hubo contaminaci\u00f3n. <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 320px; height: 213px;\" data-original-width=\"320\" data-original-height=\"213\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/eltrabajo.cl\/portal\/afectados-insisten-que-ocurrio-un-desastre-ecologico-en-vertedero-la-hormiga\/predio-hermanos-olmedo\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"209\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"60825\" data-orig-file=\"https:\/\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg\" data-orig-size=\"530,350\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1438966416&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Predio Hermanos Olmedo\" data-image-description=\"&lt;p&gt;El predio de hermanos Olmedo lleno de basuras y erosionada su tierra de labranza.&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg?fit=300%2C198&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg?fit=530%2C350&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg?w=316&#038;h=209&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg?w=530&amp;ssl=1 530w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg?resize=227%2C150&amp;ssl=1 227w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Predio-Hermanos-Olmedo.jpg?resize=400%2C264&amp;ssl=1 400w\" width=\"316\" height=\"209\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"209\" itemprop=\"http:\/\/schema.org\/image\" title=\"Predio Hermanos Olmedo\" alt=\"El predio de hermanos Olmedo lleno de basuras y erosionada su tierra de labranza.\" style=\"width: 316px; height: 209px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> El predio de hermanos Olmedo lleno de basuras y erosionada su tierra de labranza. <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>A 24 horas del incidente ocurrido quebrada abajo del vertedero La Hormiga, los hermanos Olmedo volvieron a registrar en im\u00e1genes las consecuencias de las \u00faltimas lluvias. Seg\u00fan indicaron a trav\u00e9s de un&#8230;<\/p>\n","protected":false},"author":482,"featured_media":60823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-60822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Relleno-sanitario-1.jpg?fit=530%2C350&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=60822"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/60823"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=60822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=60822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=60822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}