{"id":60837,"date":"2015-08-11T09:39:30","date_gmt":"2015-08-11T12:39:30","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=60837"},"modified":"2015-08-11T09:39:30","modified_gmt":"2015-08-11T12:39:30","slug":"construyen-moderna-sala-de-clases-para-parvulos-en-escuela-jorge-barros-de-palomar","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/construyen-moderna-sala-de-clases-para-parvulos-en-escuela-jorge-barros-de-palomar\/","title":{"rendered":"Construyen moderna sala de clases para p\u00e1rvulos en Escuela Jorge Barros de Palomar"},"content":{"rendered":"<figure id=\"attachment_60838\" aria-describedby=\"caption-attachment-60838\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Nuevo-jardin-infantil.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-60838 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Nuevo-jardin-infantil-300x198.jpg?resize=300%2C198\" alt=\"Loreto Galdames, directora de Obras de la Municipalidad de Panquehue.\" width=\"300\" height=\"198\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Nuevo-jardin-infantil.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Nuevo-jardin-infantil.jpg?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Nuevo-jardin-infantil.jpg?resize=227%2C150&amp;ssl=1 227w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Nuevo-jardin-infantil.jpg?resize=400%2C264&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Nuevo-jardin-infantil.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-60838\" class=\"wp-caption-text\">Loreto Galdames, directora de Obras de la Municipalidad de Panquehue.<\/figcaption><\/figure>\n<ul>\n<li><strong>De acuerdo a lo informado por la Directora de Obras de la Municipalidad, Loreto Galdames, se trata de un proyecto que demanda una inversi\u00f3n de 41 millones de pesos.<\/strong><\/li>\n<\/ul>\n<p><strong>PANQUEHUE.<\/strong>&#8211; Un 30 % de avance registran las obras de construcci\u00f3n de una moderna sala de clases para los p\u00e1rvulos de la Escuela Jorge Barros de la localidad de Palomar en la comuna de Panquehue.<br \/>\nDe acuerdo a lo informado por la Directora de Obras de la Municipalidad, Loreto Galdames, se trata de un proyecto que demand\u00f3 una inversi\u00f3n de 41.359.023 pesos, que consideran la construcci\u00f3n de una sala de 59 M\u00b2, la que incluye servicios higi\u00e9nicos y bodega, con una capacidad para 24 menores.<br \/>\nEl proyecto que es ejecutado por la empresa M M Ingenier\u00eda y Construcciones Ltda, es financiado a trav\u00e9s del Programa de Mejoramiento Urbano (PMU), bajo la l\u00ednea emergencia FIE.<br \/>\n\u201cSe trata de una nueva sala de clases en alba\u00f1iler\u00eda para los ni\u00f1os de k\u00ednder de la escuela Jorge Barros. El proyecto del mismo modo considera mejorar los servicios higi\u00e9nicos existentes de los p\u00e1rvulos.<br \/>\nLa obra lleva un avance del 30 %, ya est\u00e1n los muros de alba\u00f1iler\u00eda levantados, ahora se est\u00e1 trabajando en los moldajes para el uso del hormig\u00f3n en los pilares y cadenas, por el momento las obras est\u00e1n un poco detenidas debido a la situaci\u00f3n de las lluvias, pero se est\u00e1 trabajando al interior de la sala existente, con la aplicaci\u00f3n de la pintura y el cambio de cer\u00e1mica\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo a lo informado por la Directora de Obras de la Municipalidad, Loreto Galdames, se trata de un proyecto que demanda una inversi\u00f3n de 41 millones de pesos. PANQUEHUE.&#8211; Un 30&#8230;<\/p>\n","protected":false},"author":482,"featured_media":60838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-60837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Nuevo-jardin-infantil.jpg?fit=530%2C350&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=60837"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/60838"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=60837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=60837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=60837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}