{"id":60909,"date":"2015-08-12T10:43:16","date_gmt":"2015-08-12T13:43:16","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=60909"},"modified":"2015-08-12T10:43:16","modified_gmt":"2015-08-12T13:43:16","slug":"san-felipe-basket-bate-records-y-se-convierte-en-el-dueno-absoluto-de-la-libcentro-b","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/san-felipe-basket-bate-records-y-se-convierte-en-el-dueno-absoluto-de-la-libcentro-b\/","title":{"rendered":"San Felipe Basket bate r\u00e9cords y se convierte en el due\u00f1o absoluto de la Libcentro B"},"content":{"rendered":"<figure id=\"attachment_60910\" aria-describedby=\"caption-attachment-60910\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-15.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-60910 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-15-300x197.jpg?resize=300%2C197\" alt=\"El equipo U15 de San Felipe Basket consigui\u00f3 el t\u00edtulo al ganar el cuadrangular final jugado en el gimnasio del club Sergio Ceppi.\" width=\"300\" height=\"197\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-15.jpg?resize=300%2C197&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-15.jpg?resize=200%2C131&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-15.jpg?resize=228%2C150&amp;ssl=1 228w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-15.jpg?resize=400%2C263&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-15.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-60910\" class=\"wp-caption-text\">El equipo U15 de San Felipe Basket consigui\u00f3 el t\u00edtulo al ganar el cuadrangular final jugado en el gimnasio del club Sergio Ceppi.<\/figcaption><\/figure>\n<ul>\n<li><strong>Los quintetos U13, U15 y U17 comandados t\u00e9cnicamente por Felipe Rodr\u00edguez, Vladimir Morales y Marco Cueto impusieron un registro que puede ser hist\u00f3rico en el baloncesto nacional.<\/strong><\/li>\n<\/ul>\n<p>Los t\u00edtulos obtenidos en la capital durante el fin de semana pasado por sus quintetos masculinos U15 y U17 solo vinieron a ratificar y confirmar el dominio que desde el inicio mismo de la competencia tuvo San Felipe Basket en la Libcentro B, liga en la cual la instituci\u00f3n deportiva sanfelipe\u00f1a impuso un record que dif\u00edcilmente podr\u00e1 ser superado en el futuro.<br \/>\nLas cosas no eran simples para San Felipe, debido a que como visitantes y rivales de muchos debieron hacer frente a los cuadrangulares finales en las series U15 y U17, cosa que claramente pas\u00f3 a un segundo plano porque desde el inicio mismo de cada mini torneo los aconcag\u00fcinos pisaron el acelerador a fondo, imponiendo un ritmo demoledor con el cual aplastaron a quien se puso por delante.<br \/>\nAunque las dos historias tuvieron un final feliz, cada una de ellas tuvo un derrotero distinto, ya que los escenarios (gimnasios) en los cuales San Felipe Basket grit\u00f3 campe\u00f3n estaban en distintos puntos de la regi\u00f3n Metropolitana.<\/p>\n<p><strong>U15<\/strong><br \/>\nLos menores de 15 a\u00f1os ten\u00edan que hacer frente a una tarea tit\u00e1nica, porque no era menor el hecho que Sergio Ceppi fuera el equipo organizador del cuadrangular final. En su casa los capitalinos casi siempre hacen pesar su condici\u00f3n de local, lo que los transformaba en grandes favoritos para ganar la corona.<br \/>\nEn el primer duelo y tal como se supon\u00eda, San Felipe se impuso a B\u00e1squetbol de la Universidad de Chile, triunfo que le dio los pasajes de manera directa a la final en la cual choc\u00f3 con Sergio Ceppi, el que sin mayores inconvenientes hab\u00eda superado a la Universidad Cat\u00f3lica.<br \/>\nEn la final, frente a frente estaban los dos mejores quintetos de toda la fase regular, lo que anticipaba un partido re\u00f1ido e intenso, en el cual San Felipe desde la primera chicharra marc\u00f3 diferencias importantes, al punto que termin\u00f3 ganando el duelo de manera muy c\u00f3moda por un claro 45 a 63 a su favor.<br \/>\nCuando se juega a un nivel superlativo, cuesta mucho centrarse en actuaciones individuales porque es obvio que el equipo en su conjunto brill\u00f3, pero igual hay que hacer menci\u00f3n al trabajo brillante de Tomas Gonz\u00e1lez, Lino S\u00e1ez, Gabriel Soto y Sim\u00f3n Salgado, los que junto al resto de sus compa\u00f1eros bridaron una verdadera exhibici\u00f3n de b\u00e1squetbol que los llev\u00f3 al olimpo, ese lugar reservado s\u00f3lo para los escogidos.<\/p>\n<p><strong>U17<\/strong><br \/>\nLa historia en la divisi\u00f3n U17 era igualmente compleja, esto porque en el primer partido de cuadrangular que tuvo como escenario el gimnasio del Stadio Italiano, en el primer partido debieron medirse con el Prat de San Felipe y el \u2018cl\u00e1sico\u2019 qued\u00f3 en manos de San Felipe Basket, conjunto que sac\u00f3 16 puntos de ventaja lo que le permiti\u00f3 instalarse en la gran final, con un envi\u00f3n an\u00edmico importante.<br \/>\nAlcanzar la estrella de su categor\u00eda, no era nada sencillo, ya que el obst\u00e1culo a superar era el Club Palestino, un equipo que llegaba invicto al juego m\u00e1s importante e infartante de todo el torneo. El pleito tal como se anticipaba, solo se defini\u00f3 en los \u00faltimos minutos y San Felipe logr\u00f3 sacarlo adelante gracias a la actitud de sus jugadores que sabiendo que estaban golpeando las puertas de la historia, batallaron hasta hacerlo suyo por un ajustado 74 a 71.<br \/>\nEn el triunfo del team comandado por el profesor Vladimir Morales, sobresalieron Thomas Gonz\u00e1lez, Lino S\u00e1ez, Basti\u00e1n Soto, Mat\u00edas Porras e Iv\u00e1n Sandoval quien fue el goleador con 19 puntos, pero ante tama\u00f1a haza\u00f1a es injusto detenerse en algunas individualidades porque el equipo funcion\u00f3 como un reloj perfectamente sincronizado, ya que de otra forma hubiera sido imposible vencer al gigante de colonia \u00e1rabe.<br \/>\nEn s\u00edntesis dos t\u00edtulos se sumaron al que d\u00edas atr\u00e1s hab\u00edan conseguido los U13, algo que no tiene precedentes en la Libcentro, liga en la cual San Felipe Basket dej\u00f3 muy en claro que \u2018En la Ciudad Donde Vibra M\u00e1s Fuerte La Vida\u2019 el baloncesto es el rey.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"640\" data-carousel-extra='null' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 640px; height: 211px;\" data-original-width=\"640\" data-original-height=\"211\" > <div class=\"gallery-group images-1\" style=\"width: 320px; height: 211px;\" data-original-width=\"320\" data-original-height=\"211\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/eltrabajo.cl\/portal\/san-felipe-basket-bate-records-y-se-convierte-en-el-dueno-absoluto-de-la-libcentro-b\/san-felipe-u-17\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"207\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"60911\" data-orig-file=\"https:\/\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg\" data-orig-size=\"530,348\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"san felipe u 17\" data-image-description=\"&lt;p&gt;Los U17 de San Felipe Basket, para llegar a lo m\u00e1s alto superaron en la final al Club Palestino, cuadro que hasta ese duelo ostentaba un invicto que los sanfelipe\u00f1os hicieron trizas.&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg?fit=300%2C197&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg?fit=530%2C348&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg?w=316&#038;h=207&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg?w=530&amp;ssl=1 530w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg?resize=200%2C131&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg?resize=300%2C197&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg?resize=228%2C150&amp;ssl=1 228w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-17.jpg?resize=400%2C263&amp;ssl=1 400w\" width=\"316\" height=\"207\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"207\" itemprop=\"http:\/\/schema.org\/image\" title=\"san felipe u 17\" alt=\"Los U17 de San Felipe Basket, para llegar a lo m\u00e1s alto superaron en la final al Club Palestino, cuadro que hasta ese duelo ostentaba un invicto que los sanfelipe\u00f1os hicieron trizas.\" style=\"width: 316px; height: 207px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Los U17 de San Felipe Basket, para llegar a lo m\u00e1s alto superaron en la final al Club Palestino, cuadro que hasta ese duelo ostentaba un invicto que los sanfelipe\u00f1os hicieron trizas. <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 320px; height: 211px;\" data-original-width=\"320\" data-original-height=\"211\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/eltrabajo.cl\/portal\/san-felipe-basket-bate-records-y-se-convierte-en-el-dueno-absoluto-de-la-libcentro-b\/tecnicos-san-felipe\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"316\"> <meta itemprop=\"height\" content=\"207\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"60912\" data-orig-file=\"https:\/\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg\" data-orig-size=\"530,348\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"tecnicos san felipe\" data-image-description=\"&lt;p&gt;Bajo la batuta de los entrenadores Felipe Rodr\u00edguez y Vladimir Morales (en la imagen) m\u00e1s el aporte de Marco Cueto, San Felipe Basket se adue\u00f1\u00f3 de las series formativas de la Libcentro B.&lt;\/p&gt; \" data-medium-file=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg?fit=300%2C197&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg?fit=530%2C348&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg?w=316&#038;h=207&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg?w=530&amp;ssl=1 530w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg?resize=200%2C131&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg?resize=300%2C197&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg?resize=228%2C150&amp;ssl=1 228w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/tecnicos-san-felipe.jpg?resize=400%2C263&amp;ssl=1 400w\" width=\"316\" height=\"207\" loading=\"lazy\" data-original-width=\"316\" data-original-height=\"207\" itemprop=\"http:\/\/schema.org\/image\" title=\"tecnicos san felipe\" alt=\"Bajo la batuta de los entrenadores Felipe Rodr\u00edguez y Vladimir Morales (en la imagen) m\u00e1s el aporte de Marco Cueto, San Felipe Basket se adue\u00f1\u00f3 de las series formativas de la Libcentro B.\" style=\"width: 316px; height: 207px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Bajo la batuta de los entrenadores Felipe Rodr\u00edguez y Vladimir Morales (en la imagen) m\u00e1s el aporte de Marco Cueto, San Felipe Basket se adue\u00f1\u00f3 de las series formativas de la Libcentro B. <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los quintetos U13, U15 y U17 comandados t\u00e9cnicamente por Felipe Rodr\u00edguez, Vladimir Morales y Marco Cueto impusieron un registro que puede ser hist\u00f3rico en el baloncesto nacional. Los t\u00edtulos obtenidos en la&#8230;<\/p>\n","protected":false},"author":482,"featured_media":60910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-60909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/san-felipe-u-15.jpg?fit=530%2C348&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=60909"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/60910"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=60909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=60909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=60909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}