{"id":60974,"date":"2015-08-14T09:22:45","date_gmt":"2015-08-14T12:22:45","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=60974"},"modified":"2015-08-14T09:22:45","modified_gmt":"2015-08-14T12:22:45","slug":"esperan-posible-reapertura-de-paso-internacional-cristo-redentor","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/esperan-posible-reapertura-de-paso-internacional-cristo-redentor\/","title":{"rendered":"Esperan posible reapertura de paso internacional Cristo Redentor"},"content":{"rendered":"<figure id=\"attachment_60975\" aria-describedby=\"caption-attachment-60975\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Paso-cristo-redentor.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-60975 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Paso-cristo-redentor-300x197.jpg?resize=300%2C197\" alt=\"Se espera que durante el d\u00eda de hoy viernes, las condiciones clim\u00e1ticas permitan reabrir el t\u00fanel internacional. \" width=\"300\" height=\"197\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Paso-cristo-redentor.jpg?resize=300%2C197&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Paso-cristo-redentor.jpg?resize=200%2C131&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Paso-cristo-redentor.jpg?resize=228%2C150&amp;ssl=1 228w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Paso-cristo-redentor.jpg?resize=400%2C263&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Paso-cristo-redentor.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-60975\" class=\"wp-caption-text\">Se espera que durante el d\u00eda de hoy viernes, las condiciones clim\u00e1ticas permitan reabrir el t\u00fanel internacional.<\/figcaption><\/figure>\n<ul>\n<li><strong>Gobernadora valor\u00f3 la medida de bajar a todo el personal del complejo por la ocurrencia de cuatro avalanchas.<\/strong><\/li>\n<\/ul>\n<p><strong>LOS ANDES<\/strong>.- La gobernadora provincial Mar\u00eda Victoria Rodr\u00edguez, indic\u00f3 que dependiendo de las condiciones clim\u00e1ticas, hoy viernes podr\u00eda ser reabierto finalmente el paso internacional Cristo Redentor.<br \/>\nLa autoridad coment\u00f3 que la direcci\u00f3n de Vialidad ha estado trabajando arduamente estos d\u00edas en el despeje del camino, \u201cya que abrieron la ruta para que en primera instancia Chilquinta pudiera reinstalar los postes y poder restablecer el sistema el\u00e9ctrico del complejo\u201d.<br \/>\n\u201cTambi\u00e9n hay que agradecer a la Escuela de Alta Monta\u00f1a que contribuy\u00f3 con sus especialistas con el tema de control de avalanchas y todav\u00eda est\u00e1n trabajando en ello, porque con lo sucedido en materia clim\u00e1tica fue muy acertada la medida de bajar a todos los funcionarios del Complejo Los Libertadores, ya que en este temporal pasado hubo cuatro avalanchas detectadas y una de ellas arranco las ca\u00f1er\u00edas de agua del Complejo Los Libertadores\u201d, expuso.<br \/>\nNo obstante, aclar\u00f3 que el complejo se encuentra plenamente operativo pues le fue reparado el sistema de agua potable, la conectividad de Internet, \u201cpero se present\u00f3 un nuevo frente de mal tiempo el cual nos impidi\u00f3 poder abrir como hubi\u00e9ramos deseado este mi\u00e9rcoles o jueves\u201d.<br \/>\nEn cuanto al estado de la ruta, dijo que hay sectores donde cayeron cerca de cuatro metros de nieve y avalanchas de seis metros, \u201clo que ha significado que se ha tenido que estar repasando, es decir que hay que evitar que cuando est\u00e9n los funcionarios trabajando pueda existir un riesgo de avalancha, por lo tanto hay que tomar la precauci\u00f3n previa y gracias al apoyo de la Escuela de Alta Monta\u00f1a hemos realizados estos trabajos de control de avalanchas, lo cual ha disminuido en gran medida la posibilidad de enfrentar este tipo de riesgo\u201d.<br \/>\nIndic\u00f3 adem\u00e1s que a pesar de las avalanchas que se dejaron caer, no hay destrozos en el Sistema Integrado Cristo Redentor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gobernadora valor\u00f3 la medida de bajar a todo el personal del complejo por la ocurrencia de cuatro avalanchas. LOS ANDES.- La gobernadora provincial Mar\u00eda Victoria Rodr\u00edguez, indic\u00f3 que dependiendo de las condiciones&#8230;<\/p>\n","protected":false},"author":482,"featured_media":60975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-60974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/Paso-cristo-redentor.jpg?fit=530%2C348&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=60974"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/60974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/60975"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=60974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=60974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=60974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}