{"id":61230,"date":"2015-08-24T09:09:07","date_gmt":"2015-08-24T12:09:07","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=61230"},"modified":"2015-08-24T09:09:07","modified_gmt":"2015-08-24T12:09:07","slug":"inicio-torneo-de-baby-futbol-interescolar-rural","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/inicio-torneo-de-baby-futbol-interescolar-rural\/","title":{"rendered":"Inici\u00f3 Torneo de Baby F\u00fatbol interescolar Rural"},"content":{"rendered":"<figure id=\"attachment_61231\" aria-describedby=\"caption-attachment-61231\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/TORNEO-BABY-FUTBOL-RURAL.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-61231 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/TORNEO-BABY-FUTBOL-RURAL-300x198.jpg?resize=300%2C198\" alt=\"Durante la semana pasada se dio inicio al Torneo de Baby F\u00fatbol Interescolar Rural, en el que participan equipos de las escuelas Las Vegas, Las Pe\u00f1as, Las Palmas y como invitado, la Escuela Jorge Prieto Letelier.\" width=\"300\" height=\"198\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/TORNEO-BABY-FUTBOL-RURAL.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/TORNEO-BABY-FUTBOL-RURAL.jpg?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/TORNEO-BABY-FUTBOL-RURAL.jpg?resize=228%2C150&amp;ssl=1 228w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/TORNEO-BABY-FUTBOL-RURAL.jpg?resize=400%2C263&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/TORNEO-BABY-FUTBOL-RURAL.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-61231\" class=\"wp-caption-text\">Durante la semana pasada se dio inicio al Torneo de Baby F\u00fatbol Interescolar Rural, en el que participan equipos de las escuelas Las Vegas, Las Pe\u00f1as, Las Palmas y como invitado, la Escuela Jorge Prieto Letelier.<\/figcaption><\/figure>\n<p><strong>LLAY LLAY.<\/strong>&#8211; Un Torneo de Baby F\u00fatbol Interescolar Rural se inici\u00f3 este jueves 20 de agosto. Participan, los equipos de las escuelas: Las Vegas, Las Pe\u00f1as, Las Palmas y como invitado, la Escuela Jorge Prieto Letelier.<br \/>\nEn esta primera fecha jugaron de local, Escuela Las Vegas Vs. Escuela Jorge Prieto Letelier. Seg\u00fan el calendario de actividades, tendr\u00e1n cinco encuentros deportivos m\u00e1s, donde alternadamente jugar\u00e1n como locales y visitantes.<br \/>\nLa actividad tiene como finalidad, incentivar pr\u00e1cticas deportivas en los estudiantes; estrechar lazos de amistad, fortalecer el compa\u00f1erismo y los valores sociales.<\/p>\n<figure id=\"attachment_61232\" aria-describedby=\"caption-attachment-61232\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/BABY-FUTBOL.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-61232 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/BABY-FUTBOL-300x198.jpg?resize=300%2C198\" alt=\"Los ni\u00f1os tienen talleres los d\u00edas mi\u00e9rcoles, y los jueves se est\u00e1n reforzando la parte f\u00edsica.\" width=\"300\" height=\"198\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/BABY-FUTBOL.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/BABY-FUTBOL.jpg?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/BABY-FUTBOL.jpg?resize=227%2C150&amp;ssl=1 227w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/BABY-FUTBOL.jpg?resize=400%2C264&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/BABY-FUTBOL.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-61232\" class=\"wp-caption-text\">Los ni\u00f1os tienen talleres los d\u00edas mi\u00e9rcoles, y los jueves se est\u00e1n reforzando la parte f\u00edsica.<\/figcaption><\/figure>\n<p>Danilo Rubio, director de la Escuela de Las Vegas dijo, \u201cEste es un cuadrangular, que se realiza entre escuelas de microcentro. Queremos retomar la antigua actividad deportiva, que se hab\u00eda perdido. La iniciativa tiene buena recepci\u00f3n por la comunidad educativa, lo que me tiene muy contento\u201d.<br \/>\nEl Microcentro, es donde se agrupan las escuelas de multigrado, que tienen cursos unidos.<br \/>\nDanilo Ram\u00edrez, encargado del Taller de Deportes de la Escuela Las Vegas, indic\u00f3 que \u201clos ni\u00f1os tienen talleres los d\u00edas mi\u00e9rcoles, y los jueves se est\u00e1n reforzando la parte f\u00edsica\u201d.<br \/>\nEl profesor de Educaci\u00f3n F\u00edsica de la Escuela Jorge Prieto Letelier, Johann Espinoza resalt\u00f3 la importancia de poder fortalecer el compa\u00f1erismo y los valores, entre los ni\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LLAY LLAY.&#8211; Un Torneo de Baby F\u00fatbol Interescolar Rural se inici\u00f3 este jueves 20 de agosto. Participan, los equipos de las escuelas: Las Vegas, Las Pe\u00f1as, Las Palmas y como invitado, la&#8230;<\/p>\n","protected":false},"author":482,"featured_media":61231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-61230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/08\/TORNEO-BABY-FUTBOL-RURAL.jpg?fit=530%2C349&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/61230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=61230"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/61230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/61231"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=61230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=61230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=61230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}