{"id":61802,"date":"2015-09-09T09:15:18","date_gmt":"2015-09-09T12:15:18","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=61802"},"modified":"2015-09-09T09:15:18","modified_gmt":"2015-09-09T12:15:18","slug":"ministerio-del-medio-ambiente-realiza-taller-a-municipales-de-la-provincia","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/ministerio-del-medio-ambiente-realiza-taller-a-municipales-de-la-provincia\/","title":{"rendered":"Ministerio del Medio Ambiente realiza taller a municipales de la Provincia"},"content":{"rendered":"<figure id=\"attachment_61803\" aria-describedby=\"caption-attachment-61803\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/09\/Taller-municipal.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-61803 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/09\/Taller-municipal-300x198.jpg?resize=300%2C198\" alt=\"Del taller participaron Mauricio Curaz, Prodesal; Oscar Mar\u00edn, Scam Municipal; Claudio Tapia, Ministerio Medio Ambiente; Nelson Leiva Asemuch y Juan Vargas, Comit\u00e9 Paritario.\" width=\"300\" height=\"198\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/09\/Taller-municipal.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/09\/Taller-municipal.jpg?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/09\/Taller-municipal.jpg?resize=228%2C150&amp;ssl=1 228w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/09\/Taller-municipal.jpg?resize=400%2C263&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/09\/Taller-municipal.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-61803\" class=\"wp-caption-text\">Del taller participaron Mauricio Curaz, Prodesal; Oscar Mar\u00edn, Scam Municipal; Claudio Tapia, Ministerio Medio Ambiente; Nelson Leiva Asemuch y Juan Vargas, Comit\u00e9 Paritario.<\/figcaption><\/figure>\n<p>Este lunes 07 de septiembre fue efectuada una jornada taller entre las15:00 a 17:00 hrs, en el sal\u00f3n de honor municipal. Este taller se denomin\u00f3 \u2018Medici\u00f3n del Carbono en la Gesti\u00f3n Municipal\u2019, y fue realizado por el profesional Claudio Tapia del Ministerio del Medio Ambiente ante un centenar de funcionarios municipales.<br \/>\nEsta actividad se enmarca en el Programa de Mejoramiento de la Gesti\u00f3n 2015 y cumple los objetivos y directrices de la administraci\u00f3n municipal.<br \/>\nNelson Leiva coordinador del PMGM, indic\u00f3 \u201cAgradezco el apoyo del dicho ministerio y de sus docentes, adem\u00e1s, fuera de la charla y experiencia en los distintos municipios del pa\u00eds, se entreg\u00f3 el texto del Manual del Carbono Municipal que nos entrega el conocimiento del gasto energ\u00e9tico que hacemos como personas y como municipio en s\u00ed. Esta jornada tuvo un gran atractivo en cuanto a que como organizaci\u00f3n con estas herramientas apuntemos a la eficiencia energ\u00e9tica y tengamos este sello inserto en nuestras acciones hacia la comunidad\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes 07 de septiembre fue efectuada una jornada taller entre las15:00 a 17:00 hrs, en el sal\u00f3n de honor municipal. Este taller se denomin\u00f3 \u2018Medici\u00f3n del Carbono en la Gesti\u00f3n Municipal\u2019,&#8230;<\/p>\n","protected":false},"author":482,"featured_media":61803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-61802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/09\/Taller-municipal.jpg?fit=530%2C349&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/61802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=61802"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/61802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/61803"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=61802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=61802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=61802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}