{"id":65215,"date":"2015-12-28T14:55:44","date_gmt":"2015-12-28T17:55:44","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=65215"},"modified":"2015-12-28T14:55:44","modified_gmt":"2015-12-28T17:55:44","slug":"tres-detenidos-cuando-intentaban-ingresar-marihuana-por-los-libertadores","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/tres-detenidos-cuando-intentaban-ingresar-marihuana-por-los-libertadores\/","title":{"rendered":"Tres detenidos cuando intentaban ingresar marihuana por Los Libertadores"},"content":{"rendered":"<figure id=\"attachment_65216\" aria-describedby=\"caption-attachment-65216\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-65216 size-medium\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/12\/Droga-argentina-300x197.jpg?resize=300%2C197\" alt=\"La incautaci\u00f3n se efectu\u00f3 en la localidad de Uspallata, gracias a la alerta dada por un perro adiestrado durante un control de rutina. (Foto: Diario Los Andes de Mendoza)\" width=\"300\" height=\"197\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/12\/Droga-argentina.jpg?resize=300%2C197&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/12\/Droga-argentina.jpg?resize=200%2C131&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/12\/Droga-argentina.jpg?resize=228%2C150&amp;ssl=1 228w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/12\/Droga-argentina.jpg?resize=400%2C263&amp;ssl=1 400w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/12\/Droga-argentina.jpg?w=530&amp;ssl=1 530w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-65216\" class=\"wp-caption-text\">La incautaci\u00f3n se efectu\u00f3 en la localidad de Uspallata, gracias a la alerta dada por un perro adiestrado durante un control de rutina. (Foto: Diario Los Andes de Mendoza)<\/figcaption><\/figure>\n<ul>\n<li><strong>Polic\u00eda argentina incaut\u00f3 m\u00e1s de 73 kilos de cannabis sativa ocultos en el doble fondo de un autom\u00f3vil.<\/strong><\/li>\n<\/ul>\n<p><strong>LOS ANDES.<\/strong>&#8211; La Gendarmer\u00eda Argentina detuvo en la localidad de Uspallata a una mujer y dos hombres que pretend\u00edan ingresar a nuestro pa\u00eds m\u00e1s de 73 kilos de marihuana oculta en el doble fondo de un autom\u00f3vil.<br \/>\nSeg\u00fan consigna el diario Los Andes de Mendoza, la detecci\u00f3n de este cargamento se produjo gracias a la alerta dada por un can adiestrado durante un control de rutina cerca de Uspallata.<br \/>\nLa droga se encontraba oculta en el parachoque trasero de un autom\u00f3vil Peugeot 206 con patente trasandina, el cual esperaba burlar los controles policiales tanto en Horcones como en Libertadores.<br \/>\nEn total se incautaron 73 kilos 212 gramos de cannabis sativa agrupados en 87 ladrillos que deb\u00edan ser entregados en la ciudad de Santiago para ser distribuidos luego durante las Fiestas de Fin de a\u00f1o.<br \/>\nLos tres ocupantes del m\u00f3vil, todos de nacionalidad argentina quedaron detenidos y a disposici\u00f3n de la justica de ese pa\u00eds.<br \/>\nEsta incautaci\u00f3n refleja el nivel de contacto de bandas de traficantes chilenas con proveedores de la droga en la zona de Mendoza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polic\u00eda argentina incaut\u00f3 m\u00e1s de 73 kilos de cannabis sativa ocultos en el doble fondo de un autom\u00f3vil. LOS ANDES.&#8211; La Gendarmer\u00eda Argentina detuvo en la localidad de Uspallata a una mujer&#8230;<\/p>\n","protected":false},"author":482,"featured_media":65216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-65215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2015\/12\/Droga-argentina.jpg?fit=530%2C348&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/65215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/482"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=65215"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/65215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/65216"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=65215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=65215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=65215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}