{"id":80797,"date":"2017-08-07T06:03:04","date_gmt":"2017-08-07T10:03:04","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/2017\/?p=80797"},"modified":"2017-08-07T06:03:04","modified_gmt":"2017-08-07T10:03:04","slug":"joven-de-20-anos-de-edad-se-quita-la-vida-colgandose-del-cuello","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/joven-de-20-anos-de-edad-se-quita-la-vida-colgandose-del-cuello\/","title":{"rendered":"Joven de 20 a\u00f1os de edad se quita la vida colg\u00e1ndose del cuello"},"content":{"rendered":"<figure id=\"attachment_80798\" aria-describedby=\"caption-attachment-80798\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-80798\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/08\/HERMAN-ASTUDILLO-ESPINOZA-copia.jpg?resize=580%2C650\" alt=\"Herman Astudillo Espinoza, de 20 a\u00f1os de edad, se quit\u00f3 la vida al interior de su domicilio este viernes.\" width=\"580\" height=\"650\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERMAN-ASTUDILLO-ESPINOZA-copia.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERMAN-ASTUDILLO-ESPINOZA-copia.jpg?resize=134%2C150&amp;ssl=1 134w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERMAN-ASTUDILLO-ESPINOZA-copia.jpg?resize=268%2C300&amp;ssl=1 268w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERMAN-ASTUDILLO-ESPINOZA-copia.jpg?resize=400%2C448&amp;ssl=1 400w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-80798\" class=\"wp-caption-text\">Herman Astudillo Espinoza, de 20 a\u00f1os de edad, se quit\u00f3 la vida al interior de su domicilio este viernes.<\/figcaption><\/figure>\n<ul>\n<li><strong><span style=\"color: #ff0000;\">Tragedia en Poblaci\u00f3n San Francisco de San Felipe:<\/span>\u00a0Las diligencias de la PDI descartaron la intervenci\u00f3n de terceras personas, encontrando una misiva explicando su fatal decisi\u00f3n.<\/strong><\/li>\n<\/ul>\n<p>Como Herman Astudillo Espinoza, de 20 a\u00f1os de edad, fue identificado por la Brigada de Homicidios de la PDI, el joven que se quit\u00f3 la vida al interior de su vivienda en la poblaci\u00f3n San Francisco (Ex 11 de Septiembre) de San Felipe, horrible tragedia que qued\u00f3 al descubierto por sus familiares, quienes adem\u00e1s encontraron una angustiante misiva que explicar\u00eda la fatal decisi\u00f3n.<br \/>\nEl lamentable hecho habr\u00eda ocurrido durante la tarde de este viernes, luego que la familia hallara el cuerpo sin vida del joven, dando cuenta del terrible suceso a los carabineros, quienes se constituyeron en el lugar para esperar las instrucciones del Fiscal de Turno, quien dispuso la concurrencia del personal de la Brigada de Homicidios de la Polic\u00eda de Investigaciones de Los Andes.<br \/>\nEl comisario de la PDI, Gino Guti\u00e9rrez C\u00e1ceres, inform\u00f3 a Diario El Trabajo que tras el an\u00e1lisis externo al cuerpo del fallecido, se descart\u00f3 la intervenci\u00f3n de terceras personas en el deceso.<br \/>\n\u00abFue encontrado por familiares, dej\u00f3 una misiva al respecto y hab\u00eda manifestado su intenci\u00f3n con intentos anteriores, se descarta la intervenci\u00f3n de terceros, esto fue una asfixia por ahorcamiento del tipo suicida, el cuerpo fue remitido al Servicio M\u00e9dico Legal y los antecedentes obran en la Fiscal\u00eda\u00bb.<br \/>\n<strong>Pablo Salinas Sald\u00edas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tragedia en Poblaci\u00f3n San Francisco de San Felipe:\u00a0Las diligencias de la PDI descartaron la intervenci\u00f3n de terceras personas, encontrando una misiva explicando su fatal decisi\u00f3n. Como Herman Astudillo Espinoza, de 20 a\u00f1os&#8230;<\/p>\n","protected":false},"author":1,"featured_media":80799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-80797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERMAN-ASTUDILLO-ESPINOZA.jpg?fit=580%2C348&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/80797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=80797"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/80797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/80799"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=80797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=80797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=80797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}