{"id":81093,"date":"2017-08-21T05:03:45","date_gmt":"2017-08-21T09:03:45","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/2017\/?p=81093"},"modified":"2017-08-21T05:03:45","modified_gmt":"2017-08-21T09:03:45","slug":"microtraficante-a-prision-por-vender-pasta-base-en-villa-el-totoral","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/microtraficante-a-prision-por-vender-pasta-base-en-villa-el-totoral\/","title":{"rendered":"Microtraficante a prisi\u00f3n por vender pasta base en Villa El Totoral"},"content":{"rendered":"<figure id=\"attachment_81094\" aria-describedby=\"caption-attachment-81094\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-81094\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/08\/PASTA-BASE-TOTORAL.jpg?resize=580%2C348\" alt=\"La Brigada Microtr\u00e1fico Cero de la PDI incaut\u00f3 pasta base y dinero en efectivo desde un departamento de Villa El Totoral de San Felipe.\" width=\"580\" height=\"348\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/PASTA-BASE-TOTORAL.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/PASTA-BASE-TOTORAL.jpg?resize=200%2C120&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/PASTA-BASE-TOTORAL.jpg?resize=300%2C180&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/PASTA-BASE-TOTORAL.jpg?resize=250%2C150&amp;ssl=1 250w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/PASTA-BASE-TOTORAL.jpg?resize=400%2C240&amp;ssl=1 400w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-81094\" class=\"wp-caption-text\">La Brigada Microtr\u00e1fico Cero de la PDI incaut\u00f3 pasta base y dinero en efectivo desde un departamento de Villa El Totoral de San Felipe.<\/figcaption><\/figure>\n<ul>\n<li><strong><span style=\"color: #ff0000;\">Operativo encabezado por la PDI:\u00a0<\/span>Tras denuncias se efectu\u00f3 un allanamiento en el domicilio de la imputada, quien fue detenida junto a su yerno por el delito de Microtr\u00e1fico de drogas.<\/strong><\/li>\n<\/ul>\n<p>Un total de 32 gramos de pasta base de coca\u00edna y $69.000 en efectivo, fue el resultado de un allanamiento efectuado por el Grupo Microtr\u00e1fico Cero de la Polic\u00eda de Investigaciones al interior de departamento en Villa El Totoral de San Felipe, resultando una mujer y su yerno detenidos por este delito.<br \/>\nTras una orden a investigar de la Fiscal\u00eda por denuncias a esta Polic\u00eda, arrojaron como resultado la aparente venta il\u00edcita de drogas desde este inmueble donde se almacenaban 155 papelinas de coca\u00edna base y el dinero en efectivo, evidencias que fueron incautadas tras una orden judicial de entrada y registro al domicilio.<br \/>\nCon las pruebas obtenidas result\u00f3 detenida una mujer identificada como Carolina A.A., de 43 a\u00f1os de edad, quien mantiene antecedentes delictuales por este mismo il\u00edcito y su yerno de iniciales C.M.M.S., de 20 a\u00f1os de edad, quienes fueron derivados hasta el Juzgado de Garant\u00eda de San Felipe para ser formalizados por este delito.<br \/>\nLa Fiscal\u00eda solicit\u00f3 para la imputada debido a su prontuario delictual, la m\u00e1xima cautelar de Prisi\u00f3n Preventiva por representar un serio peligro para la salud de la sociedad, medida que fue aceptada por el juez de garant\u00eda, ordenando el traslado de la acusada hasta el Centro de Cumplimiento Penitenciario Femenino de Los Andes mientras se investiga el caso.<br \/>\nEn tanto, para el imputado el tribunal orden\u00f3 dejarlo en libertad bajo las cautelares de Firma Mensual en Carabineros y Prohibici\u00f3n de salir del pa\u00eds.<br \/>\n<strong>Pablo Salinas Sald\u00edas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Operativo encabezado por la PDI:\u00a0Tras denuncias se efectu\u00f3 un allanamiento en el domicilio de la imputada, quien fue detenida junto a su yerno por el delito de Microtr\u00e1fico de drogas. Un total&#8230;<\/p>\n","protected":false},"author":1,"featured_media":81094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-81093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/PASTA-BASE-TOTORAL.jpg?fit=580%2C348&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=81093"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/81094"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=81093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=81093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=81093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}