{"id":81100,"date":"2017-08-21T05:05:06","date_gmt":"2017-08-21T09:05:06","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/2017\/?p=81100"},"modified":"2017-08-21T05:05:06","modified_gmt":"2017-08-21T09:05:06","slug":"roban-equipo-de-enlace-de-radio-calypso-en-cerro-punta-el-olivo","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/roban-equipo-de-enlace-de-radio-calypso-en-cerro-punta-el-olivo\/","title":{"rendered":"Roban equipo de enlace de Radio Calypso en Cerro Punta El Olivo"},"content":{"rendered":"<figure id=\"attachment_81101\" aria-describedby=\"caption-attachment-81101\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-81101\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/08\/Omar-garate..jpg?resize=580%2C348\" alt=\"Omar G\u00e1rate due\u00f1o de Radio Calypso, cuyos equipos fueron robados desde Cerro Punta El Olivo.\" width=\"580\" height=\"348\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/Omar-garate..jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/Omar-garate..jpg?resize=200%2C120&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/Omar-garate..jpg?resize=300%2C180&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/Omar-garate..jpg?resize=250%2C150&amp;ssl=1 250w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/Omar-garate..jpg?resize=400%2C240&amp;ssl=1 400w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-81101\" class=\"wp-caption-text\">Omar G\u00e1rate due\u00f1o de Radio Calypso, cuyos equipos fueron robados desde Cerro Punta El Olivo.<\/figcaption><\/figure>\n<ul>\n<li><span style=\"color: #ff0000;\"><strong>Empresario Omar G\u00e1rate sospecha de personas cercanas a los medios:<\/strong><\/span><\/li>\n<\/ul>\n<p>El empresario radial Omar Garate, conocido popularmente como Omarcito, sufri\u00f3 el robo de cuatro equipos de su emisora Radio Calypso, que en San Felipe funciona en el 90.7 de la FM. Los equipos se encontraban instalados Cerro Punta El Olivo junto a otros correspondientes a varios medios locales y nacionales.<br \/>\n\u00abDentro de la planta transmisora hay otros medios de comunicaci\u00f3n de la zona y esto es muy raro, lo que ocurri\u00f3 es muy raro, porque no se violent\u00f3, no se hizo tira ning\u00fan candado ni chapa, se abri\u00f3 con llave y me robaron mis equipos de la radio que tengo en San Felipe.<br \/>\nCalypso, la 90.7 en FM, hoy quiero denunciar esto, porque no lo hizo \u2018Juanito P\u00e9rez\u2019, esto lo hizo alguien ligado a los medios de comunicaci\u00f3n que seguramente ocuparon la llave para sustraer mis equipos, fueron mis equipos y ah\u00ed hay dos o tres medios m\u00e1s est\u00e1n en estas instalaciones all\u00e1 en el cerro en San Felipe\u00bb, sostuvo Omarcito.<br \/>\nEl empresario se\u00f1al\u00f3 que las transmisiones de la radio cayeron este viernes a eso de las 15:00 horas, antes de esa hora funcionaba todo bien en los estudios, \u00abpero no ten\u00edamos el enlace con el cerro, hoy s\u00e1bado fueron nuestros t\u00e9cnicos, estaba todo cerradito y entrando se dieron cuenta que no estaban nuestros equipos de enlaces, que une el cerro con el estudio que tenemos en San Felipe\u00bb, asegur\u00f3.<br \/>\nEl lugar cuenta con un sistema de seguridad a cargo de la empresa Verisure, que seg\u00fan el empresario y a vista de los hechos no funcion\u00f3.<br \/>\nCont\u00f3 que el transmisor lo apagaron y se llevaron los equipos de radioenlace.<br \/>\nTambi\u00e9n se supone, dijo, hay una sola llave para ingresar al lugar, no hay segundas llaves. Mencion\u00f3 que hoy lunes estampar\u00eda la denuncia correspondiente en los organismos pertinentes. Todo lo sustra\u00eddo fue avaluado en la suma de 2 millones de pesos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empresario Omar G\u00e1rate sospecha de personas cercanas a los medios: El empresario radial Omar Garate, conocido popularmente como Omarcito, sufri\u00f3 el robo de cuatro equipos de su emisora Radio Calypso, que en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":81101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-81100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/Omar-garate..jpg?fit=580%2C348&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=81100"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/81101"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=81100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=81100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=81100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}