{"id":81306,"date":"2017-08-30T05:03:58","date_gmt":"2017-08-30T09:03:58","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/2017\/?p=81306"},"modified":"2017-08-30T05:03:58","modified_gmt":"2017-08-30T09:03:58","slug":"hombre-de-41-anos-resulto-apunalado-en-el-torax-en-confuso-incidente","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/hombre-de-41-anos-resulto-apunalado-en-el-torax-en-confuso-incidente\/","title":{"rendered":"Hombre de 41 a\u00f1os result\u00f3 apu\u00f1alado en el t\u00f3rax en confuso incidente"},"content":{"rendered":"<figure id=\"attachment_81307\" aria-describedby=\"caption-attachment-81307\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-81307\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/08\/HERIDO-ARMA-BLANCA.jpg?resize=580%2C350\" alt=\"Un hombre de 41 a\u00f1os de edad result\u00f3 herido en el t\u00f3rax, debiendo ser asistido en el Hospital de Llay Llay. (Foto Referencial).\" width=\"580\" height=\"350\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERIDO-ARMA-BLANCA.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERIDO-ARMA-BLANCA.jpg?resize=200%2C121&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERIDO-ARMA-BLANCA.jpg?resize=300%2C181&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERIDO-ARMA-BLANCA.jpg?resize=249%2C150&amp;ssl=1 249w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERIDO-ARMA-BLANCA.jpg?resize=400%2C241&amp;ssl=1 400w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-81307\" class=\"wp-caption-text\">Un hombre de 41 a\u00f1os de edad result\u00f3 herido en el t\u00f3rax, debiendo ser asistido en el Hospital de Llay Llay. (Foto Referencial).<\/figcaption><\/figure>\n<ul>\n<li><strong><span style=\"color: #ff0000;\">V\u00edctima declin\u00f3 hacer denuncia ante Carabineros:<\/span>\u00a0El hecho se habr\u00eda originado en el contexto de una ri\u00f1a en la v\u00eda p\u00fablica en Llay Llay, luego que una turba de personas abordara a la v\u00edctima con quien sostuvieron una discusi\u00f3n, mientras un desconocido lo atac\u00f3 propin\u00e1ndole una pu\u00f1alada.<\/strong><\/li>\n<\/ul>\n<p>En un confuso incidente, un hombre de 41 a\u00f1os de edad result\u00f3 herido tras recibir una pu\u00f1alada en el t\u00f3rax, luego que una turba de personas iniciara una ri\u00f1a de proporciones, mientras uno de ellos atac\u00f3 a la v\u00edctima de una estocada en el cuerpo, para luego huir del lugar de los hechos en calle Circunvalaci\u00f3n de la comuna de Llay Llay.<br \/>\nSeg\u00fan la informaci\u00f3n proporcionada por Carabineros que tom\u00f3 conocimiento de los hechos, detalla que el afectado fue derivado alrededor de las 04:45 horas de la madrugada de este domingo, hasta el Hospital San Francisco de esa localidad, indicando que un grupo de hombres y mujeres, quienes transitaban por la v\u00eda p\u00fablica, lo abordaron mientras la v\u00edctima se encontraba dentro de su veh\u00edculo estacionado.<br \/>\nAparentemente en esos instantes se habr\u00eda iniciado una discusi\u00f3n entre el afectado y el grupo de desconocidos, quienes habr\u00edan comenzado a golpear con los pies el m\u00f3vil, motivando al conductor a descender de su veh\u00edculo para increpar a los sujetos, recibiendo una estocada en el t\u00f3rax, debiendo ser asistido por personal m\u00e9dico.<br \/>\nFuncionarios de Carabineros de la Subcomisar\u00eda de Llay Llay, tras ser informados de lo ocurrido, se trasladaron hasta el centro asistencial para indagar m\u00e1s antecedentes del caso, sin embargo la v\u00edctima de iniciales G.N.C.A. declin\u00f3 realizar la denuncia correspondiente para iniciar la captura del agresor, reportando imprecisos detalles de lo ocurrido.<br \/>\nNo obstante, la polic\u00eda uniformada indic\u00f3 que tras la revisi\u00f3n de las c\u00e1maras de vigilancia municipal, se logr\u00f3 constatar que existen registros audiovisuales del momento de la agresi\u00f3n, donde se lograr\u00eda establecer las identidades de los involucrados en esta ri\u00f1a, entregando el reporte a la Fiscal\u00eda de las diligencias que podr\u00edan abrir una carpeta investigativa.<br \/>\nEn tanto el lesionado salv\u00f3 de ser v\u00edctima de una lesi\u00f3n de gravedad, gracias a que fue asistido a tiempo de la herida producida por arma blanca.<br \/>\n<strong>Pablo Salinas Sald\u00edas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edctima declin\u00f3 hacer denuncia ante Carabineros:\u00a0El hecho se habr\u00eda originado en el contexto de una ri\u00f1a en la v\u00eda p\u00fablica en Llay Llay, luego que una turba de personas abordara a la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":81307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-81306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/08\/HERIDO-ARMA-BLANCA.jpg?fit=580%2C350&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=81306"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/81307"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=81306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=81306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=81306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}