{"id":81550,"date":"2017-09-08T05:01:23","date_gmt":"2017-09-08T09:01:23","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/2017\/?p=81550"},"modified":"2017-09-08T05:01:23","modified_gmt":"2017-09-08T09:01:23","slug":"runners-aconcaguinos-regresan-de-la-cruz-cargados-de-medallas","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/runners-aconcaguinos-regresan-de-la-cruz-cargados-de-medallas\/","title":{"rendered":"Runners aconcag\u00fcinos regresan de La Cruz cargados de medallas"},"content":{"rendered":"<figure id=\"attachment_81552\" aria-describedby=\"caption-attachment-81552\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-81552\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/09\/Corrida1.jpg?resize=580%2C400\" alt=\"JUVENTUD DEPORTISTA.- Deportistas de gran factura son los que cada fin de semana se la juegan en alguna ciudad distinta. Sue\u00f1an, corren, ganan y siguen la ruta.\" width=\"580\" height=\"400\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida1.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida1.jpg?resize=200%2C138&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida1.jpg?resize=300%2C207&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida1.jpg?resize=218%2C150&amp;ssl=1 218w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida1.jpg?resize=400%2C276&amp;ssl=1 400w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-81552\" class=\"wp-caption-text\">JUVENTUD DEPORTISTA.- Deportistas de gran factura son los que cada fin de semana se la juegan en alguna ciudad distinta. Sue\u00f1an, corren, ganan y siguen la ruta.<\/figcaption><\/figure>\n<p>Fue en la comuna de La Cruz en donde se desarroll\u00f3 hace pocos d\u00edas la primera corrida municipal \u2018Corre por los Bomberos de La Cruz\u2019, prueba pedestre que fue organizada por la Municipalidad de la Cruz y el Team Runners La Cruz, en apoyo a Bomberos de esta comuna, ya que al inscribirse se ped\u00eda un aporte voluntario, recaud\u00e1ndose m\u00e1s de $300.000 con los m\u00e1s de 300 atletas participantes en esta jornada, misma que se desarroll\u00f3 en los 1,5 K, 5K y 10K.<br \/>\nFue entonces en este escenario que Aconcagua Runners se present\u00f3 con una delegaci\u00f3n conformada en su gran mayor\u00eda por j\u00f3venes, presentando en los 5K al joven Abner Vidal, quien se qued\u00f3 en la primera posici\u00f3n general de la prueba, luego en ese mismo circuito se presentaron Slomy Olivares y Martina Malerba, quienes llegaron en tercer y cuarto lugar respectivamente.<br \/>\nTambi\u00e9n brillaron en esta cita deportiva Carlos Reinoso, Alexis Z\u00fa\u00f1iga, Josu\u00e9 Estay, Melissa Ponce, Paolo L\u00e9rtola y Mario Carvajal, pero los que se quedaron con el primer lugar fueron Jes\u00fas Chacana (El Potro Puyayino), y en la General el primer lugar le correspondi\u00f3 al joven Javier Reveco. Y en la categor\u00eda M\u00e1xima y Todo Competidor, el ganador general fue \u00c1lvaro Silva, llev\u00e1ndose los aplausos en esta primera versi\u00f3n.<br \/>\nVienen ya los meses m\u00e1s intensos del a\u00f1o en materia de competencias de atletismo, por lo que de seguro todas estas corridas de invierno habr\u00e1n de servir para estar bien fogueados, ya que desarrollar\u00e1n viajes y correr\u00e1n mucho m\u00e1s, por lo que en Diario El Trabajo les deseamos una buena cosecha deportiva a todos los chicos de Aconcagua Runners.<br \/>\n<strong>Roberto Gonz\u00e1lez Short<\/strong><\/p>\n<figure id=\"attachment_81551\" aria-describedby=\"caption-attachment-81551\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-81551\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/09\/Corrida_Alvaro-Silva.jpg?resize=580%2C399\" alt=\"SOLIDEZ DEMOSTRADA.- En la categor\u00eda M\u00e1xima y Todo Competidor, el ganador general fue \u00c1lvaro Silva, llev\u00e1ndose los aplausos en esta primera versi\u00f3n.\" width=\"580\" height=\"399\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida_Alvaro-Silva.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida_Alvaro-Silva.jpg?resize=200%2C138&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida_Alvaro-Silva.jpg?resize=300%2C206&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida_Alvaro-Silva.jpg?resize=218%2C150&amp;ssl=1 218w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida_Alvaro-Silva.jpg?resize=400%2C275&amp;ssl=1 400w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-81551\" class=\"wp-caption-text\">SOLIDEZ DEMOSTRADA.- En la categor\u00eda M\u00e1xima y Todo Competidor, el ganador general fue \u00c1lvaro Silva, llev\u00e1ndose los aplausos en esta primera versi\u00f3n.<\/figcaption><\/figure>\n<figure id=\"attachment_81553\" aria-describedby=\"caption-attachment-81553\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-81553\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/09\/Corrida2.jpg?resize=580%2C400\" alt=\"PANCHITA IMPARABLE.- Con gran energ\u00eda los exponentes de Aconcagua Runners llevan el deporte a todos los rincones de la V Regi\u00f3n, esta vez brillaron en La Cruz.\" width=\"580\" height=\"400\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida2.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida2.jpg?resize=200%2C138&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida2.jpg?resize=300%2C207&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida2.jpg?resize=218%2C150&amp;ssl=1 218w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida2.jpg?resize=400%2C276&amp;ssl=1 400w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-81553\" class=\"wp-caption-text\">PANCHITA IMPARABLE.- Con gran energ\u00eda los exponentes de Aconcagua Runners llevan el deporte a todos los rincones de la V Regi\u00f3n, esta vez brillaron en La Cruz.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Fue en la comuna de La Cruz en donde se desarroll\u00f3 hace pocos d\u00edas la primera corrida municipal \u2018Corre por los Bomberos de La Cruz\u2019, prueba pedestre que fue organizada por la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":81553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-81550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/Corrida2.jpg?fit=580%2C400&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=81550"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/81553"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=81550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=81550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=81550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}