{"id":81672,"date":"2017-09-14T05:03:44","date_gmt":"2017-09-14T09:03:44","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/2017\/?p=81672"},"modified":"2017-09-14T05:03:44","modified_gmt":"2017-09-14T09:03:44","slug":"union-san-felipe-cae-derrotado-1-a-3-y-se-complica-en-copa-chile","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/portal\/union-san-felipe-cae-derrotado-1-a-3-y-se-complica-en-copa-chile\/","title":{"rendered":"Uni\u00f3n San Felipe cae derrotado 1 a 3 y se complica en Copa Chile"},"content":{"rendered":"<figure id=\"attachment_81673\" aria-describedby=\"caption-attachment-81673\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-81673\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/09\/uni-huachipato.jpg?resize=580%2C399\" alt=\"El Un\u00ed termin\u00f3 sucumbiendo ante la jerarqu\u00eda de un rival de primera como Huachipato.\" width=\"580\" height=\"399\" srcset=\"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/uni-huachipato.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/uni-huachipato.jpg?resize=200%2C138&amp;ssl=1 200w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/uni-huachipato.jpg?resize=300%2C206&amp;ssl=1 300w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/uni-huachipato.jpg?resize=218%2C150&amp;ssl=1 218w, https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/uni-huachipato.jpg?resize=400%2C275&amp;ssl=1 400w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-81673\" class=\"wp-caption-text\">El Un\u00ed termin\u00f3 sucumbiendo ante la jerarqu\u00eda de un rival de primera como Huachipato.<\/figcaption><\/figure>\n<p>Luego de hacer un primer tiempo satisfactorio que le permiti\u00f3 irse al descanso en ventaja por la cuenta m\u00ednima, el Un\u00ed cay\u00f3 por 3 a 1 frente a Huachipato en el partido jugado anoche en el Estadio Municipal, ante m\u00e1s de mil espectadores.<br \/>\nEn el segundo lapso los de Madrid otorgaron muchas licencias a los sure\u00f1os, las que se reflejaron en los goles de Juan C\u00f3rdova en el minuto 46, Soteldo y Ortega en los minutos 64 y 67.<br \/>\nEl Un\u00ed form\u00f3 con Andr\u00e9s Fern\u00e1ndez en el arco; Jes\u00fas Pino, David Fern\u00e1ndez, Gonzalo Villegas; Cristian Collao, Emmanuel P\u00edo, F\u00e9lix Cort\u00e9s, Mathias Crocco, Gabriel Moyano, Claudio Galeano, Miguel Orellana.<br \/>\nEn el segundo tiempo ingresaron Ricardo Gonz\u00e1lez, Jaime Droguett y Juan M\u00e9ndez, los que reemplazaron a Moyano, Galeano y Crocco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de hacer un primer tiempo satisfactorio que le permiti\u00f3 irse al descanso en ventaja por la cuenta m\u00ednima, el Un\u00ed cay\u00f3 por 3 a 1 frente a Huachipato en el partido&#8230;<\/p>\n","protected":false},"author":1,"featured_media":81673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-81672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/eltrabajo.cl\/portal\/wp-content\/uploads\/2017\/09\/uni-huachipato.jpg?fit=580%2C399&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/comments?post=81672"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/posts\/81672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media\/81673"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/media?parent=81672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/categories?post=81672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/portal\/wp-json\/wp\/v2\/tags?post=81672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}