{"id":126890,"date":"2024-01-04T23:05:37","date_gmt":"2024-01-05T02:05:37","guid":{"rendered":"https:\/\/eltrabajo.cl\/portal\/?p=126890"},"modified":"2024-01-07T00:16:27","modified_gmt":"2024-01-07T03:16:27","slug":"estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/","title":{"rendered":"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong>Gestionado por la Dideco:<\/strong><\/span><\/p>\n<p>Ayer desde las 10 de la ma\u00f1ana hasta las 15:00 horas, en la sede vecinal de la Junta de Vecinos Padre Hurtado, ubicada en pasaje Colunqu\u00e9n n\u00famero 10 Poblaci\u00f3n Conac de San Felipe, un grupo de estudiantes de Podolog\u00eda del Instituto AIEP de esta ciudad, se dio cita para poner en pr\u00e1ctica sus conocimientos y atender a una decena de vecinos del sector, principalmente adultos mayores.<\/p>\n<p>Una de las vecinas, <strong>Evelyn Vald\u00e9s<\/strong>, en conversaci\u00f3n con <strong>Diario El Trabajo<\/strong> reiter\u00f3 la actividad, agregando que esto da la posibilidad <em>\u00aba las juntas de vecinos a un tratamiento podol\u00f3gico, son muy agradables todas. Esto consiste m\u00e1s que nada en un tratamiento de cortar u\u00f1as, sacar queratosis, las callosidades que se forman en la planta del pie\u00bb,<\/em> cuenta.<\/p>\n<p>&#8211;<strong> \u00bfC\u00f3mo ha sido la actividad?<\/strong><\/p>\n<p>&#8211; Muy buena, agradable. Agradables las chicas, chicos y los chiques.<\/p>\n<p>&#8211; <strong>\u00bfC\u00f3mo surge la idea?<\/strong><\/p>\n<p>&#8211; A trav\u00e9s de la junta de vecinos con el Instituto AIEP y Dideco.<\/p>\n<p>Cabe destacar que en la ocasi\u00f3n fueron atendidas alrededor de 30 personas, desde las 10:00 hasta las 15:00 horas, comentando que la recepci\u00f3n por parte de los vecinos <em>\u00abha sido buena, bien agradable de ambas partes, tanto de las chicas pod\u00f3logas y los mismos vecinos o socios\u00bb,<\/em> se\u00f1ala.<\/p>\n<p>Comenta que seguir\u00e1n buscando este tipo de operativos que vayan en beneficio de los vecinos.<\/p>\n<p>\u00ab<em>Agradecida de la junta de vecinos que nos da la posibilidad de tener estos operativos, porque aqu\u00ed en el sector hay mucha gente adulto mayor que no tiene a lo mejor las condiciones econ\u00f3micas o de tiempo para hacerse este tipo de procedimiento\u00bb,<\/em> finaliza.<\/p>\n<p>Finalmente, el presidente de la junta de vecinos, <strong>Patricio Briones<\/strong>, se\u00f1al\u00f3 a nuestro medio estar muy contento con el operativo <em>\u00abdel Instituto AIEP a trav\u00e9s de la Dideco, en el cual asistieron los socios, gente joven, adulta y de todas las edades llegaron para este operativo, en el cual eran 30 personas desde las 10 de la ma\u00f1ana hasta las 15:00 horas. Estamos muy agradecidos de las personas que vinieron y de la gesti\u00f3n de la se\u00f1orita Magdalena de la Dideco\u00bb,<\/em> concluy\u00f3.<\/p>\n<figure id=\"attachment_127181\" aria-describedby=\"caption-attachment-127181\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-127181\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-1.jpg\" alt=\"De izquierda a derecha el presidente de la Junta de Vecinos, Patricio Briones, junto a los estudiantes de podolog\u00eda del Instituto AIEP, sede San Felipe.\" width=\"699\" height=\"411\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-1.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-1-300x176.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-1-150x88.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-1-696x409.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-127181\" class=\"wp-caption-text\">De izquierda a derecha el presidente de la Junta de Vecinos, Patricio Briones, junto a los estudiantes de podolog\u00eda del Instituto AIEP, sede San Felipe.<\/figcaption><\/figure>\n<figure id=\"attachment_127180\" aria-describedby=\"caption-attachment-127180\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-127180\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1.jpg\" alt=\"Una vecina del sector siendo atendida en este operativo que se realiz\u00f3 ayer.\" width=\"700\" height=\"525\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1.jpg 700w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1-300x225.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1-150x113.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1-696x522.jpg 696w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1-560x420.jpg 560w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1-80x60.jpg 80w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1-265x198.jpg 265w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-127180\" class=\"wp-caption-text\">Una vecina del sector siendo atendida en este operativo que se realiz\u00f3 ayer.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Gestionado por la Dideco: Ayer desde las 10 de la ma\u00f1ana hasta las 15:00 horas, en la sede vecinal de la Junta de Vecinos Padre Hurtado, ubicada en pasaje Colunqu\u00e9n n\u00famero 10 Poblaci\u00f3n Conac de San Felipe, un grupo de estudiantes de Podolog\u00eda del Instituto AIEP de esta ciudad, se dio cita para poner en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":127180,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-126890","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cronica-2"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Gestionado por la Dideco: Ayer desde las 10 de la ma\u00f1ana hasta las 15:00 horas, en la sede vecinal de la Junta de Vecinos Padre Hurtado, ubicada en pasaje Colunqu\u00e9n n\u00famero 10 Poblaci\u00f3n Conac de San Felipe, un grupo de estudiantes de Podolog\u00eda del Instituto AIEP de esta ciudad, se dio cita para poner en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-05T02:05:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-07T03:16:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico\",\"datePublished\":\"2024-01-05T02:05:37+00:00\",\"dateModified\":\"2024-01-07T03:16:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/\"},\"wordCount\":432,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Operativo-3-1.jpg\",\"articleSection\":[\"Cr\u00f3nica\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/\",\"name\":\"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Operativo-3-1.jpg\",\"datePublished\":\"2024-01-05T02:05:37+00:00\",\"dateModified\":\"2024-01-07T03:16:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Operativo-3-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Operativo-3-1.jpg\",\"width\":700,\"height\":525,\"caption\":\"Una vecina del sector siendo atendida en este operativo que se realiz\u00f3 ayer.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/","og_locale":"es_ES","og_type":"article","og_title":"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico - Diario El Trabajo","og_description":"Gestionado por la Dideco: Ayer desde las 10 de la ma\u00f1ana hasta las 15:00 horas, en la sede vecinal de la Junta de Vecinos Padre Hurtado, ubicada en pasaje Colunqu\u00e9n n\u00famero 10 Poblaci\u00f3n Conac de San Felipe, un grupo de estudiantes de Podolog\u00eda del Instituto AIEP de esta ciudad, se dio cita para poner en [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2024-01-05T02:05:37+00:00","article_modified_time":"2024-01-07T03:16:27+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico","datePublished":"2024-01-05T02:05:37+00:00","dateModified":"2024-01-07T03:16:27+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/"},"wordCount":432,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1.jpg","articleSection":["Cr\u00f3nica"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/","url":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/","name":"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1.jpg","datePublished":"2024-01-05T02:05:37+00:00","dateModified":"2024-01-07T03:16:27+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Operativo-3-1.jpg","width":700,"height":525,"caption":"Una vecina del sector siendo atendida en este operativo que se realiz\u00f3 ayer."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/estudiantes-aiep-con-jjvv-padre-hurtado-desarrollan-operativo-podologico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Estudiantes AIEP con JJVV Padre Hurtado desarrollan operativo podol\u00f3gico"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/126890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=126890"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/126890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/127180"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=126890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=126890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=126890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}